{"id":160,"date":"2021-03-07T00:09:21","date_gmt":"2021-03-07T03:09:21","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2021\/03\/07\/cineasta-que-causou-frisson-com-drama-de-epoca-lesbico-lanca-filme-em-berlim\/"},"modified":"2021-03-07T00:09:21","modified_gmt":"2021-03-07T03:09:21","slug":"cineasta-que-causou-frisson-com-drama-de-epoca-lesbico-lanca-filme-em-berlim","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2021\/03\/07\/cineasta-que-causou-frisson-com-drama-de-epoca-lesbico-lanca-filme-em-berlim\/","title":{"rendered":"Cineasta que causou frisson com drama de \u00e9poca l\u00e9sbico lan\u00e7a filme em Berlim"},"content":{"rendered":"<p>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; &#8220;Um relacionamento consiste em inventar sua pr\u00f3pria linguagem&#8221;, disse a diretora francesa C\u00e9line Sciamma em entrevista a um jornal brit\u00e2nico um ano atr\u00e1s, sobre o seu ent\u00e3o rec\u00e9m-lan\u00e7ado &#8220;Retrato de uma Jovem em Chamas&#8221;, premiado no Festival de Cannes. &#8220;\u00c9 por isso que voc\u00ea chora quando perde algu\u00e9m que ama. Essa l\u00edngua voc\u00ea n\u00e3o vai falar com mais ningu\u00e9m.&#8221;<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>O relacionamento constru\u00eddo no drama de \u00e9poca de 2019 \u00e9 entre duas mulheres adultas que se apaixonam. Mas a ideia de criar uma linguagem em que dois sujeitos se encontram tamb\u00e9m permeia a rela\u00e7\u00e3o entre m\u00e3e e filha de &#8220;Petite Maman&#8221;, filme que ela estreou na mostra competitiva do Festival de Berlim nesta quarta (3).<\/p>\n<p>Sciamma p\u00f4s na tela uma esp\u00e9cie de salto no tempo para que a hierarquia et\u00e1ria entre as duas personagens, uma de oito e outra de 31 anos, fosse abolida -algo que ela mesma chama, em entrevista por videoconfer\u00eancia, de uma &#8220;fantasia secreta&#8221;.<\/p>\n<p>A pequena Nelly (Jos\u00e9phine Sanz) acaba de perder sua av\u00f3 e retorna, com seus pais, \u00e0 casa onde sua m\u00e3e (Nina Meurisse) passou a inf\u00e2ncia para esvazi\u00e1-la definitivamente. No dia em que a crian\u00e7a descobre que sua m\u00e3e foi embora antes do dia definido para a partida da fam\u00edlia, ela adentra a floresta pr\u00f3xima e encontra uma menina da mesma idade construindo uma cabana feita de troncos.<\/p>\n<p>O encontro das duas logo levanta o principal mist\u00e9rio do longa -a nova amiga de Nelly tem o nome de sua m\u00e3e, a leva para uma casa que \u00e9 uma vers\u00e3o mobiliada do im\u00f3vel rec\u00e9m-desmontado e a apresenta \u00e0 sua m\u00e3e que, assim como a av\u00f3 de Nelly que acaba de morrer, usa uma bengala.<\/p>\n<p>&#8220;\u00c9 como um novo mito sobre encontrar seus pais quando crian\u00e7a, um novo conto&#8221;, define Sciamma. O filme, gravado j\u00e1 durante a pandemia, em novembro do ano passado, tamb\u00e9m foi pensado para o p\u00fablico infantil -esse \u00e9 um dos motivos, justifica a cineasta, para ele ter apenas 72 minutos de dura\u00e7\u00e3o.<\/p>\n<p>Leia Tamb\u00e9m: <a href=\"https:\/\/www.noticiasaominuto.com.br\/ultima-hora\/1782517\/daniel-bruhl-de-capitao-america-e-adeus-lenin-estreia-na-direcao-em-berlim\" target=\"_blank\" rel=\"noopener noreferrer\">Daniel Br\u00fchl, de &#8216;Capit\u00e3o Am\u00e9rica&#8217; e &#8216;Adeus, L\u00eanin&#8217;, estreia na dire\u00e7\u00e3o em Berlim<\/a><\/p>\n<p>A diretora conta que rodou o filme em sua cidade natal, e que a casa onde o filme se passa \u00e9 uma mistura do que havia nas resid\u00eancias de suas av\u00f3s. Ela afirma, no entanto, que mais do que um filme ligado \u00e0 sua biografia, a hist\u00f3ria \u00e9 uma tentativa da cineasta de &#8220;criar espa\u00e7o&#8221; para o espectador.<br \/>&#8220;Se voc\u00ea vir o filme com a crian\u00e7a que voc\u00ea ama, acho que, quando voc\u00eas sa\u00edrem [do cinema]&#8221;, exemplifica, essa sa\u00edda &#8220;n\u00e3o ser\u00e1 igual&#8221;.<\/p>\n<p>&#8220;Petite Maman&#8221; n\u00e3o se edifica com a intensidade de &#8220;Retrato de uma Jovem em Chamas&#8221;. S\u00e3o, inclusive, em gestos pedestres que m\u00e3e e filha vivem um luto compartilhado -como quando Nelly, no banco de tr\u00e1s do carro, leva petiscos e um suco de caixinha \u00e0 boca de sua m\u00e3e, que conduz as duas para longe da casa de repouso onde a morte do come\u00e7o da trama acontece.<\/p>\n<p>Mas \u00e9 s\u00f3 quando as duas se encontram aos oito anos de idade que elas conseguem conversar, ainda que pouco, sobre a melancolia de Marion e os questionamentos de Nelly sobre se \u00e9 ela a raz\u00e3o da tristeza da m\u00e3e.<\/p>\n<p>&#8220;O filme \u00e9 sobre a perda, mas acho que ele \u00e9 mais sobre abolir o passado, o presente e as barreiras da idade&#8221;, diz a diretora, que conta que animes de Hayao Miyazaki, como &#8220;Meu Amigo Totoro&#8221;, inspiraram parte da hist\u00f3ria de &#8220;Petite Maman&#8221;.<\/p>\n<p>Ela, que chama a experi\u00eancia de &#8220;um salto no tempo sem m\u00e1quina do tempo&#8221;, afirma que a ideia era se distanciar da figura de um &#8220;turista num momento hist\u00f3rico&#8221; nessa passagem de anos.<\/p>\n<p>Em vez de sonhar em viajar no tempo para encontrar civiliza\u00e7\u00f5es antigas ou um futuro melhor que o presente, no filme, a fantasia acontece para que se possa compartilhar um tempo em comum.<\/p>\n<p>&#8220;Quando voc\u00ea fala em voz alta, parece uma fantasia. \u00c9 uma fantasia secreta&#8221;, diz Sciamma, sobre encontrar os pais quando pequenos. &#8220;Eu espero que isso se torne uma fantasia coletiva.&#8221;<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Cultura<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/ultima-hora\/1782560\/cineasta-que-causou-frisson-com-drama-de-epoca-lesbico-lanca-filme-em-berlim?utm_source=rss-cultura&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; &#8220;Um relacionamento consiste em inventar sua pr\u00f3pria linguagem&#8221;, disse a<\/p>\n","protected":false},"author":0,"featured_media":161,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-160","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=160"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/160\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/161"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}