{"id":1535,"date":"2021-03-24T13:12:29","date_gmt":"2021-03-24T16:12:29","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2021\/03\/24\/tiago-leifert-fala-da-2a-onda-da-covid-apos-comentarios-de-sarah\/"},"modified":"2021-03-24T13:12:29","modified_gmt":"2021-03-24T16:12:29","slug":"tiago-leifert-fala-da-2a-onda-da-covid-apos-comentarios-de-sarah","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2021\/03\/24\/tiago-leifert-fala-da-2a-onda-da-covid-apos-comentarios-de-sarah\/","title":{"rendered":"Tiago Leifert fala da 2\u00aa onda da Covid ap\u00f3s coment\u00e1rios de Sarah"},"content":{"rendered":"<p>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; A participante do BBB 21, Sarah Andrade, 29, voltou a falar na tarde desta ter\u00e7a-feira (23) sobre a pandemia, reclamou dos protocolos de seguran\u00e7a durante o r\u00e9veillon, classificando como &#8220;frescura&#8221;, durante conversa com Caio e Arthur. A afirma\u00e7\u00e3o da sister revoltou internautas e sua equipe se posicionou dizendo que n\u00e3o compactua com sua opini\u00e3o.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>&#8220;Eu fui para R\u00e9veillon esse ano, uma frescura da porra. Toda hora chegava pol\u00edcia, falando para ficar nas mesas, esse neg\u00f3cio de distanciamento, tinha que fazer teste antes&#8221;, falou. Arthur Picoli, 26, respondeu que n\u00e3o saiu de casa devido a pandemia e passou as festas de final de ano longe das fam\u00edlias e amigos. &#8220;Passei Natal e Ano Novo sozinho&#8221;, falou.<\/p>\n<p>Ap\u00f3s os coment\u00e1rios de Sarah, o apresentador do programa, Tiago Leifert, informou ao vivo aos confinados que o Brasil vive a segunda onda da Covid-19 e que ela \u00e9 &#8220;muito pesada&#8221;. Viih Tube e Juliette come\u00e7aram a chorar e Fiuk perguntou se a fam\u00edlia dele estava bem. Nesta ter\u00e7a, o pa\u00eds registra mais de 3.000 mortes pela Covid em 24 horas, e a pandemia segue descontrolada.<\/p>\n<p>Leifert sugeriu aos brothers para no Raio-X falarem para as f\u00e3s respeitarem os protocolos de seguran\u00e7a. Ap\u00f3s conversar com eles, disse que precisava falar da pandemia porque alguns achavam que est\u00e1 tudo bem e falavam de festas. Sarah ficou de boca aberta ao receber as informa\u00e7\u00f5es.<\/p>\n<p>Dias antes, Sarah j\u00e1 havia confessado em conversa com os colegas de confinamento que no ano passado fez diversas viagens e foi com frequ\u00eancia a baladas, tudo \u00e0s risadas. Novamente, coube a Arthur o papel da raz\u00e3o. Ele disse que segurou a onda no isolamento social e que s\u00f3 ia em casa de alunos com quem ele j\u00e1 convivia.<\/p>\n<p>Internautas criticaram a afirma\u00e7\u00e3o de Sarah e pediram a sua expuls\u00e3o. Uma pessoa marcou o diretor do programa, Boninho, dizendo que ela est\u00e1 debochando a pandemia e que est\u00e1 feio demais. Outra internauta pede para darem bronca ao vivo na sister porque vai ficar feio para o programa em rede nacional &#8220;encorajando o povo a viajar e se aglomerar&#8221;.<\/p>\n<p>A equipe de Sarah discordou da sister e publicou nas redes sociais que algumas palavras ditas dentro do programa doeram em muitas pessoas e com raz\u00e3o. &#8220;Sarah errou, mas o jogo \u00e9 l\u00e1 dentro, aqui fora vamos fazer o que pudermos para ajudar os afetados pela pandemia. Sarita, ao sair, com certeza se arrepender\u00e1 de palavras ditas e ficar\u00e1 feliz com a nossa atitude&#8221;, escreveu a equipe.<\/p>\n<p>A atitude foi elogiada nas redes sociais pelo ator Bruno Gagliasso que tem promovido boa informa\u00e7\u00e3o em mostrar para ela que houve de errado. &#8220;Parab\u00e9ns aos administradores da conta da Sarah Andrade que tem promovido boa informa\u00e7\u00e3o e compromisso em mostrar para ela o que houve de errado em rela\u00e7\u00e3o \u00e0 pandemia. \u00c9 disso que precisamos. Uni\u00e3o na conscientiza\u00e7\u00e3o das pessoas&#8221;, escreveu.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Fama<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/celebridades\/1789026\/2-tiago-leifert-fala-da-2-onda-da-covid-apos-comentarios-de-sarah?utm_source=rss-fama&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; A participante do BBB 21, Sarah Andrade, 29, voltou a<\/p>\n","protected":false},"author":0,"featured_media":1536,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1535","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fama-e-tv"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1535","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1535"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1535\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/1536"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1535"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1535"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}