{"id":1457,"date":"2021-03-24T09:16:02","date_gmt":"2021-03-24T12:16:02","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2021\/03\/24\/em-busca-de-solucoes-para-pandemia-empresarios-procuram-lira-e-pacheco\/"},"modified":"2021-03-24T09:16:02","modified_gmt":"2021-03-24T12:16:02","slug":"em-busca-de-solucoes-para-pandemia-empresarios-procuram-lira-e-pacheco","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2021\/03\/24\/em-busca-de-solucoes-para-pandemia-empresarios-procuram-lira-e-pacheco\/","title":{"rendered":"Em busca de solu\u00e7\u00f5es para pandemia, empres\u00e1rios procuram Lira e Pacheco"},"content":{"rendered":"<p>Banqueiros e empres\u00e1rios se reuniram, em dois momentos, na segunda-feira, 22, com o presidente da C\u00e2mara, Arthur Lira (PP-AL), e do Senado, Rodrigo Pacheco (DEM-MG). Foram discutidas sa\u00eddas para agilizar a compra de vacinas e insumos, no pior momento da pandemia no Pa\u00eds.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>Em tom de cansa\u00e7o e cr\u00edticas, apresentaram tr\u00eas preocupa\u00e7\u00f5es: vacina, falta de leitos, al\u00e9m de insumos e medicamentos para aqueles que est\u00e3o internados, por conta da covid-19. Um dos empres\u00e1rios tamb\u00e9m pediu benef\u00edcios fiscais, em troca de gastos com iniciativas de combate \u00e0 pandemia.<\/p>\n<p>O primeiro encontro foi organizado pelo m\u00e9dico Claudio Lottenberg, presidente do Conselho do Hospital Albert Einstein e do Icos (Instituto Coaliz\u00e3o Sa\u00fade). Mais tarde, um jantar ocorreu na casa de Washington Cinel, dono da empresa de seguran\u00e7a Gocil. Dentre os participantes, estiveram os banqueiros Luiz Carlos Trabuco, presidente do conselho de administra\u00e7\u00e3o do Bradesco, e Andr\u00e9 Esteves, s\u00f3cio-fundador do BTG Pactual, os empres\u00e1rios Abilio Diniz, Fl\u00e1vio Rocha, da Riachuelo, e Carlos Sanchez, da fabricante de medicamentos EMS. Alguns, como Diniz e Rocha, participaram por videoconfer\u00eancia.<\/p>\n<p>Conforme apurou o <strong>Estad\u00e3o\/Broadcast<\/strong>, o tema do debate foi exclusivamente a pandemia &#8211; em diferentes frentes na discuss\u00e3o. Uma das vertentes da elite empresarial do Pa\u00eds come\u00e7a a falar em uma &#8220;frente de solidariedade&#8221;, em uma nova ofensiva para ajudar o Brasil a atravessar a pior fase da pandemia. Outra quer atos mais pr\u00e1ticos, como a mudan\u00e7a na regra para a compra de vacinas pela iniciativa privada e benef\u00edcios em impostos.<\/p>\n<p>&#8220;Sem entendimento e pacifica\u00e7\u00e3o, n\u00e3o vamos a lugar nenhum. A vacina \u00e9 importante. Mas tem de esperar&#8221;, diz Trabuco, do Bradesco. De acordo com ele, o que \u00e9 poss\u00edvel fazer agora \u00e9 &#8220;trabalhar para ter leitos e insumos hospitalares&#8221;. Nos encontros, m\u00e9dicos fizeram depoimentos preocupantes quanto \u00e0 car\u00eancia dos hospitais para receber as pessoas diagnosticadas com covid-19 e em situa\u00e7\u00e3o mais grave.<\/p>\n<p>&#8220;As reuni\u00f5es s\u00e3o boas, teve ontem (domingi, 21), ter\u00e1 amanh\u00e3 (quarta, 24), no sentido de buscar di\u00e1logo para encontrar solu\u00e7\u00f5es. As pessoas t\u00eam de entender que a crise de sa\u00fade j\u00e1 est\u00e1 explicitada, agora, trata-se de uma crise humanit\u00e1ria&#8221;, afirmou Trabuco.<\/p>\n<p><strong>Benef\u00edcio fiscal<\/strong><\/p>\n<p>J\u00e1 o presidente do conselho de administra\u00e7\u00e3o do grupo Guararapes, dono da varejista de moda Riachuelo, Fl\u00e1vio Rocha, disse que, entre as medidas discutidas com os chefes do Legislativo, estava uma contrapartida para a oferta de leitos para tratamento da covid-19. &#8220;As empresas poderiam doar leitos e abater parte do valor do Imposto de Renda&#8221;, afirma.<\/p>\n<p>Lira e Pacheco prometeram aos empres\u00e1rios que o Congresso vai estudar medidas para agilizar a importa\u00e7\u00e3o de insumos e produtos farmac\u00eauticos de forma geral, em meio \u00e0 car\u00eancia nos hospitais e a lota\u00e7\u00e3o dos leitos Brasil afora.<\/p>\n<p>Pacheco disse, conforme um dos presentes, que a &#8220;fase de negacionismo&#8221; j\u00e1 passou. &#8220;Ser negacionista hoje \u00e9 macabro e f\u00fanebre&#8221;, afirmou o presidente do Senado, relatou a fonte.<\/p>\n<p>Os encontros de banqueiros e empres\u00e1rios com Lira e Pacheco ocorrem um dia ap\u00f3s um qu\u00f3rum parecido participar de um encontro virtual com o ministro da Economia, Paulo Guedes. Na conversa, que durou quase quatro horas, o &#8220;Posto Ipiranga&#8221;, como \u00e9 chamado pelo presidente Bolsonaro, foi cobrado, principalmente, por vacinas.<\/p>\n<p>Hoje, uma nova reuni\u00e3o para tratar da pandemia no Pa\u00eds est\u00e1 agendada. Desta vez, o encontro ser\u00e1 com os chefes dos Poderes. Entre os presentes, est\u00e3o previstos o presidente Jair Bolsonaro, Pacheco, Lira, o ministro Luiz Fux, do Supremo Tribunal Federal (STF), al\u00e9m de governadores.<\/p>\n<p>As informa\u00e7\u00f5es s\u00e3o do jornal <strong>O Estado de S. Paulo.<\/strong><\/p>\n<p><a href=\"https:\/\/www.noticiasaominuto.com.br\/economia\/1788995\/em-busca-de-solucoes-para-pandemia-empresarios-procuram-lira-e-pacheco?utm_source=rss-economia&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><br \/>\nNot\u00edcias ao Minuto Brasil &#8211; Economia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Banqueiros e empres\u00e1rios se reuniram, em dois momentos, na segunda-feira, 22, com o presidente da<\/p>\n","protected":false},"author":0,"featured_media":1458,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-1457","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1457","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1457"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1457\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/1458"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}