{"id":1356,"date":"2021-03-23T18:08:40","date_gmt":"2021-03-23T21:08:40","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2021\/03\/23\/mario-frias-erra-portugues-ao-agradecer-a-elogios-de-eduardo-bolsonaro\/"},"modified":"2021-03-23T18:08:40","modified_gmt":"2021-03-23T21:08:40","slug":"mario-frias-erra-portugues-ao-agradecer-a-elogios-de-eduardo-bolsonaro","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2021\/03\/23\/mario-frias-erra-portugues-ao-agradecer-a-elogios-de-eduardo-bolsonaro\/","title":{"rendered":"Mario Frias erra portugu\u00eas ao agradecer a elogios de Eduardo Bolsonaro"},"content":{"rendered":"<p>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; O secret\u00e1rio da Cultura, Mario Frias, cometeu um erro gramatical ao comentar numa publica\u00e7\u00e3o do deputado federal Eduardo Bolsonaro (PSL-SP), no Instagram, nesta segunda-feira (23).<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>&#8220;Muito obrigado, a luta \u00e9 di\u00e1ria e sem direito a descanso. Vamos trabalhar incansavelmente para que todos os brasileiros tenham assesso a Cultura&#8221;, escreveu Frias, errando a grafia da palavra &#8220;acesso&#8221;. Pouco tempo depois, ele editou o coment\u00e1rio para corrigir o erro.<\/p>\n<p>Na postagem, o deputado tece cr\u00edticas \u00e0 classe art\u00edstica brasileira, ao PT e ao funcionamento da lei Rouanet.<\/p>\n<p>Em v\u00eddeo, Eduardo diz que parte das pessoas que n\u00e3o gostam do governo Bolsonaro quer somente retornar ao que chamou de &#8220;as tetas do Estado&#8221;. O deputado tamb\u00e9m elogiou Frias.<\/p>\n<p>&#8220;Mario Frias e Andr\u00e9 Porciuncula fizeram o que qualquer gestor privado l\u00facido faria&#8221;, escreveu Eduardo.<\/p>\n<p>Essa n\u00e3o foi a primeira vez que Frias erra grafia de palavras. Em julho de 2020, o secret\u00e1rio publicou uma frase com a palavra &#8220;agrade\u00e7e&#8221; -e virou motivo de piada nas redes. E em mar\u00e7o deste ano, apareceu num v\u00eddeo institucional legendado de maneira errada.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Cultura<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/ultima-hora\/1788835\/mario-frias-erra-portugues-ao-agradecer-a-elogios-de-eduardo-bolsonaro?utm_source=rss-cultura&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; O secret\u00e1rio da Cultura, Mario Frias, cometeu um erro gramatical<\/p>\n","protected":false},"author":0,"featured_media":1357,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-1356","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1356"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1356\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/1357"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}