{"id":128933,"date":"2023-06-11T16:08:25","date_gmt":"2023-06-11T19:08:25","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/06\/11\/desembargador-avalia-que-seria-irresponsabilidade-descomunal-tirar-a-saude-publica-municipal-dos-trilhos-em-que-se-encontraem-cuiaba-ao-prorrogar-intervencao\/"},"modified":"2023-06-11T16:08:25","modified_gmt":"2023-06-11T19:08:25","slug":"desembargador-avalia-que-seria-irresponsabilidade-descomunal-tirar-a-saude-publica-municipal-dos-trilhos-em-que-se-encontraem-cuiaba-ao-prorrogar-intervencao","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/06\/11\/desembargador-avalia-que-seria-irresponsabilidade-descomunal-tirar-a-saude-publica-municipal-dos-trilhos-em-que-se-encontraem-cuiaba-ao-prorrogar-intervencao\/","title":{"rendered":"Desembargador avalia que \u2018seria irresponsabilidade descomunal tirar a sa\u00fade p\u00fablica municipal dos trilhos em que se encontra\u201dem Cuiab\u00e1 ao prorrogar interven\u00e7\u00e3o"},"content":{"rendered":"<p>O desembargador Orlando Perri, que ontem decidiu <a href=\"https:\/\/www.sonoticias.com.br\/politica\/desembargador-prorroga-intervencao-na-saude-em-cuiaba-ate-dezembro\/\">pela prorroga\u00e7\u00e3o da interven\u00e7\u00e3o<\/a> na Sa\u00fade de Cuiab\u00e1 para at\u00e9 31 de dezembro, considerou que os avan\u00e7os obtidos durante os 90 dias da interven\u00e7\u00e3o do governo estadual s\u00e3o ineg\u00e1veis, mas insuficientes para corrigir a sa\u00fade p\u00fablica cuiabana, pois seu estado ainda \u00e9 cr\u00edtico e inspira muitos cuidados.<\/p>\n<p>\u201cSeria uma irresponsabilidade descomunal tirar a sa\u00fade p\u00fablica municipal dos trilhos em que se encontra, desviando-a para um caminho de incertezas e inseguran\u00e7a\u201d, destacou o desembargador em trecho do documento.<\/p>\n<p>Perri destacou ainda o \u201cesfor\u00e7o empreendido para o restabelecimento da sa\u00fade p\u00fablica cuiabana por parte da equipe da interven\u00e7\u00e3o e que a efic\u00e1cia do processo de reestrutura\u00e7\u00e3o depende do empenho de todos os atores envolvidos, inclusive dos profissionais que atuam na execu\u00e7\u00e3o direta da aten\u00e7\u00e3o secund\u00e1ria, com compromisso, seriedade, \u00e9tica, e que seja de forma permanente\u201d.<\/p>\n<p>\u201cComo bem pontuado pelo TCE-MT (Tribunal de Contas do Estado), o diagn\u00f3stico realizado pela equipe t\u00e9cnica da Comiss\u00e3o Permanente de Sa\u00fade e Assist\u00eancia Social n\u00e3o deixa d\u00favidas quanto \u00e0 constata\u00e7\u00e3o das a\u00e7\u00f5es e resultados positivos e efetivos adotados neste per\u00edodo inicial da interven\u00e7\u00e3o\u201d, acrescentou.<\/p>\n<p>Entre as melhorias realizadas na Sa\u00fade de Cuiab\u00e1 pela interven\u00e7\u00e3o e que foram citadas pelo desembargador est\u00e3o:<\/p>\n<p>\u2013 O aumento do n\u00famero de profissionais da sa\u00fade: com o remanejamento interno de pessoal lotado em unidades prim\u00e1rias para as secund\u00e1rias, que ainda est\u00e1 em processo de execu\u00e7\u00e3o, as Unidades de Pronto Atendimento e as Policl\u00ednicas passaram a contar com maior n\u00famero de t\u00e9cnicos de enfermagem, enfermeiros e m\u00e9dicos;<\/p>\n<p>\u2013 O aumento no abastecimento de medicamentos nas farm\u00e1cias das unidades: as farm\u00e1cias dessas unidades se encontram mais bem abastecidas, de modo a favorecer a permanente disponibilidade dos produtos segundo as necessidades dos usu\u00e1rios;<\/p>\n<p>\u2013 A resolutividade no processo de regula\u00e7\u00e3o de pacientes: diminui\u00e7\u00e3o no tempo de espera na regula\u00e7\u00e3o de pacientes internados na rede secund\u00e1ria para a rede terci\u00e1ria, com exce\u00e7\u00e3o dos pacientes vasculares e cardio (cateterismo), que apesar da melhora, ainda permanecem em tempo maior de espera;<\/p>\n<p>\u2013 A reativa\u00e7\u00e3o dos servi\u00e7os de Raio-X nas unidades: o retorno dos servi\u00e7os de Raio-X gera celeridade no diagn\u00f3stico e no tratamento; e. levantamento situacional de cada unidade: o diagn\u00f3stico situacional das unidades possibilitou identificar as oportunidades de melhoria, desde as condi\u00e7\u00f5es de trabalho dos servidores;<\/p>\n<p>\u2013 O gerenciamento, o controle, a movimenta\u00e7\u00e3o, a dispensa\u00e7\u00e3o de materiais e medicamentos; bem como o procedimento de atendimentos dos usu\u00e1rios, com a redefini\u00e7\u00e3o de alguns fluxos;<\/p>\n<p>\u2013 E o pagamento dos fornecedores de servi\u00e7os: com o adimplemento financeiro da presta\u00e7\u00e3o de servi\u00e7os contratados, possibilitou a reativa\u00e7\u00e3o de servi\u00e7os imprescind\u00edveis para o atendimento aos usu\u00e1rios, tais como manuten\u00e7\u00e3o de equipamentos m\u00e9dicos e hospitalares.<\/p>\n<p>Conforme o desembargador, a equipe de interven\u00e7\u00e3o dever\u00e1 continuar apresentando relat\u00f3rio t\u00e9cnico com a descri\u00e7\u00e3o de todas as a\u00e7\u00f5es adotadas, encaminhando-o, quinzenalmente, ao Tribunal de Contas do Estado de Mato Grosso. O tempo de interven\u00e7\u00e3o continuar\u00e1 sendo supervisionado pelo Tribunal de Justi\u00e7a.<\/p>\n<p>A informa\u00e7\u00e3o \u00e9 da secretaria estadual de Comunica\u00e7\u00e3o. <\/p>\n<p>Fonte: S\u00f3 Not\u00edcias<br \/>\nArtigo Original em &gt; www.sonoticias.com.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O desembargador Orlando Perri, que ontem decidiu pela prorroga\u00e7\u00e3o da interven\u00e7\u00e3o na Sa\u00fade de Cuiab\u00e1<\/p>\n","protected":false},"author":0,"featured_media":128934,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-128933","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/128933","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=128933"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/128933\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/128934"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=128933"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=128933"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=128933"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}