{"id":1267,"date":"2021-03-23T12:08:21","date_gmt":"2021-03-23T15:08:21","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2021\/03\/23\/ppi-recomenda-inclusao-de-correios-e-ebc-no-programa-nacional-de-desestatizacao\/"},"modified":"2021-03-23T12:08:21","modified_gmt":"2021-03-23T15:08:21","slug":"ppi-recomenda-inclusao-de-correios-e-ebc-no-programa-nacional-de-desestatizacao","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2021\/03\/23\/ppi-recomenda-inclusao-de-correios-e-ebc-no-programa-nacional-de-desestatizacao\/","title":{"rendered":"PPI recomenda inclus\u00e3o de Correios e EBC no Programa Nacional de Desestatiza\u00e7\u00e3o"},"content":{"rendered":"<p>O Di\u00e1rio Oficial da Uni\u00e3o (DOU) traz publicadas nesta ter\u00e7a-feira, 23, as resolu\u00e7\u00f5es do Conselho do Programa de Parceria de Investimentos (CCPI) que recomendam a inclus\u00e3o da Empresa Brasileira de Correios e Tel\u00e9grafos (ECT) e da Empresa Brasil de Comunica\u00e7\u00e3o (EBC) no Programa Nacional de Desestatiza\u00e7\u00e3o (PND). A decis\u00e3o pela inclus\u00e3o das duas estatais no programa j\u00e1 havia sido anunciada semana passada. Para se confirmar, as recomenda\u00e7\u00f5es precisam ser acatadas pelo presidente da Rep\u00fablica por decreto.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>Conforme disse a secret\u00e1ria do Programa de Parcerias de Investimento (PPI), Martha Seillier no \u00faltimo dia 16, o governo j\u00e1 decidiu que a desestatiza\u00e7\u00e3o dos Correios ser\u00e1 feita por venda do controle acion\u00e1rio da estatal. O que ainda ser\u00e1 definido \u00e9 se a venda para o setor privado ser\u00e1 apenas de parte majorit\u00e1ria da empresa ou de 100% das a\u00e7\u00f5es.<\/p>\n<p>A privatiza\u00e7\u00e3o dos Correios ainda depende da aprova\u00e7\u00e3o de um projeto de lei de autoria do Executivo que permite \u00e0 iniciativa privada prestar servi\u00e7os que hoje apenas os Correios podem operar. A previs\u00e3o, por ora, \u00e9 que o leil\u00e3o ocorra em 2022.<\/p>\n<p>Quando \u00e0 EBC, sua inclus\u00e3o no PND ir\u00e1 permitir, segundo o PPI, a avalia\u00e7\u00e3o de alternativas mais eficientes de execu\u00e7\u00e3o da pol\u00edtica p\u00fablica, sem necessariamente o uso de uma empresa estatal, &#8220;possibilitando a escolha da melhor modalidade para a sua desestatiza\u00e7\u00e3o&#8221;.<\/p>\n<p>De acordo com governo, a desestatiza\u00e7\u00e3o da EBC poder\u00e1 resultar em significativa desonera\u00e7\u00e3o aos cofres federais, gerando uma exclus\u00e3o estimada de aproximadamente R$ 400 milh\u00f5es de despesas do Or\u00e7amento da Uni\u00e3o.<\/p>\n<p><a href=\"https:\/\/www.noticiasaominuto.com.br\/economia\/1788671\/ppi-recomenda-inclusao-de-correios-e-ebc-no-programa-nacional-de-desestatizacao?utm_source=rss-economia&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><br \/>\nNot\u00edcias ao Minuto Brasil &#8211; Economia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Di\u00e1rio Oficial da Uni\u00e3o (DOU) traz publicadas nesta ter\u00e7a-feira, 23, as resolu\u00e7\u00f5es do Conselho<\/p>\n","protected":false},"author":0,"featured_media":1268,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-1267","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1267"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1267\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/1268"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1267"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}