{"id":121480,"date":"2023-04-26T08:08:47","date_gmt":"2023-04-26T11:08:47","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/26\/prefeito-se-casa-com-adolescente-de-16-anos-e-promove-sogra-a-secretaria-de-cultura-no-pr\/"},"modified":"2023-04-26T08:08:47","modified_gmt":"2023-04-26T11:08:47","slug":"prefeito-se-casa-com-adolescente-de-16-anos-e-promove-sogra-a-secretaria-de-cultura-no-pr","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/26\/prefeito-se-casa-com-adolescente-de-16-anos-e-promove-sogra-a-secretaria-de-cultura-no-pr\/","title":{"rendered":"Prefeito se casa com adolescente de 16 anos e promove sogra a secret\u00e1ria de Cultura no PR"},"content":{"rendered":"<p>(FOLHAPRESS) &#8211; O prefeito de Arauc\u00e1ria (PR), Hissam Hussein Dehaini (Cidadania), 65, se casou neste m\u00eas com uma adolescente de 16 anos e, na mesma semana, promoveu a sogra ao cargo de secret\u00e1ria municipal de Cultura e Turismo.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>O casamento com menores de idade que tenham 16 ou 17 anos \u00e9 permitido pela legisla\u00e7\u00e3o brasileira desde que haja autoriza\u00e7\u00e3o dos pais.<br \/>Hissam est\u00e1 no segundo mandato como prefeito da cidade, que fica na regi\u00e3o metropolitana de Curitiba, e \u00e9 empres\u00e1rio. Nas elei\u00e7\u00f5es de 2020, informou \u00e0 Justi\u00e7a Eleitoral ter um patrim\u00f4nio de mais de R$ 14 milh\u00f5es.<\/p>\n<p>A esposa adolescente \u00e9 estudante. Pela legisla\u00e7\u00e3o brasileira, o casamento s\u00f3 \u00e9 autorizado a partir dos 16 anos. Abaixo desta idade, n\u00e3o h\u00e1 qualquer permiss\u00e3o. Al\u00e9m disso, artigo do C\u00f3digo Civil define que, para quem tem entre 16 e 18 anos (incompletos), o casamento depende de autoriza\u00e7\u00e3o dos pais ou respons\u00e1veis legais.<\/p>\n<p>A m\u00e3e da adolescente se tornou secret\u00e1ria de Cultura e Turismo no \u00faltimo dia 14. Dois dias antes, em 12 de abril, o Jornal Oficial dos Cart\u00f3rios de Registro Civil do Brasil publicava o ato que informa que o casal apresentou os documentos para realiza\u00e7\u00e3o do casamento (edital de proclamas).<\/p>\n<p>Ela n\u00e3o foi a primeira pessoa da fam\u00edlia a ganhar um cargo. Em outubro de 2022, uma tia da adolescente, se tornou secret\u00e1ria de Planejamento do munic\u00edpio.<\/p>\n<p>Procurada, a Prefeitura de Arauc\u00e1ria afirmou que as duas possuem ampla experi\u00eancia no servi\u00e7o p\u00fablico. &#8220;A decis\u00e3o acerca da composi\u00e7\u00e3o de seu secretariado \u00e9 ato discricion\u00e1rio do chefe do Poder Executivo, o qual entendeu que a servidora em quest\u00e3o [a m\u00e3e da adolescente] re\u00fane as condi\u00e7\u00f5es necess\u00e1rias para o exerc\u00edcio do cargo&#8221;, diz nota enviada \u00e0 reportagem.<\/p>\n<p>Sobre a tia, a gest\u00e3o afirma que ela \u00e9 &#8220;servidora concursada no munic\u00edpio h\u00e1 mais de dez anos&#8221;. Segundo a prefeitura, antes de assumir o comando do Planejamento ela j\u00e1 havia exercido outros dois cargos de chefia na mesma pasta, de superintendente de projetos e inova\u00e7\u00e3o e de diretora-geral.<\/p>\n<p>Ainda segundo o munic\u00edpio, antes de assumir a pasta da Cultura, a m\u00e3e da jovem exerceu dois cargos na secretaria de Educa\u00e7\u00e3o, primeiro como assessora (nomeada em agosto de 2021) e depois como diretora-geral (nomeada em janeiro de 2022).<\/p>\n<p>Como diretora-geral da Educa\u00e7\u00e3o, ela recebia quase R$ 15 mil (R$ 14.917,38, valor bruto). No cargo de secret\u00e1ria, o sal\u00e1rio bruto sobe para R$ 21.416.<\/p>\n<p>HIST\u00d3RICO<\/p>\n<p>A contrata\u00e7\u00e3o de parentes ou pessoas ligadas \u00e0 fam\u00edlia \u00e9 uma pr\u00e1tica adotada por Hissam Hussein Dehaini desde o primeiro mandato. Em 2019, a Oscip (Organiza\u00e7\u00e3o da Sociedade Civil de Interesse P\u00fablico) Vigilantes da Gest\u00e3o P\u00fablica chegou a entrar com uma reclama\u00e7\u00e3o no STF (Supremo Tribunal Federal) questionando nomea\u00e7\u00f5es, mas o processo foi arquivado no mesmo ano.<\/p>\n<p>A Corte entendeu que as contrata\u00e7\u00f5es n\u00e3o feriam a s\u00famula antinepotismo pois diziam respeito a cargos de natureza pol\u00edtica.<\/p>\n<p>Na \u00e9poca, a Oscip apontava as nomea\u00e7\u00f5es de Cristiane Inez Martins Dehaini (ent\u00e3o esposa do prefeito) como secret\u00e1ria de Assist\u00eancia Social; de Ryam Hissam Dehaini (filha do prefeito), como secret\u00e1ria de Gest\u00e3o de Pessoas; de Jos\u00e9 Roberto Martins (cunhado do prefeito), como secret\u00e1rio de Trabalho e Emprego; e de Eduardo Rogriguez Mello (genro do prefeito), como secret\u00e1rio de Administra\u00e7\u00e3o.<\/p>\n<p>Atualmente, al\u00e9m de Ryam, que segue no comando da pasta de Gest\u00e3o de Pessoas, Yasmim Hissam Dehaini, outra filha do prefeito, est\u00e1 na cadeira de secret\u00e1ria de Administra\u00e7\u00e3o. H\u00e1, ainda, Cilmara Maria do Ros\u00e1rio, nora do prefeito, no cargo de secret\u00e1ria de Comunica\u00e7\u00e3o.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Brasil<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/brasil\/2013427\/prefeito-se-casa-com-adolescente-de-16-anos-e-promove-sogra-a-secretaria-de-cultura-no-pr?utm_source=rss-brasil&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(FOLHAPRESS) &#8211; O prefeito de Arauc\u00e1ria (PR), Hissam Hussein Dehaini (Cidadania), 65, se casou neste<\/p>\n","protected":false},"author":0,"featured_media":121481,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-121480","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/121480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=121480"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/121480\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/121481"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=121480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=121480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=121480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}