{"id":121478,"date":"2023-04-26T08:08:42","date_gmt":"2023-04-26T11:08:42","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/26\/treinador-escolhido-chelsea-ja-teria-chegado-a-acordo-com-pochettino\/"},"modified":"2023-04-26T08:08:42","modified_gmt":"2023-04-26T11:08:42","slug":"treinador-escolhido-chelsea-ja-teria-chegado-a-acordo-com-pochettino","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/26\/treinador-escolhido-chelsea-ja-teria-chegado-a-acordo-com-pochettino\/","title":{"rendered":"Treinador escolhido: Chelsea j\u00e1 teria chegado a acordo com Pochettino"},"content":{"rendered":"<p>O Chelsea teria chegado a um &#8220;acordo verbal&#8221; com Mauricio Pochettino, treinador argentino que assumir\u00e1 o comando t\u00e9cnico dos blues a partir do ver\u00e3o europeu, quando a nova temporada come\u00e7a a ser preparada. Essa informa\u00e7\u00e3o foi divulgada pelos ingleses da talkSPORT nesta quarta-feira.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>A mesma publica\u00e7\u00e3o afirma que os respons\u00e1veis pelo Chelsea est\u00e3o decididos a concluir tudo at\u00e9 o final desta semana.<\/p>\n<p>Lembre-se de que Mauricio Pochettino est\u00e1 sem clube desde junho de 2022, quando deixou o PSG ap\u00f3s duas temporadas completas. Antes disso, ele treinou o Southampton, na Inglaterra, antes de mudar para o Tottenham. Aos 51 anos, ele se prepara para uma nova aventura em terras da rainha.<\/p>\n<p>Leia Tamb\u00e9m: <a href=\"https:\/\/www.noticiasaominuto.com.br\/esporte\/2013478\/guardiola-e-arrogante-mas-no-bom-sentido-sabe-que-e-o-melhor\" target=\"_blank\" rel=\"noopener noreferrer\">&#8220;Guardiola \u00e9 arrogante, mas no bom sentido. Sabe que \u00e9 o melhor&#8221;<\/a><\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Esporte<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/esporte\/2013494\/treinador-escolhido-chelsea-ja-teria-chegado-a-acordo-com-pochettino?utm_source=rss-esporte&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Chelsea teria chegado a um &#8220;acordo verbal&#8221; com Mauricio Pochettino, treinador argentino que assumir\u00e1<\/p>\n","protected":false},"author":0,"featured_media":121479,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-121478","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/121478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=121478"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/121478\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/121479"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=121478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=121478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=121478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}