{"id":121349,"date":"2023-04-25T15:08:22","date_gmt":"2023-04-25T18:08:22","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/25\/betty-faria-critica-quem-xinga-velha-na-web-apos-polemica-com-gagliasso\/"},"modified":"2023-04-25T15:08:22","modified_gmt":"2023-04-25T18:08:22","slug":"betty-faria-critica-quem-xinga-velha-na-web-apos-polemica-com-gagliasso","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/25\/betty-faria-critica-quem-xinga-velha-na-web-apos-polemica-com-gagliasso\/","title":{"rendered":"Betty Faria critica quem &#8216;xinga velha&#8217; na web ap\u00f3s pol\u00eamica com Gagliasso"},"content":{"rendered":"<p>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; \u00c0s v\u00e9speras de completar 82 anos, a atriz Betty Faria diz que o &#8220;ser humano est\u00e1 envenenado de \u00f3dio&#8221; e que &#8220;vivemos na \u00e9poca da hipocrisia&#8221;. A artista foi, recentemente, atacada na internet por sair em defesa da apresentadora Patricia Poeta. A jornalista vem sendo criticada por, entre outras coisas, ter interrompido ao vivo uma fala de Manoel Soares, seu colega no programa Encontro (Globo).<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>Betty tuitou que h\u00e1 uma campanha contra Patricia e questionou se Manoel seria uma v\u00edtima. Por causa disso, virou alvo nas redes. O ator Bruno Gagliasso chegou a compar\u00e1-la \u00e0 atriz Regina Duarte, que ficou conhecida nos \u00faltimos anos por espalhar fake news e defender o governo de Jair Bolsonaro (PL) -Betty se op\u00f4s ao bolsonarismo e apoiou o candidato Ciro Gomes (PDT) no \u00faltimo pleito.<\/p>\n<p>&#8220;N\u00f3s estamos vivendo na \u00e9poca da hipocrisia. Tem que ser politicamente correto. Se uma pessoa que sofre algum tipo de preconceito faz uma cagada, n\u00e3o age corretamente, voc\u00ea n\u00e3o pode falar, porque existe uma milit\u00e2ncia que reage&#8221;, desabafa.<\/p>\n<p>Betty conversou com a reportagem na semana passada, por videoconfer\u00eancia. Aceitou falar sobre o tema de forma generalizada, sem citar o nome de Gagliasso.<\/p>\n<p>&#8220;Mas eu n\u00e3o vou me calar. Sempre fui rebelde. Vou falar o que eu quiser, o que me der vontade, o que eu achar que n\u00e3o est\u00e1 certo. Principalmente, se for para defender uma mulher, que \u00e9 sempre a espinafrada&#8221;, afirma ela.<\/p>\n<p>Na v\u00e9spera da entrevista \u00e0 reportagem, Betty disse ter conversado com uma amiga que \u00e9 de &#8220;esquerda e muito inteligente&#8221; -e que ela n\u00e3o poderia dizer o nome-, e que teria afirmado que elas deveriam &#8220;ficar mais quietas&#8221;.<\/p>\n<p>&#8220;Vivi a ditadura [militar] nos anos 1960, 1970 e n\u00e3o fiquei quieta. Vou ficar quieta agora, a essa altura da vida?&#8221;, questiona. &#8220;Como n\u00e3o pode falar? Que porra de democracia \u00e9 essa que voc\u00ea n\u00e3o pode demonstrar desagrado com determinados comportamentos?&#8221;, indigna-se. Ela completar\u00e1 82 anos em maio.<\/p>\n<p>A atriz, que segue contratada da Globo e acaba de rodar um filme em Portugal, diz que tamb\u00e9m ficou emocionada com todo o apoio que recebeu, especialmente o de Faf\u00e1 de Bel\u00e9m. Mesmo afirmando n\u00e3o ser amiga de Betty, a cantora destacou em publica\u00e7\u00e3o nas redes sociais que a atriz a ensinou sobre &#8220;empoderamento feminino, liberdade, posicionamento e coragem&#8221;.<\/p>\n<p>&#8220;Foi uma declara\u00e7\u00e3o de amor, que eu vou levar para sempre no meu cora\u00e7\u00e3o&#8221;, diz a atriz. Betty Faria pondera, por\u00e9m, que a discuss\u00e3o central evocada pela pol\u00eamica vai al\u00e9m do desrespeito causado pelos ataques que sofreu. &#8220;\u00c9 a radicaliza\u00e7\u00e3o, \u00e9 a guerra.&#8221;<\/p>\n<p>&#8220;E isso se reflete no boboca que entra na internet para xingar uma velha num domingo de manh\u00e3 para aparecer, para ser her\u00f3i. Entendeu?&#8221;, argumenta. &#8220;Como \u00e9 que chama agora o termo? \u00c9 a lacra\u00e7\u00e3o&#8221;, diz, aos risos.<\/p>\n<p>&#8220;As pessoas t\u00eam que ter consci\u00eancia pol\u00edtica. J\u00e1 que tem internet, que tem m\u00eddia, veja um pouco do que est\u00e1 acontecendo no mundo. A extrema direita est\u00e1 entrando e tomando conta&#8221;, analisa.<\/p>\n<p>Para ela, o mundo precisa de paz, mas isso n\u00e3o significa que se aceite impunidade. &#8220;Se [a pessoa] estiver errada, tem que ser chamada a aten\u00e7\u00e3o, sim. N\u00e3o vai agir mal, e eu vou ficar calada&#8221;, enfatiza.<\/p>\n<p><span class=\"news_bold\">NOVOS PROJETOS<\/span><\/p>\n<p>Se a radicaliza\u00e7\u00e3o das redes sociais t\u00eam preocupado Betty Faria, na vida profissional, ela diz que est\u00e1 bem satisfeita com seus trabalhos mais recentes. A atriz acaba de voltar de uma temporada de dois meses em Portugal, onde filmou o longa-metragem &#8220;Justa&#8221;, da diretora portuguesa Teresa Villaverde.<\/p>\n<p>A produ\u00e7\u00e3o conta a hist\u00f3ria de um grupo de sobreviventes dos inc\u00eandios florestais que atingiram o pa\u00eds em 2017. Betty faz o papel de uma brasileira que fica cega. &#8220;Eu tenho muito medo dessa palavra desafio, mas foi o maior da minha carreira, porque eu nunca tinha feito uma personagem cega&#8221;, diz.<\/p>\n<p>Ela afirma tamb\u00e9m que foi uma &#8220;experi\u00eancia inesquec\u00edvel&#8221;. &#8220;Fiz um filme h\u00e1 mais de 40 anos, que at\u00e9 hoje eu conto hist\u00f3rias, que \u00e9 o &#8216;Bye Bye Brasil&#8217; [de 1979, do Cac\u00e1 Diegues].&#8221;<\/p>\n<p>&#8220;Eu sinto que acabei de fazer o &#8216;Bye Bye Portugal&#8217;. Porque quando tem um filme assim, com emo\u00e7\u00f5es fortes, loca\u00e7\u00f5es dif\u00edceis e uma equipe maravilhosa, vira uma fam\u00edlia&#8221;, afirma Betty.<\/p>\n<p>A atriz tamb\u00e9m diz estar muito feliz com o sucesso que a novela &#8220;Partido Alto&#8221; (Globo, 1984) tem feito no Globoplay. O folhetim, escrito por Aguinaldo Silva e Gloria Perez, foi disponibilizado na plataforma de streaming da Globo no \u00faltimo dia 10.<\/p>\n<p>Na hist\u00f3ria, ela faz o papel da manicure Jussara. &#8220;Os dois [Aguinaldo Silva e Gloria Perez] foram muito importantes na minha trajet\u00f3ria, porque me deram muitas oportunidades para mostrar o meu trabalho&#8221;, salienta.<\/p>\n<p>Betty Faria conta que, em sua temporada em Portugal, aproveitou para jantar com o autor, respons\u00e1vel pela adapta\u00e7\u00e3o para a TV de &#8220;Tieta&#8221;, um dos personagens mais marcantes da carreira da atriz.<\/p>\n<p>&#8220;Eu jantei com o Aguinaldo, e ele me disse assim: &#8216;Estou escrevendo o meu livro de mem\u00f3rias, e um cap\u00edtulo \u00e9 s\u00f3 sobre voc\u00ea'&#8221;, relembra ela, emocionada.<\/p>\n<p>Questionada se voltaria a fazer novelas, Betty diz que aceitaria se fosse um &#8220;personagem gostoso&#8221;. &#8220;Eu gosto de trabalhar e adoro fazer televis\u00e3o&#8221;, afirma. &#8220;E eu sou contratada da Globo. N\u00e3o sei se \u00e9 adequado falar, mas a Globo foi muito bacana, muito gentil comigo e ganhei um contrato vital\u00edcio. Ent\u00e3o, estou \u00e0 disposi\u00e7\u00e3o da emissora&#8221;, conclui.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Fama<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/fama\/2013140\/betty-faria-critica-quem-xinga-velha-na-web-apos-polemica-com-gagliasso?utm_source=rss-fama&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; \u00c0s v\u00e9speras de completar 82 anos, a atriz Betty Faria<\/p>\n","protected":false},"author":0,"featured_media":121350,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-121349","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fama-e-tv"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/121349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=121349"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/121349\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/121350"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=121349"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=121349"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=121349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}