{"id":121337,"date":"2023-04-25T14:08:28","date_gmt":"2023-04-25T17:08:28","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/25\/lula-condena-violacao-da-integridade-territorial-da-ucrania\/"},"modified":"2023-04-25T14:08:28","modified_gmt":"2023-04-25T17:08:28","slug":"lula-condena-violacao-da-integridade-territorial-da-ucrania","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/25\/lula-condena-violacao-da-integridade-territorial-da-ucrania\/","title":{"rendered":"Lula condena viola\u00e7\u00e3o da integridade territorial da Ucr\u00e2nia"},"content":{"rendered":"<p>O presidente Luiz In\u00e1cio Lula da Silva condenou a \u201cviola\u00e7\u00e3o da integridade territorial da Ucr\u00e2nia\u201d pela R\u00fassia, em discurso na Assembleia da Rep\u00fablica, parlamento portugu\u00eas. Lula est\u00e1 em viagem oficial a Portugal e foi homenageado, nesta ter\u00e7a-feira (25), em cerim\u00f4nia na Casa.<\/p>\n<p>\u201cAcreditamos em uma ordem internacional fundada no respeito ao Direito Internacional e na preserva\u00e7\u00e3o das soberanias nacionais\u201d, afirmou.<\/p>\n<p>Para Lula, na Europa, \u201cpol\u00edticos demagogos\u201d negam os benef\u00edcios conquistados com a paz e a coopera\u00e7\u00e3o na Uni\u00e3o Europeia. \u201cQuem acredita em solu\u00e7\u00f5es militares para os problemas atuais luta contra os ventos da hist\u00f3ria. Nenhuma solu\u00e7\u00e3o de qualquer conflito, nacional ou internacional, ser\u00e1 duradoura se n\u00e3o for baseada no di\u00e1logo e na negocia\u00e7\u00e3o pol\u00edtica\u201d, disse Lula.<\/p>\n<p>O presidente apontou, novamente, a preocupa\u00e7\u00e3o com as crises alimentar e energ\u00e9tica provocadas pela guerra e defendeu a amplia\u00e7\u00e3o do Conselho de Seguran\u00e7a das Na\u00e7\u00f5es Unidas, para torn\u00e1-lo \u201cmais representativo em seu processo deliberativo e mais eficaz na implementa\u00e7\u00e3o de suas decis\u00f5es\u201d.<\/p>\n<p>Lula tamb\u00e9m citou que a falta de regula\u00e7\u00e3o das redes sociais est\u00e1 impulsionando ideologias extremistas. \u201cO mundo tem visto o recrudescimento de ideologias extremistas, impulsionadas pela ditadura dos algor\u00edtimos. Elas reduzem o espa\u00e7o para o di\u00e1logo e a empatia, propagam o \u00f3dio e constrangem a express\u00e3o de nossa humanidade\u201d, disse.<\/p>\n<p>\u201cEu considero a integra\u00e7\u00e3o resultante da Uni\u00e3o Europeia um patrim\u00f4nio democr\u00e1tico da humanidade. E eu vi no Brasil, a consequ\u00eancia tr\u00e1gica que sempre acontece quando se nega a pol\u00edtica, se nega o di\u00e1logo\u201d, acrescentou o presidente.<\/p>\n<p>Durante o discurso, Lula foi alvo de protestos de parlamentares do partido Chega, de extrema-direita. As manifesta\u00e7\u00f5es come\u00e7aram quando Lula disse que se sentia em casa em Portugal.<\/p>\n<p>O presidente do Parlamento portugu\u00eas, Santos Silva, interrompeu a fala e cobrou respeito. \u201cOs senhores deputados que se querem permanecer na sess\u00e3o plen\u00e1ria devem comportar-se com urbanidade, cortesia e a educa\u00e7\u00e3o que \u00e9 exigida a qualquer representante do povo de portugu\u00eas, chega de degradarem as institui\u00e7\u00f5es, chega de porem vergonha no nome de Portugal\u201d, disse o portugu\u00eas.<\/p>\n<p>Lula, ent\u00e3o, terminou o discurso com a frase \u201cViva a liberdade e democracia, n\u00e3o ao fascismo\u201d. Ap\u00f3s o evento, o presidente falou \u00e0 imprensa que quando as \u201cpessoas n\u00e3o t\u00eam uma coisa boa para aparecer\u201d fazem &#8220;essa cena de rid\u00edculo&#8221;, \u201cum papel\u00e3o\u201d.<\/p>\n<p>A cerim\u00f4nia em homenagem a Lula antecedeu \u00e0 sess\u00e3o solene da Assembleia da Rep\u00fablica em comemora\u00e7\u00e3o os 49 anos da Revolu\u00e7\u00e3o dos Cravos. Em 25 de abril de 1974, um movimento pol\u00edtico e social p\u00f4s fim \u00e0 ditadura de Ant\u00f3nio Salazar em Portugal. Na ocasi\u00e3o, a popula\u00e7\u00e3o distribu\u00eda cravos vermelhos a soldados dissidentes, que os colocavam nos canos de suas armas.<\/p>\n<p>Lula lembrou a democracia que come\u00e7ou em Portugal depois do 25 de abril, \u201ccriando as bases para o desenvolvimento econ\u00f4mico com justi\u00e7a social\u201d, e acrescentou que \u201ca democracia no Brasil viveu recentes amea\u00e7as\u201d.<\/p>\n<p>\u201cSaudosos do autoritarismo tentaram atrasar nosso rel\u00f3gio em 50 anos e reverter as liberdades que conquistamos desde a transi\u00e7\u00e3o democr\u00e1tica. Os ataques foram constantes. Os irm\u00e3os portugueses assistiram a tudo, preocupados com a possibilidade de que o Brasil desse as costas ao mundo. A not\u00edcia que lhes trago \u00e9 que as for\u00e7as democr\u00e1ticas brasileiras demonstraram sua solidez e resili\u00eancia\u201d, disse.<\/p>\n<p>O presidente Lula est\u00e1 em visita oficial a Portugal desde sexta-feira (21). Ontem (24), participou de encontro com empres\u00e1rios e da cerim\u00f4nia de entrega do Pr\u00eamio Cam\u00f5es a Chico Buarque. Em 2019, Chico Buarque foi o vencedor da 31\u00aa edi\u00e7\u00e3o do Pr\u00eamio Luiz Vaz de Cam\u00f5es de Literatura, mas o ato de entrega n\u00e3o foi assinado pelo ent\u00e3o presidente Jair Bolsonaro.<\/p>\n<p>Ap\u00f3s a homenagem na Assembleia da Rep\u00fablica, a comitiva brasileira encerrou a agenda em Portugal e embarcou para Madri, capital da Espanha, \u00faltimo trecho da visita oficial \u00e0 Europa.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Mundo<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/ultima-hora\/2013161\/lula-condena-violacao-da-integridade-territorial-da-ucrania?utm_source=rss-mundo&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O presidente Luiz In\u00e1cio Lula da Silva condenou a \u201cviola\u00e7\u00e3o da integridade territorial da Ucr\u00e2nia\u201d<\/p>\n","protected":false},"author":0,"featured_media":121338,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-121337","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/121337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=121337"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/121337\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/121338"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=121337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=121337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=121337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}