{"id":121212,"date":"2023-04-24T20:08:45","date_gmt":"2023-04-24T23:08:45","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/24\/rival-nocauteado-por-whindersson-manda-recado-para-haters-brasileiros\/"},"modified":"2023-04-24T20:08:45","modified_gmt":"2023-04-24T23:08:45","slug":"rival-nocauteado-por-whindersson-manda-recado-para-haters-brasileiros","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/24\/rival-nocauteado-por-whindersson-manda-recado-para-haters-brasileiros\/","title":{"rendered":"Rival nocauteado por Whindersson manda recado para &#8216;haters brasileiros&#8217;"},"content":{"rendered":"<p>SANTOS, SP (UOL\/FOLHAPRESS) &#8211; O rapper polon\u00eas Filip Marcinek se pronunciou nas redes sociais depois de ser nocauteado por Whindersson Nunes na High Stakes, torneio internacional de boxe.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>&#8220;Ol\u00e1 meus haters brasileiros! Agrade\u00e7o muito todas as mensagens cheias de carinho para mim depois da luta de ontem, honestamente. Nunes foi muito excelente no ringue&#8221;, afirmou Marcinek.<\/p>\n<p>&#8220;Movimento da cabe\u00e7a, controle de ringue, poder nas m\u00e3os. \u00d3timo trabalho. O meu estilo [&#8230;] n\u00e3o foi suficiente para este tipo de estilo de boxe. Meu segundo advers\u00e1rio da noite foram os apoiadores brasileiros do Whindersson&#8221;.<\/p>\n<p>&#8220;\u00c9 uma das melhores li\u00e7\u00f5es para mim lutar rodeado de 11 mil pessoas. Pessoas que realmente te odeiam&#8230; Apesar disso, \u00e9 s\u00f3 um espet\u00e1culo&#8221;, disse.<\/p>\n<p>&#8220;Estou voltando para a Pol\u00f4nia mais rico por esta experi\u00eancia. Uma das mais importantes de toda a minha vida. Te vejo em Londres. Sexta-feira lan\u00e7arei m\u00fasica nova. Podem conferir porque eu prefiro m\u00fasica mais do que esporte&#8221;, concluiu o rapper.<\/p>\n<p><span class=\"news_bold\">VIT\u00d3RIA EM DOIS ROUNDS<\/span><\/p>\n<p>Whindersson Nunes fez bonito na OVO Arena, em Londres (Inglaterra), em sua estreia no &#8216;High Stakes&#8217;, torneio de boxe entre celebridades.<\/p>\n<p>O youtuber do Piau\u00ed precisou de apenas dois rounds para garantir o triunfo e uma vaga na semifinal da competi\u00e7\u00e3o.<\/p>\n<p>Na pr\u00f3xima rodada, que acontecer\u00e1 no dia 3 de junho, Whindersson enfrentar\u00e1 King Kenny, que venceu My Mate Nate tamb\u00e9m por nocaute t\u00e9cnico neste s\u00e1bado (22), em Londres.<\/p>\n<p>Ainda no ringue, o brasileiro ainda aproveitou para retrucar as provoca\u00e7\u00f5es do rapper polon\u00eas, que o chamou de &#8220;palha\u00e7o&#8221; na semana pr\u00e9-evento: &#8220;Eu falei que o palha\u00e7o ia pegar, e pegou&#8221;.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Esporte<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/esporte\/2012857\/rival-nocauteado-por-whindersson-manda-recado-para-haters-brasileiros?utm_source=rss-esporte&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTOS, SP (UOL\/FOLHAPRESS) &#8211; O rapper polon\u00eas Filip Marcinek se pronunciou nas redes sociais depois<\/p>\n","protected":false},"author":0,"featured_media":121213,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-121212","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/121212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=121212"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/121212\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/121213"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=121212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=121212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=121212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}