{"id":121010,"date":"2023-04-23T13:08:35","date_gmt":"2023-04-23T16:08:35","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/23\/militao-marca-vini-jr-da-assistencia-e-real-madrid-vence-celta-no-espanhol\/"},"modified":"2023-04-23T13:08:35","modified_gmt":"2023-04-23T16:08:35","slug":"militao-marca-vini-jr-da-assistencia-e-real-madrid-vence-celta-no-espanhol","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/23\/militao-marca-vini-jr-da-assistencia-e-real-madrid-vence-celta-no-espanhol\/","title":{"rendered":"Milit\u00e3o marca, Vini Jr. d\u00e1 assist\u00eancia e Real Madrid vence Celta no Espanhol"},"content":{"rendered":"<p>Com atua\u00e7\u00f5es decisivas de Vinicius J\u00fanior e \u00c9der Milit\u00e3o, o Real Madrid conquistou a quarta vit\u00f3ria seguida na temporada, por diferentes competi\u00e7\u00f5es. Em casa, fez 2 a 0 sobre o Celta de Vigo, neste s\u00e1bado, pelo Campeonato Espanhol. O atacante brasileiro deu assist\u00eancia para o primeiro gol, enquanto o zagueiro anotou o segundo gol da partida. <\/p>\n<p>O time de Madri chegou aos 65 pontos, a oito do l\u00edder Barcelona, que tem 73 e ainda jogar\u00e1 nesta rodada. De quebra, assegura a vice-lideran\u00e7a da tabela por abrir cinco de vantagem sobre o Atl\u00e9tico de Madrid, o atual terceiro colocado da classifica\u00e7\u00e3o. J\u00e1 o Celta \u00e9 o 12\u00ba, com 36 pontos.<\/p>\n<\/p>\n<p>Ap\u00f3s assegurar a classifica\u00e7\u00e3o \u00e0s semifinais da Liga dos Campe\u00f5es, o t\u00e9cnico Carlo Ancelotti resolveu dar descanso \u00e0 metade da equipe titular do Real. Assim, deu chance para Nacho, R\u00fcdiger, Tchouam\u00e9ni, Dani Ceballos e Marco Asensio neste s\u00e1bado. Vinicius J\u00fanior e Milit\u00e3o foram mantidos entre os titulares, enquanto Rodrygo come\u00e7ou no banco de reservas. <\/p>\n<\/p>\n<p>Com tantas mudan\u00e7as, o Real enfrentou dificuldades para amea\u00e7ar o Celta nos primeiros 30 minutos de jogo. Vini Jr. era a principal arma ofensiva, pela esquerda. Benzema sofria para sair da marca\u00e7\u00e3o. A situa\u00e7\u00e3o s\u00f3 come\u00e7ou a ficar favor\u00e1vel aos anfitri\u00f5es a partir dos 41 minutos, quando o brasileiro avan\u00e7ou pela esquerda e cruzou rasteiro para Asensio, que chegou batendo, direto para as redes. <\/p>\n<\/p>\n<p>O jogo acabou sendo decidido em poucos minutos. Isso porque, logo aos 2 minutos do segundo tempo, o Real alcan\u00e7ou o segundo gol, em lance de bola parada. Ap\u00f3s cobran\u00e7a de escanteio na \u00e1rea, Milit\u00e3o veio de tr\u00e1s surpreendendo os zagueiros rivais e cabeceou firme para o gol. <\/p>\n<\/p>\n<p>Da\u00ed em diante, o Real passou a desacelerar, afora um ou duas investidas com maior perigo no ataque, sempre com a participa\u00e7\u00e3o de Vinicius J\u00fanior. Nos instantes finais, Rodrygo entrou na vaga do compatriota, mas teve pouco tempo para fazer a diferen\u00e7a no ataque madrilenho.<\/p>\n<\/p>\n<p>OUTROS RESULTADOS<\/p>\n<p>Mais cedo, a Real Sociedad sustentou a quarta coloca\u00e7\u00e3o da tabela ao vencer o Rayo Vallecano por 2 a 1, em casa. Sorloth e Lejeune, contra, marcaram os gols dos anfitri\u00f5es. O time da casa chegou a marcar mais um, mas o lance foi anulado pelo VAR, no in\u00edcio da partida. Palazon descontou para o Rayo Vallecano.<\/p>\n<\/p>\n<p>Dentro da zona de classifica\u00e7\u00e3o para a pr\u00f3xima edi\u00e7\u00e3o da Liga dos Campe\u00f5es, a Real Sociedad soma agora 54 pontos, a seis do Atl\u00e9tico de Madrid, que tem um jogo a menos. E seis \u00e0 frente do Betis, quinto colocado, fora da briga pela principal competi\u00e7\u00e3o europeia no momento. <\/p>\n<\/p>\n<p>O Betis perdeu a chance de seguir na cola da Real Sociedad ao ser batido pelo Osasuna por 3 a 2, neste s\u00e1bado. Budimir, duas vezes, e Moncayola, decidiram o jogo ainda no primeiro tempo. O Osasuna ocupa o oitavo lugar da tabela, com 41 pontos.<\/p>\n<\/p>\n<p>Ainda neste s\u00e1bado, o Athletic Bilbao derrotou o Almer\u00eda por 2 a 1, fora de casa, enquanto o Valladolid bateu o Girona por 1 a 0.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Esporte<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/esporte\/2012467\/militao-marca-vini-jr-da-assistencia-e-real-madrid-vence-celta-no-espanhol?utm_source=rss-esporte&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com atua\u00e7\u00f5es decisivas de Vinicius J\u00fanior e \u00c9der Milit\u00e3o, o Real Madrid conquistou a quarta<\/p>\n","protected":false},"author":0,"featured_media":121011,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-121010","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/121010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=121010"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/121010\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/121011"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=121010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=121010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=121010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}