{"id":120978,"date":"2023-04-23T08:08:34","date_gmt":"2023-04-23T11:08:34","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/23\/bruno-rodrigues-decide-cruzeiro-bate-gremio-e-vence-1a-na-volta-a-serie-a\/"},"modified":"2023-04-23T08:08:34","modified_gmt":"2023-04-23T11:08:34","slug":"bruno-rodrigues-decide-cruzeiro-bate-gremio-e-vence-1a-na-volta-a-serie-a","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/23\/bruno-rodrigues-decide-cruzeiro-bate-gremio-e-vence-1a-na-volta-a-serie-a\/","title":{"rendered":"Bruno Rodrigues decide, Cruzeiro bate Gr\u00eamio e vence 1\u00aa na volta \u00e0 S\u00e9rie A"},"content":{"rendered":"<p>S\u00c3O PAULO, SP (UOL\/FOLHAPRESS) &#8211; O Cruzeiro venceu o Gr\u00eamio na noite deste s\u00e1bado (22), por 1 a 0, pela segunda rodada da S\u00e9rie A do Campeonato Brasileiro, no Independ\u00eancia.<br \/>Bruno Rodrigues foi o grande destaque da partida e marcou o \u00fanico gol do confronto em jogada ensaiada de escanteio.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>Essa foi a primeira vit\u00f3ria do time mineiro na sua volta \u00e0 elite do Campeonato Brasileiro. O time ga\u00facho, por sua vez, sofreu a sua primeira derrota no retorno.<\/p>\n<p>O Cruzeiro chegou aos tr\u00eas pontos e agora ocupa a 9\u00aa coloca\u00e7\u00e3o provis\u00f3ria da competi\u00e7\u00e3o. O Gr\u00eamio tem a mesma pontua\u00e7\u00e3o, mas aparece na 11\u00aa posi\u00e7\u00e3o.<\/p>\n<p>O Cruzeiro n\u00e3o vencia um jogo pela S\u00e9rie A do Campeonato Brasileiro desde o dia 31 de outubro de 2019. Naquele dia, o time bateu o Botafogo, fora de casa, por 2 a 0, na 29\u00aa rodada da edi\u00e7\u00e3o daquele ano.<\/p>\n<p><span class=\"news_bold\">COMO FOI O JOGO<\/span><br \/>O Gr\u00eamio come\u00e7ou o jogo dando ind\u00edcios de que poderia controlar a partida. Logo nos primeiros minutos, o time comandado por Renato Ga\u00facho pressionou o Cruzeiro e dificultou a sa\u00edda de bola dos donos da casa.<br \/>Contudo, depois dos 10 minutos de bola rolando, o Cruzeiro tomou conta da partida. O time mineiro, inicialmente, tentou jogadas pelo setor central do gramado, mas encontrou portas fechadas.<\/p>\n<p>A principal sa\u00edda se deu pelo lado esquerdo. A dupla formada por Bruno Rodrigues e Mateus Vital organizou as principais jogadas do Cruzeiro e levou perigo ao gol advers\u00e1rio.<\/p>\n<p>O Cruzeiro come\u00e7ou o segundo tempo pressionando assim como fez durante o final da etapa inicial. Depois de muitos erros de finaliza\u00e7\u00e3o, o gol saiu em uma jogada ensaiada de escanteio.<br \/>Depois do gol marcado, o Cruzeiro abaixou suas linhas e deu a bola para o Gr\u00eamio, que pressionou. A equipe do Rio Grande do Sul criou boas oportunidades de empatar, mas acabou parando em Rafael Cabral.<\/p>\n<p><span class=\"news_bold\">LANCES IMPORTANTES E GOLS<\/span><br \/>Su\u00e1rez quase a abriu o placar logo no primeiro minuto de jogo. O uruguaio surpreendeu ao tentar uma finaliza\u00e7\u00e3o na lateral direita da \u00e1rea. Mesmo sem \u00e2ngulo, obrigou Rafael Cabral a espalmar para escanteio.<\/p>\n<p>A primeira chegada de perigo do Cruzeiro veio pelo alto. Em cruzamento de escanteio, Gilberto apareceu livre na primeira trave e cabeceou, mas mandou nas m\u00e3os de Gabriel Grando.<br \/>No lance seguinte \u00e0 chance de Gilberto, Bruno Rodrigues tabelou com Mateus Vital e arriscou de fora da \u00e1rea. Gabriel Grando voou no canto direito alto e espalmou para escanteio.<br \/>Bruno Rodrigues teve nova chance de abrir o placar pouco depois. Richard desviou cruzamento na dire\u00e7\u00e3o da segunda trave, mas o atacante chegou atrasado e n\u00e3o conseguiu completar para o gol.<\/p>\n<p>A press\u00e3o do Cruzeiro seguiu no final do primeiro tempo e o goleiro do Gr\u00eamio precisou trabalhar de novo. Bruno Rodrigues recebeu cruzamento no meio da \u00e1rea e finalizou de voleio. Gabriel Grando, com a ponta dos dedos, espalmou para escanteio.<\/p>\n<p>Gabriel Grando teve que salvar o Gr\u00eamio novamente, mas j\u00e1 no come\u00e7o do segundo tempo. Richard recebeu passe de Ramiro dentro da \u00e1rea e finalizou de primeira. O goleiro defendeu com o p\u00e9. Na sobra, Vital tentou voleio, mas acertou Bitello.<br \/>Gilberto teve uma chance de ouro aos 11 minutos do segundo tempo. O atacante recebeu passe de Ramiro na marca do p\u00eanalti, mas, livre, pegou mal na bola e isolou.<\/p>\n<p>O gol que abriu o placar para o Cruzeiro saiu em uma jogada ensaiada. Em um escanteio, Filipe Machado cruzou no meio da \u00e1rea, e Bruno Rodrigues apareceu livre para finalizar. A bola saiu mascada, mas encobriu Gabriel Grando.<\/p>\n<p>O goleiro do Cruzeiro evitou o empate em chute de longe de Cristaldo. O argentino soltou a bomba de fora da \u00e1rea, mas viu o camisa 1 cair no canto esquerdo para espalmar.<\/p>\n<p>O Gr\u00eamio teve nova chance de empatar. Su\u00e1rez finalizou, e Rafael Cabral espalmou. No rebote, o uruguaio tocou para o meio, e Cristaldo finalizou mascado, mas na dire\u00e7\u00e3o do gol. Rafael Cabral voltou a tempo e salvou o Cruzeiro.<\/p>\n<p><span class=\"news_bold\">CRUZEIRO<\/span><br \/>Rafael Cabral; William, Lucas Oliveira, Luciano Cast\u00e1n e Marlon; Richard (Neto Moura), Ramiro (Filipe Machado) e Mateus Vital (Wallisson); Nik\u00e3o (Rafael Bil\u00fa), Bruno Rodrigues e Gilberto. T\u00e9cnico: Pepa<\/p>\n<p><span class=\"news_bold\">GR\u00caMIO<\/span><br \/>Gabriel Grando; Jo\u00e3o Pedro, Bruno Alves, Kannemann e Diogo Barbosa; Lucas Silva (Everton Galdino), Bitello e Cristaldo (Gustavinho); Nathan (Zinho), Vina (Andr\u00e9) e Su\u00e1rez. T\u00e9cnico: Renato Ga\u00fachoLocal: Independ\u00eancia, em Belo Horizonte (MG)<br \/>\u00c1rbitro: Fl\u00e1vio Rodrigues de Souza (SP)<br \/>Cart\u00f5es amarelos: Ramiro, Gilberto, Richard, Lucas Oliveira, Marlon (CRU), Su\u00e1rez, Kannemann (GRE)<br \/>Cart\u00e3o vermelho: Lucas Oliveira (CRU)<br \/>Gols: Bruno Rodrigues (18&#8217;\/2\u00b0T)<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Esporte<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/esporte\/2012508\/bruno-rodrigues-decide-cruzeiro-bate-gremio-e-vence-1-na-volta-a-serie-a?utm_source=rss-esporte&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00c3O PAULO, SP (UOL\/FOLHAPRESS) &#8211; O Cruzeiro venceu o Gr\u00eamio na noite deste s\u00e1bado (22),<\/p>\n","protected":false},"author":0,"featured_media":120979,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-120978","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/120978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=120978"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/120978\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/120979"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=120978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=120978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=120978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}