{"id":120967,"date":"2023-04-23T06:08:35","date_gmt":"2023-04-23T09:08:35","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/23\/messi-chega-a-barcelona-carregado-de-malas-e-faz-disparar-os-rumores\/"},"modified":"2023-04-23T06:08:35","modified_gmt":"2023-04-23T09:08:35","slug":"messi-chega-a-barcelona-carregado-de-malas-e-faz-disparar-os-rumores","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/23\/messi-chega-a-barcelona-carregado-de-malas-e-faz-disparar-os-rumores\/","title":{"rendered":"Messi chega a Barcelona carregado de malas e faz &#8216;disparar&#8217; os rumores"},"content":{"rendered":"<p>Lionel Messi chegou, ao final da manh\u00e3 de s\u00e1bado, no Aeroporto Josep Tarradellas Barcelona-El Prat, menos de 24 horas depois de ter ajudado o Paris Saint-Germain a derrotar o Angers, por 2-1, com uma assist\u00eancia para o gol de Kylian Mbapp\u00e9.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>De acordo com o jornalista espanhol Gerard Romero, sempre bem informado a prop\u00f3sito da atualidade do Barcelona, o jogador argentino voou acompanhado da fam\u00edlia&#8230; e de &#8220;14 malas&#8221;, fazendo, de imediato, &#8216;disparar&#8217; os rumores.<\/p>\n<p>Lembrando que o atacante, de 35 anos, termina contrato com os atuais campe\u00f5es franceses no pr\u00f3ximo m\u00eas de junho, sendo que as mais recentes informa\u00e7\u00f5es oriundas da Fran\u00e7a afirmam que o destino de Messi est\u00e1 cada vez mais longe do PSG.<\/p>\n<p>Uma situa\u00e7\u00e3o que tem aumentado as esperan\u00e7as do presidente do Barcelona, Joan Laporta, que nunca escondeu que veria com bons olhos a possibilidade de recuperar o jogador que, h\u00e1 apenas dois anos, perdeu, a &#8216;custo zero&#8217;.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"es\">NOTICIA <a href=\"https:\/\/twitter.com\/JijantesFC?ref_src=twsrc%5Etfw\">@JijantesFC<\/a> <\/p>\n<p>LEO MESSI se encuentra desde hoy al mediod\u00eda en Barcelona junto con su familia<\/p>\n<p>Han llegado en un vuelo privado y Pepe Costa ha salido por la terminal corporativa con 14 maletas<\/p>\n<p>Leo ha salido escondido por la T1 del aeropuerto con su familia<\/p>\n<p>\u2014 Jijantes FC (@JijantesFC) <a href=\"https:\/\/twitter.com\/JijantesFC\/status\/1649890785289023492?ref_src=twsrc%5Etfw\">April 22, 2023<\/a><\/p><\/blockquote>\n<p>Leia Tamb\u00e9m: <a href=\"https:\/\/www.noticiasaominuto.com.br\/esporte\/2012385\/al-hilal-vai-a-paris-para-seduzir-messi-com-proposta-de-outro-mundo\" target=\"_blank\" rel=\"noopener\">Al Hilal vai a Paris para seduzir Messi com proposta &#8216;de outro mundo&#8217;<\/a><\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Esporte<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/esporte\/2012516\/messi-chega-a-barcelona-carregado-de-malas-e-faz-disparar-os-rumores?utm_source=rss-esporte&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lionel Messi chegou, ao final da manh\u00e3 de s\u00e1bado, no Aeroporto Josep Tarradellas Barcelona-El Prat,<\/p>\n","protected":false},"author":0,"featured_media":120968,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-120967","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/120967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=120967"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/120967\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/120968"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=120967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=120967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=120967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}