{"id":120886,"date":"2023-04-22T12:08:17","date_gmt":"2023-04-22T15:08:17","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/22\/deputado-propoe-lei-para-facilitar-a-compra-de-lotes-urbanizados-em-mato-grosso\/"},"modified":"2023-04-22T12:08:17","modified_gmt":"2023-04-22T15:08:17","slug":"deputado-propoe-lei-para-facilitar-a-compra-de-lotes-urbanizados-em-mato-grosso","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/22\/deputado-propoe-lei-para-facilitar-a-compra-de-lotes-urbanizados-em-mato-grosso\/","title":{"rendered":"Deputado prop\u00f5e lei para facilitar a compra de lotes urbanizados em Mato Grosso"},"content":{"rendered":"<p>O deputado estadual Cl\u00e1udio Ferreira (PTB) apresentou, na Assembleia Legislativa, o projeto que cria a \u201cLei Lote Legal\u201d, que tem o objetivo de facilitar a aquisi\u00e7\u00e3o de lotes urbanizados por fam\u00edlias de baixa renda. Os lotes dever\u00e3o ser ofertados pelo governo do Estado, com valores pelo menos 50% menores do que os praticados no mercado.<\/p>\n<p>Para participar do programa, a pessoa deve ser maior de 18 anos, ter renda familiar de at\u00e9 cinco sal\u00e1rios m\u00ednimos e n\u00e3o ter outro im\u00f3vel. Cl\u00e1udio menciona que, muitas vezes, o pr\u00f3prio governo do Estado enfrenta a burocracia \u2014 e tamb\u00e9m a dificuldade financeira \u2014 para tocar e construir grandes conjuntos habitacionais. \u201cE muitas fam\u00edlias precisam de apenas desse empurr\u00e3ozinho, que \u00e9 a ajuda para adquirir um lote\u201d, aponta,<\/p>\n<p>De acordo com o projeto, no Lote Legal, o governo dever\u00e1 ofertar os lotes com infraestrutura b\u00e1sica de \u00e1gua, esgoto, pavimenta\u00e7\u00e3o asf\u00e1ltica, passeio p\u00fablico e ilumina\u00e7\u00e3o p\u00fablica, informa a assessoria.<\/p>\n<p>O projeto vai ser apreciado nas comiss\u00f5es permanentes e, posteriormente, ser\u00e1 votado em plen\u00e1rio.<\/p>\n<p>Fonte: S\u00f3 Not\u00edcias<br \/>\nArtigo Original em &gt; www.sonoticias.com.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O deputado estadual Cl\u00e1udio Ferreira (PTB) apresentou, na Assembleia Legislativa, o projeto que cria a<\/p>\n","protected":false},"author":0,"featured_media":120887,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-120886","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/120886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=120886"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/120886\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/120887"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=120886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=120886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=120886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}