{"id":120772,"date":"2023-04-21T15:08:21","date_gmt":"2023-04-21T18:08:21","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/21\/eliezer-relata-susto-com-filha-lua-meu-coracao-parou\/"},"modified":"2023-04-21T15:08:21","modified_gmt":"2023-04-21T18:08:21","slug":"eliezer-relata-susto-com-filha-lua-meu-coracao-parou","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/21\/eliezer-relata-susto-com-filha-lua-meu-coracao-parou\/","title":{"rendered":"Eliezer relata susto com filha Lua: &#8216;Meu cora\u00e7\u00e3o parou&#8217;"},"content":{"rendered":"<p>Eliezer, pai da pequena Lua, compartilhou recentemente um momento de desespero que viveu ao chegar ao quarto da filha durante a madrugada e encontr\u00e1-la com a cabe\u00e7a coberta. Ele usou as redes sociais para desabafar sobre a situa\u00e7\u00e3o e alertar outros pais.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>Eliezer explicou que monitora a menina de hora em hora e coloca o alarme para despertar. &#8220;Assim que cheguei l\u00e1, da minha vis\u00e3o, da porta, a coberta estava na cabe\u00e7a dela&#8221;, disse ele, acrescentando que a filha se mexe bastante. Ele imediatamente tirou a coberta da cabe\u00e7a da beb\u00ea, mas a experi\u00eancia deixou-o assustado.<\/p>\n<p>O pai mencionou o medo da morte s\u00fabita em rec\u00e9m-nascidos, que pode ser causada pelo sufocamento do beb\u00ea com objetos, bichos de pel\u00facia ou v\u00e9us no ber\u00e7o. Como resultado, ele decidiu n\u00e3o usar mais cobertas na filha durante a noite e est\u00e1 procurando alternativas para mant\u00ea-la aquecida, j\u00e1 que em S\u00e3o Paulo, onde a fam\u00edlia mora, os dias frios j\u00e1 come\u00e7aram.<\/p>\n<p>Eliezer tamb\u00e9m ressaltou que as enfermeiras disseram que a filha n\u00e3o tem for\u00e7a para virar o pesco\u00e7o, mas ele afirmou que a beb\u00ea tem for\u00e7a para virar o corpo inteiro. Ele concluiu dizendo que n\u00e3o quer passar por outro susto como esse novamente. A boa not\u00edcia \u00e9 que tudo acabou bem!<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Fama<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/fama\/2012210\/eliezer-relata-susto-com-filha-lua-meu-coracao-parou?utm_source=rss-fama&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eliezer, pai da pequena Lua, compartilhou recentemente um momento de desespero que viveu ao chegar<\/p>\n","protected":false},"author":0,"featured_media":120773,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-120772","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fama-e-tv"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/120772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=120772"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/120772\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/120773"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=120772"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=120772"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=120772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}