{"id":120656,"date":"2023-04-20T20:09:02","date_gmt":"2023-04-20T23:09:02","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/20\/chelsea-fara-amistoso-nos-eua-contra-time-de-ator-de-hollywood\/"},"modified":"2023-04-20T20:09:02","modified_gmt":"2023-04-20T23:09:02","slug":"chelsea-fara-amistoso-nos-eua-contra-time-de-ator-de-hollywood","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/20\/chelsea-fara-amistoso-nos-eua-contra-time-de-ator-de-hollywood\/","title":{"rendered":"Chelsea far\u00e1 amistoso nos EUA contra time de ator de Hollywood"},"content":{"rendered":"<p>SANTOS, SP (UOL\/FOLHAPRESS) &#8211; O Chelsea anunciou nesta quinta-feira (20) que far\u00e1 um amistoso nos Estados Unidos contra o Wrexham, time que tem o ator Ryan Reynolds como dono.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>A partida acontecer\u00e1 no dia 19 de julho, no Kenan Stadium da Universidade da Carolina do Norte, nos Estados Unidos, com capacidade para 50 mil pessoas.<\/p>\n<p>O Wrexham est\u00e1 localizado em Pa\u00eds de Gales, mas disputa a liga inglesa.<\/p>\n<p>Atualmente, o time lidera a quinta divis\u00e3o e est\u00e1 bem perto do acesso.<\/p>\n<p>A informa\u00e7\u00e3o do amistoso foi confirmada tanto pelo Chelsea como pelo Wrexham.<\/p>\n<p>Ter a oportunidade de enfrentar um time do calibre do Chelsea no Kenan Stadium, na Carolina do Norte, ser\u00e1 um grande teste para nossos jogadores e ser\u00e1 uma parte importante de nossa prepara\u00e7\u00e3o para a temporada 2023\/24&#8243;, disse Phil Parkinson, gerente do Wrexham, ao site oficial.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Esporte<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/esporte\/2011860\/chelsea-fara-amistoso-nos-eua-contra-time-de-ator-de-hollywood?utm_source=rss-esporte&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTOS, SP (UOL\/FOLHAPRESS) &#8211; O Chelsea anunciou nesta quinta-feira (20) que far\u00e1 um amistoso nos<\/p>\n","protected":false},"author":0,"featured_media":120657,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-120656","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/120656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=120656"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/120656\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/120657"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=120656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=120656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=120656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}