{"id":120554,"date":"2023-04-20T07:08:51","date_gmt":"2023-04-20T10:08:51","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/20\/fim-do-icms-na-troca-de-mercadorias-de-uma-mesma-empresa-vai-valer-em-2024\/"},"modified":"2023-04-20T07:08:51","modified_gmt":"2023-04-20T10:08:51","slug":"fim-do-icms-na-troca-de-mercadorias-de-uma-mesma-empresa-vai-valer-em-2024","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/20\/fim-do-icms-na-troca-de-mercadorias-de-uma-mesma-empresa-vai-valer-em-2024\/","title":{"rendered":"Fim do ICMS na troca de mercadorias de uma mesma empresa vai valer em 2024"},"content":{"rendered":"<p>(FOLHAPRESS) &#8211; O STF (Supremo Tribunal Federal) confirmou, nesta quarta-feira (19), o resultado do julgamento sobre o destino dos cr\u00e9ditos de ICMS (Imposto sobre Circula\u00e7\u00e3o de Mercadorias e Servi\u00e7os), uma decis\u00e3o que favorece empresas do varejo.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>Por maioria de votos, o colegiado modulou que os efeitos do julgamento da ADC (A\u00e7\u00e3o Declarat\u00f3ria de Constitucionalidade) 49, realizado em 2021, valer\u00e3o somente a partir de 2024.<\/p>\n<p>A decis\u00e3o proibia a incid\u00eancia do ICMS sobre o envio de mercadorias entre estabelecimentos de um mesmo contribuinte, mas que ficam em estados diferentes.<\/p>\n<p>Em 2021, por unanimidade, o plen\u00e1rio do Supremo havia declarado a inconstitucionalidade de dispositivos da lei complementar 87\/1996, a Lei Kandir.<\/p>\n<p>Esses dispositivos previam a ocorr\u00eancia de fato gerador do tributo quando estabelecimentos de uma mesma empresa faziam uma transfer\u00eancia interestadual de mercadorias.<\/p>\n<p>O relator, ministro Edson Fachin, apontou em seu voto a necessidade de dar seguran\u00e7a jur\u00eddica na tributa\u00e7\u00e3o e equil\u00edbrio do federalismo fiscal.<\/p>\n<p>Em sua avalia\u00e7\u00e3o, as opera\u00e7\u00f5es praticadas e as estruturas negociais concebidas pelos contribuintes, sobretudo em rela\u00e7\u00e3o a benefici\u00e1rios de incentivos fiscais de ICMS em opera\u00e7\u00f5es interestaduais, devem ser protegidas.<\/p>\n<p>O entendimento de Fachin era o de que a simples circula\u00e7\u00e3o de uma mercadoria n\u00e3o gerava imposto, por n\u00e3o haver mudan\u00e7a de dono, e que o ICMS deve ser cobrado quando os produtos s\u00e3o transferidos de um estado para o outro e h\u00e1 mudan\u00e7a de propriet\u00e1rio.<\/p>\n<p>O ministro tamb\u00e9m ressaltou o risco de revis\u00e3o de um grande volume de opera\u00e7\u00f5es de transfer\u00eancias que n\u00e3o foram contestadas nos cinco anos que precederam a decis\u00e3o.<\/p>\n<p>O voto do relator foi seguido por Ricardo Lewandowski, C\u00e1rmen L\u00facia, Rosa Weber, Lu\u00eds Roberto Barroso e Gilmar Mendes.<\/p>\n<p>Os ministros Dias Toffoli, Alexandre de Moraes, Nunes Marques, Luiz Fux e Andr\u00e9 Mendon\u00e7a votaram para que a decis\u00e3o passasse a valer ap\u00f3s 18 meses, contados a partir da data de publica\u00e7\u00e3o da ata de julgamento dos embargos de declara\u00e7\u00e3o.<\/p>\n<p>Leia Tamb\u00e9m: <a href=\"https:\/\/www.noticiasaominuto.com.br\/politica\/2011619\/filho-de-bolsonaro-ameaca-deputado-que-questionou-facada-do-pai\" target=\"_blank\" rel=\"noopener noreferrer\">Filho de Bolsonaro amea\u00e7a deputado que questionou facada do pai<\/a><\/p>\n<p><a href=\"https:\/\/www.noticiasaominuto.com.br\/economia\/2011562\/2-fim-do-icms-na-troca-de-mercadorias-de-uma-mesma-empresa-vai-valer-em-2024?utm_source=rss-economia&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><br \/>\nNot\u00edcias ao Minuto Brasil &#8211; Economia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(FOLHAPRESS) &#8211; O STF (Supremo Tribunal Federal) confirmou, nesta quarta-feira (19), o resultado do julgamento<\/p>\n","protected":false},"author":0,"featured_media":120555,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-120554","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/120554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=120554"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/120554\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/120555"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=120554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=120554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=120554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}