{"id":120435,"date":"2023-04-19T13:08:15","date_gmt":"2023-04-19T16:08:15","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/19\/ifmt-abre-processo-seletivo-em-colider-para-curso-de-tecnologia-em-sistemas-para-internet\/"},"modified":"2023-04-19T13:08:15","modified_gmt":"2023-04-19T16:08:15","slug":"ifmt-abre-processo-seletivo-em-colider-para-curso-de-tecnologia-em-sistemas-para-internet","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/19\/ifmt-abre-processo-seletivo-em-colider-para-curso-de-tecnologia-em-sistemas-para-internet\/","title":{"rendered":"IFMT abre processo seletivo em Col\u00edder para curso de Tecnologia em Sistemas para Internet"},"content":{"rendered":"<p>O Instituto Federal de Educa\u00e7\u00e3o, Ci\u00eancia e Tecnologia de Mato Grosso lan\u00e7ou o edital com 10 vagas remanescentes para o curso de Tecnologia em Sistemas para Internet, no polo de Col\u00edder. As inscri\u00e7\u00f5es para o processo seletivo treinam na pr\u00f3xima segunda-feira (24) no site do IFMT.\u00a0<\/p>\n<p>No site est\u00e3o descritos documentos para serem feitas as inscri\u00e7\u00f5es no processo seletivo, o candidato deve ter conclu\u00eddo o ensino m\u00e9dio. A taxa \u00e9 R$ 50. A coordenadora do Polo UAB Col\u00edder, Rosana da Silva destacou que os interessados tamb\u00e9m podem ir at\u00e9 a unidade, na Avenida Tancredo Neves, Bairro da Torre, em busca de aux\u00edlio e informa\u00e7\u00f5es complementares.\u00a0<\/p>\n<p>O resultado dos aprovados\/classificados saem at\u00e9 julho.<\/p>\n<p>Fonte: S\u00f3 Not\u00edcias<br \/>\nArtigo original em &gt; www.sonoticias.com.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Instituto Federal de Educa\u00e7\u00e3o, Ci\u00eancia e Tecnologia de Mato Grosso lan\u00e7ou o edital com<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[35],"tags":[],"class_list":["post-120435","post","type-post","status-publish","format-standard","hentry","category-educacao"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/120435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=120435"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/120435\/revisions"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=120435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=120435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=120435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}