{"id":120414,"date":"2023-04-19T11:08:05","date_gmt":"2023-04-19T14:08:05","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/19\/sinop-deputado-que-preside-a-fpa-diz-na-norte-show-que-governo-tera-que-fazer-magica-e-destinar-recursos-para-producao\/"},"modified":"2023-04-19T11:08:05","modified_gmt":"2023-04-19T14:08:05","slug":"sinop-deputado-que-preside-a-fpa-diz-na-norte-show-que-governo-tera-que-fazer-magica-e-destinar-recursos-para-producao","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/19\/sinop-deputado-que-preside-a-fpa-diz-na-norte-show-que-governo-tera-que-fazer-magica-e-destinar-recursos-para-producao\/","title":{"rendered":"Sinop: deputado que preside a FPA diz na Norte Show que governo ter\u00e1 que fazer \u2018m\u00e1gica\u2019 e destinar recursos para produ\u00e7\u00e3o"},"content":{"rendered":"<p>O deputado federal e presidente da Frente Parlamentar da Agropecu\u00e1ria, Pedro Lupion (PR), destacou, ontem \u00e0 noite, durante a Norte Show medidas para o fortalecimento do agro no pa\u00eds e principais empecilhos do setor que devem ser solucionados, citando a infraestrutura com a duplica\u00e7\u00e3o da BR-163 e implanta\u00e7\u00e3o da ferrovia estadual em Mato Grosso.\u00a0Ele fez a primeira palestra da feira agropecu\u00e1ria e abordou as medidas de ajustes fiscais do governo Lula e os impactos no agro. <\/p>\n<p>\u201cFoi anunciado um arcabou\u00e7o fiscal que prev\u00ea que a despesa vai correr atr\u00e1s da receita, na verdade est\u00e1 ao contr\u00e1rio, a despesa subiu muito e a receita n\u00e3o subiu o suficiente. Alguma m\u00e1gica ter\u00e1 que ser feita pela economia para buscar os recursos necess\u00e1rios para financiar a produ\u00e7\u00e3o. S\u00f3 temos competitividade e protagonismo que temos na agropecu\u00e1ria mundial por causa do apoio que tem do estado nessa quest\u00e3o do plano safra que n\u00e3o \u00e9 milagre nenhum. \u00c9 apenas juros subsidiado para dar mais competividade aos nossos produtores\u201d, acrescentou.\u00a0<\/p>\n<p>Por outro lado, o deputado tamb\u00e9m destacou para uma recente medida adotada. \u201cO minist\u00e9rio da Agricultura divulgou nova medida, uma linha de cr\u00e9dito em d\u00f3lar para facilitar o dia a dia dos nossos produtores, algo que j\u00e1 existe no mercado financeiro tradicional e agora entra o poder p\u00fablico. \u00c9 interessante, \u00e9 bom e \u00e9 uma medida que for para somar \u00e9 positivo e vamos aplaudir, n\u00e3o fazemos uma oposi\u00e7\u00e3o s\u00f3 por oposi\u00e7\u00e3o, estamos aqui para exigir apoio e respeito ao nosso setor\u201d.\u00a0<\/p>\n<p>O presidente da FPA ressaltou que a tentativa de di\u00e1logo segue com o governo federal, entretanto, alertou para necessidades e meio para auxiliar os produtores. \u201cEstamos negociando muito forte com o governo federal, independentemente das quest\u00f5es ideol\u00f3gicas de posicionalmente pol\u00edtico. N\u00f3s precisamos fomentar a safra e apoiar os produtores rurais. Estamos com nossas entidades todas no IPA (Instituto Pensar Agro) para fazer um c\u00e1lculo de praticamente R$ 400 bilh\u00f5es para que o plano safra seja seguro, temos que chegar perto disso e buscar esse recurso. De onde eles v\u00e3o sair o governo federal tem que nos apontar\u201d, detalhou.\u00a0<\/p>\n<p>\u201cEstamos melhorando a legisla\u00e7\u00e3o acima de tudo, trabalhando muito para regulariza\u00e7\u00e3o fundi\u00e1ria e simplifica\u00e7\u00e3o de licen\u00e7as ambientais, algo que atrasa muito nas obras de infraestrutura. Almocei, em Cuiab\u00e1 (ontem), com o Mauro Mendes, praticamente 90% da Assembleia Legislativa e v\u00e1rias entidades tratando da 163, ferrovias e pontos importantes do gargalo principalmente no modais de transportes, que n\u00e3o \u00e9 s\u00f3 preocupa\u00e7\u00e3o daqui como de todo o Brasil. O governador passou os n\u00fameros de quantas estradas vicinais foram pavimentadas e receberam infraestrutura e temos que fazer isso mesmo\u201d, disse Lupion. \u00a0<\/p>\n<p>Lupion tamb\u00e9m refor\u00e7ou a import\u00e2ncia da Norte Show, em Sinop, e uni\u00e3o entre produtores, sindicatos e entidades. \u201cE nessas feiras que a gente v\u00ea a realidade do campo, s\u00e3o feiras que mostram a pot\u00eancia da nossa produ\u00e7\u00e3o e tudo aquilo que os produtores rurais fazem pelo Brasil e mundo. Tem que ser valorizado e \u00e9 isso que a gente tem feito pela frente parlamentar, essa proximidade com as entidades e sindicatos\u201d. \u201cO Brasil \u00e9 protagonista, o Mato Grosso tamb\u00e9m e merece muito nosso respeito, temos muito o que aprender com os mato-grossenses\u201d,\u00a0concluiu.\u00a0<\/p>\n<p><a href=\"https:\/\/chat.whatsapp.com\/GlnxgGg8UmIKFKzEKwsWMy\">Receba em seu WhatsApp informa\u00e7\u00f5es publicadas em S\u00f3 Not\u00edcias. Clique aqui.<\/a><\/p>\n<p>Fonte: S\u00f3 Not\u00edcias<br \/>\nArtigo Original em &gt; www.sonoticias.com.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O deputado federal e presidente da Frente Parlamentar da Agropecu\u00e1ria, Pedro Lupion (PR), destacou, ontem<\/p>\n","protected":false},"author":0,"featured_media":120415,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-120414","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/120414","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=120414"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/120414\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/120415"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=120414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=120414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=120414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}