{"id":120405,"date":"2023-04-19T10:08:26","date_gmt":"2023-04-19T13:08:26","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/19\/mp-propoe-acao-contra-lei-usada-para-calculo-do-iptu-em-varzea-grande\/"},"modified":"2023-04-19T10:08:26","modified_gmt":"2023-04-19T13:08:26","slug":"mp-propoe-acao-contra-lei-usada-para-calculo-do-iptu-em-varzea-grande","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/19\/mp-propoe-acao-contra-lei-usada-para-calculo-do-iptu-em-varzea-grande\/","title":{"rendered":"MP\u00a0prop\u00f5e a\u00e7\u00e3o contra lei usada para\u00a0c\u00e1lculo do IPTU\u00a0em V\u00e1rzea Grande"},"content":{"rendered":"<\/p>\n<p>O Minist\u00e9rio P\u00fablico do Estado ingressou, hoje, com a\u00e7\u00e3o requerendo a declara\u00e7\u00e3o da inconstitucionalidade da Lei 5.037\/22, sobre a nova planta gen\u00e9rica da \u00e1rea urbana para efeito de c\u00e1lculo e lan\u00e7amento do Imposto sobre a Propriedade Predial e Territorial Urbana e argumenta que a lei introduziu inova\u00e7\u00f5es legislativas no c\u00e1lculo e lan\u00e7amento do IPTU. \u201cNos moldes em que se encontra, a norma hostilizada malfere o artigo 50, IV, da Constitui\u00e7\u00e3o Estadual de Mato Grosso e viola os princ\u00edpios da veda\u00e7\u00e3o ao confisco e da capacidade contributiva\u201d, diz um trecho da A\u00e7\u00e3o Direta de Inconstitucionalidade. <\/p>\n<p>A promotoria aponta que a lei instituiu majora\u00e7\u00e3o impactante no valor unit\u00e1rio por metro quadrado de terreno, se comparado a anos anteriores. No bairro Centro Sul, por exemplo, o valor unit\u00e1rio do metro quadrado da Rua Almirante Barroso passou de R$ 116,62 para R$ 390. J\u00e1 na rua Salim Nadaf, tamb\u00e9m no centro da cidade, o maior valor do metro quadrado da regi\u00e3o subiu de R$ 190,95 para R$ 500,00.<\/p>\n<p>\u201cO princ\u00edpio de veda\u00e7\u00e3o ao n\u00e3o confisco tem natureza de garantia constitucional e representa uma coibi\u00e7\u00e3o \u00e0 injusta apropria\u00e7\u00e3o pelo Estado do patrim\u00f4nio ou das rendas dos contribuintes, de forma a comprometer-lhes, em raz\u00e3o da insuportabilidade da carga tribut\u00e1ria, o exerc\u00edcio do direito a uma exist\u00eancia digna, a pr\u00e1tica de atividade profissional l\u00edcita ou, ainda, a regular satisfa\u00e7\u00e3o de suas necessidades vitais b\u00e1sicas\u201d, afirmou o MP.<\/p>\n<p> Na a\u00e7\u00e3o, o procurador-geral de Justi\u00e7a, Deosdete Cruz Junior, destacou que o aumento abusivo e repentino do IPTU j\u00e1 foi objeto de discuss\u00e3o no Tribunal de Justi\u00e7a, que decidiu pela declara\u00e7\u00e3o da inconstitucionalidade da lei que tratava do assunto em Cuiab\u00e1. A a\u00e7\u00e3o foi distribu\u00edda ao desembargador Juvenal Pereira da Silva.<\/p>\n<p>Fonte: S\u00f3 Not\u00edcias<br \/>\nArtigo Original em &gt; www.sonoticias.com.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Minist\u00e9rio P\u00fablico do Estado ingressou, hoje, com a\u00e7\u00e3o requerendo a declara\u00e7\u00e3o da inconstitucionalidade da<\/p>\n","protected":false},"author":0,"featured_media":120406,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-120405","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/120405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=120405"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/120405\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/120406"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=120405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=120405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=120405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}