{"id":120289,"date":"2023-04-18T18:08:23","date_gmt":"2023-04-18T21:08:23","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/18\/em-retorno-alcaraz-vence-portugues-em-estreia-no-torneio-de-barcelona\/"},"modified":"2023-04-18T18:08:23","modified_gmt":"2023-04-18T21:08:23","slug":"em-retorno-alcaraz-vence-portugues-em-estreia-no-torneio-de-barcelona","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/18\/em-retorno-alcaraz-vence-portugues-em-estreia-no-torneio-de-barcelona\/","title":{"rendered":"Em retorno, Alcaraz vence portugu\u00eas em estreia no Torneio de Barcelona"},"content":{"rendered":"<p>De volta \u00e0s quadras ap\u00f3s perder o Masters 1000 de Montecarlo, Carlos Alcaraz n\u00e3o teve dificuldades para vencer em sua estreia no Torneio de Barcelona, diante dos seus torcedores, nesta ter\u00e7a-feira. O tenista da casa venceu o portugu\u00eas Nuno Borges por 2 sets a 0, com parciais de 6\/3 e 6\/1.<\/p>\n<p>Alcaraz havia desfalcado a chave em Montecarlo, na semana passada, por conta de uma artrite p\u00f3s-traum\u00e1tica na m\u00e3o esquerda e tamb\u00e9m devido a um desconforto muscular na coluna. Recuperado, ele estreou nesta ter\u00e7a sem demonstrar sinais de dores no duelo que durou apenas 64 minutos.<\/p>\n<\/p>\n<p>Nas oitavas de final, o atual n\u00famero dois do mundo far\u00e1 um confronto totalmente espanhol diante de Roberto Bautista Agut, que avan\u00e7ou nesta ter\u00e7a ao derrotar outro tenista da casa, Bernabe Zapata Miralles, por duplo 6\/2.<\/p>\n<\/p>\n<p>Atual terceiro colocado do ranking, o noruegu\u00eas Casper Ruud tamb\u00e9m estreou com vit\u00f3ria nesta ter\u00e7a, diretamente na segunda rodada. Ele superou o americano Ben Shelton por 6\/2 e 7\/6 (7\/1). Seu advers\u00e1rio nas oitavas vai sair do confronto entre o italiano Francesco Passaro e o argentino Francisco Cerundolo.<\/p>\n<\/p>\n<p>Tamb\u00e9m pela segunda rodada, venceram o espanhol Alejandro Davidovich Fokina e o finland\u00eas Emil Ruusuvuori, que v\u00e3o se enfrentar nas oitavas. O tenista da casa despachou o argentino Tomas Martin Etcheverry por duplo 6\/3. E Ruusuvuori surpreendeu ao eliminar o americano Frances Tiafoe por 6\/4, 6\/7 (3\/7) e 6\/4. <\/p>\n<\/p>\n<p>J\u00e1 pela rodada de abertura, os veteranos espanh\u00f3is Fernando Verdasco, Albert Ramos-Vinolas e Feliciano L\u00f3pez se despediram de forma precoce do torneio catal\u00e3o. J\u00e1 o argentino Diego Schwartzman e o belga David Goffin venceram seus jogos e alcan\u00e7aram a segunda rodada.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Esporte<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/esporte\/2010979\/em-retorno-alcaraz-vence-portugues-em-estreia-no-torneio-de-barcelona?utm_source=rss-esporte&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>De volta \u00e0s quadras ap\u00f3s perder o Masters 1000 de Montecarlo, Carlos Alcaraz n\u00e3o teve<\/p>\n","protected":false},"author":0,"featured_media":120290,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-120289","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/120289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=120289"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/120289\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/120290"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=120289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=120289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=120289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}