{"id":120261,"date":"2023-04-18T15:08:58","date_gmt":"2023-04-18T18:08:58","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/18\/benadryl-menino-de-13-anos-morre-ao-tentar-desafio-do-tiktok\/"},"modified":"2023-04-18T15:08:58","modified_gmt":"2023-04-18T18:08:58","slug":"benadryl-menino-de-13-anos-morre-ao-tentar-desafio-do-tiktok","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/18\/benadryl-menino-de-13-anos-morre-ao-tentar-desafio-do-tiktok\/","title":{"rendered":"&#8216;Benadryl&#8217;: Menino de 13 anos morre ao tentar desafio do TikTok"},"content":{"rendered":"<p>Jacob Stevens, de 13 anos, morreu ap\u00f3s ter tentado completar um desafio viral da rede social TikTok que consiste em tomar comprimidos do anti-histam\u00ednico Benadryl e filmar os efeitos. Neste, os participantes ingerem 12 a 14 comprimidos &#8211; seis vezes mais do que a dose recomendada &#8211; de modo a induzir alucina\u00e7\u00f5es.\u00a0<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>Jacob, natural do estado norte-americano do Ohio, perdeu a vida devido a uma overdose medicamentosa. Ao canal local ABC 6, a fam\u00edlia explicou que o menino ainda esteve no hospital ligado a um ventilador durante uma semana.<\/p>\n<p>Dianna Stevens, av\u00f3 de Jacob, disse querer revelar a hist\u00f3ria tr\u00e1gica do neto para que outras fam\u00edlias n\u00e3o tenham de passar pela mesma situa\u00e7\u00e3o: &#8220;Vou fazer tudo o que eu puder&#8221;, disse.\u00a0<\/p>\n<p>O menino estava em casa com amigos quando tudo aconteceu. De acordo com as informa\u00e7\u00f5es dispon\u00edveis, os menores estavam filmando a tentativa de Jacob de completar o desafio quando ele come\u00e7ou a sofrer espasmos.\u00a0<\/p>\n<p>Ao pai, Justin, os m\u00e9dicos afirmaram que o filho n\u00e3o voltaria a acordar. &#8220;Disseram que poder\u00edamos mant\u00ea-lo no ventilador, que ele iria apenas ficar ali, n\u00e3o iria respirar, sorrir, andar ou falar&#8221;. Agora, pede que plataformas como o TikTok tenham restri\u00e7\u00e3o de idade.\u00a0<\/p>\n<p>O funeral de Jason decorrer\u00e1 na pr\u00f3xima semana.\u00a0<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Mundo<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/mundo\/2010927\/benadryl-menino-de-13-anos-morre-ao-tentar-desafio-do-tiktok?utm_source=rss-mundo&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jacob Stevens, de 13 anos, morreu ap\u00f3s ter tentado completar um desafio viral da rede<\/p>\n","protected":false},"author":0,"featured_media":120262,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-120261","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/120261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=120261"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/120261\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/120262"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=120261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=120261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=120261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}