{"id":120255,"date":"2023-04-18T14:09:02","date_gmt":"2023-04-18T17:09:02","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/18\/daniel-alves-quer-ex-mulher-e-filhos-em-barcelona-como-estrategia-para-tentar-deixar-prisao\/"},"modified":"2023-04-18T14:09:02","modified_gmt":"2023-04-18T17:09:02","slug":"daniel-alves-quer-ex-mulher-e-filhos-em-barcelona-como-estrategia-para-tentar-deixar-prisao","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/18\/daniel-alves-quer-ex-mulher-e-filhos-em-barcelona-como-estrategia-para-tentar-deixar-prisao\/","title":{"rendered":"Daniel Alves quer ex-mulher e filhos em Barcelona como estrat\u00e9gia para tentar deixar pris\u00e3o"},"content":{"rendered":"<p>Preso desde o dia 20 de janeiro por suposta agress\u00e3o sexual contra uma jovem de 23 anos, Daniel Alves pretende levar os filhos e a ex-mulher Dinorah Santana para morar em Barcelona. A mudan\u00e7a faz parte de uma nova estrat\u00e9gia do jogador para responder \u00e0s acusa\u00e7\u00f5es em liberdade. A informa\u00e7\u00e3o \u00e9 do di\u00e1rio espanhol <i>As<\/i>.<\/p>\n<p>A defesa, encabe\u00e7ada por Crist\u00f3bal Martell, quer apresentar garantias \u00e0 Justi\u00e7a de que o jogador brasileiro possui la\u00e7os familiares na Espanha e que uma fuga est\u00e1 descartada. Tanto Dinorah quanto as crian\u00e7as j\u00e1 est\u00e3o a caminho do pa\u00eds europeu. A expectativa \u00e9 de que um novo pedido de liberdade seja pleiteado no Tribunal de Instru\u00e7\u00e3o n\u00ba 15 de Barcelona ainda nesta semana.<\/p>\n<\/p>\n<p>O fim do casamento com Joana Sanz, comunicado pela modelo e empres\u00e1ria por meio das redes sociais cerca de dois meses ap\u00f3s a pris\u00e3o do atleta, complicou a elabora\u00e7\u00e3o de um novo pedido de liberdade provis\u00f3ria por parte da defesa. Anteriormente, os advogados citaram a rela\u00e7\u00e3o de nove anos do ex-lateral da sele\u00e7\u00e3o brasileira com a espanhola como garantia de que o jogador n\u00e3o tinha a inten\u00e7\u00e3o de deixar o pa\u00eds.<\/p>\n<\/p>\n<p>&#8220;A quest\u00e3o das ra\u00edzes familiares. Quando Dani Alves foi preso, o Minist\u00e9rio P\u00fablico decretou a pris\u00e3o provis\u00f3ria do jogador. Argumentou ter ra\u00edzes familiares por ser casado com Joana Sanz. Isso ele colocou na mesa, mas n\u00e3o lhe adiantou muito. Joana Sanz anunciou que se estava a separar do futebolista, pelo que esse apego desapareceu&#8221;, diz a reportagem do <i>As<\/i>.<\/p>\n<\/p>\n<p>Dinorah Santana \u00e9 a primeira mulher de Daniel Alves e tamb\u00e9m atua como sua agente e s\u00f3cia nos neg\u00f3cios. Ela \u00e9 m\u00e3e de Daniel J\u00fanior e Vit\u00f3ria, de 15 e 16 anos, respectivamente. Os tr\u00eas estavam morando no Brasil. Os advogados j\u00e1 buscam saber qual ser\u00e1 o endere\u00e7o que a fam\u00edlia ir\u00e1 morar. A escola dos menores ser\u00e1 a Saint Peters, renomada institui\u00e7\u00e3o de ensino de Barcelona.<\/p>\n<\/p>\n<p>Daniel Alves dep\u00f4s na segunda-feira depois de pedir para ser novamente ouvido pela Justi\u00e7a espanhola. Em nova vers\u00e3o, o jogador brasileiro admite que houve penetra\u00e7\u00e3o sexual, mas afirma que o ato foi consentido pela v\u00edtima, cujo nome n\u00e3o foi revelado. Ele alegou ainda que mudou sua vers\u00e3o diversas vezes para tentar esconder a infidelidade de Joana Sanz.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Esporte<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/esporte\/2010851\/daniel-alves-quer-ex-mulher-e-filhos-em-barcelona-como-estrategia-para-tentar-deixar-prisao?utm_source=rss-esporte&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Preso desde o dia 20 de janeiro por suposta agress\u00e3o sexual contra uma jovem de<\/p>\n","protected":false},"author":0,"featured_media":120256,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-120255","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/120255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=120255"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/120255\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/120256"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=120255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=120255"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=120255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}