{"id":120245,"date":"2023-04-18T14:08:47","date_gmt":"2023-04-18T17:08:47","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/18\/receita-fara-leilao-com-quilos-de-ouro-e-diamantes-apreendidos-em-guarulhos\/"},"modified":"2023-04-18T14:08:47","modified_gmt":"2023-04-18T17:08:47","slug":"receita-fara-leilao-com-quilos-de-ouro-e-diamantes-apreendidos-em-guarulhos","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/18\/receita-fara-leilao-com-quilos-de-ouro-e-diamantes-apreendidos-em-guarulhos\/","title":{"rendered":"Receita far\u00e1 leil\u00e3o com quilos de ouro e diamantes apreendidos em Guarulhos"},"content":{"rendered":"<p>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; A Receita Federal recebe, at\u00e9 as 20h do dia 24 de abril, lances para joias apreendidas no aeroporto de Guarulhos, na Grande S\u00e3o Paulo. Correntes de ouro e pedras preciosas estar\u00e3o no leil\u00e3o, que receber\u00e1 propostas apenas de pessoas jur\u00eddicas.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>Os 14 lotes de joias n\u00e3o est\u00e3o dispon\u00edveis para visita por motivos de seguran\u00e7a, dado que as mercadorias s\u00e3o pequenas e t\u00eam alto valor agregado. De acordo com a Receita, a autenticidade das pedras e metais preciosos \u00e9 certificada por perito.<\/p>\n<p>O mais barato dos lotes aceita lance m\u00ednimo de R$ 60 mil e tem duas correntes de ouro puro -uma de 621,2 gramas e outra de 373,9 gramas. Segundo a cota\u00e7\u00e3o mais recente do ouro na B3, um grama do material vale R$ 314,99.<\/p>\n<p>Al\u00e9m de correntes de ouro, os volumes a serem leiloados cont\u00e9m diamantes n\u00e3o dilapidados, apatitas, rubelitas e esmeraldas.<\/p>\n<p>Os diamantes brutos integram conjunto com duas correntes de ouro que pesam juntas 1,43 quilograma, com lance inicial de R$ 100 mil.<\/p>\n<p>O lote com as apatitas, rubelitas e esmeraldas tem 1,74 quilograma de correntes de ouro, e aceita ofertas a partir de R$ 110 mil.<\/p>\n<p>H\u00e1 ainda outro conjunto com correntes e fivelas prateadas feitas com liga de 92,46% de ouro, 7,18% de prata e 0,36% de outros metais, com lance m\u00ednimo de R$ 80 mil. Esse lote pesa, no total, 1,46 quilograma.<\/p>\n<p>As mercadorias em leil\u00e3o foram apreendidas no setor de bagagens do aeroporto de Guarulhos, mas os detalhes da apreens\u00e3o s\u00e3o protegidos por sigilo fiscal.<\/p>\n<p>Pessoas jur\u00eddicas interessadas podem acessar o edital completo e ver os itens de cada um dos 14 lotes no Sistema Leil\u00e3o Eletr\u00f4nico da Receita. O leil\u00e3o est\u00e1 registrado sob o n\u00famero 0817600\/000002\/2023, e as ofertas devem ser registradas pela plataforma.<\/p>\n<p>As propostas mais altas ser\u00e3o anunciadas \u00e0s 10h do dia 25 de abril e estar\u00e3o classificadas para disputar o preg\u00e3o, com in\u00edcio marcado para 11h. Segundo a Receita, os resultados ser\u00e3o divulgados \u00e0s 12h do mesmo dia.<\/p>\n<p>Quem arrematar a mercadoria dever\u00e1 retir\u00e1-la no Armaz\u00e9m de Perdimento, localizado ao lado esquerdo do Terminal 1 do aeroporto de Guarulhos, na Rodovia H\u00e9lio Smidt.<\/p>\n<p><a href=\"https:\/\/www.noticiasaominuto.com.br\/economia\/2010808\/receita-fara-leilao-com-quilos-de-ouro-e-diamantes-apreendidos-em-guarulhos?utm_source=rss-economia&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><br \/>\nNot\u00edcias ao Minuto Brasil &#8211; Economia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; A Receita Federal recebe, at\u00e9 as 20h do dia 24<\/p>\n","protected":false},"author":0,"featured_media":120246,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-120245","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/120245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=120245"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/120245\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/120246"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=120245"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=120245"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=120245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}