{"id":120224,"date":"2023-04-18T10:19:00","date_gmt":"2023-04-18T13:19:00","guid":{"rendered":"http:\/\/roteironoticias.com.br\/?p=120224"},"modified":"2023-04-18T10:20:19","modified_gmt":"2023-04-18T13:20:19","slug":"bandidos-vem-tocando-o-terror-em-guaranta-do-norte","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/18\/bandidos-vem-tocando-o-terror-em-guaranta-do-norte\/","title":{"rendered":"Bandidos vem tocando o terror em Guarant\u00e3 do Norte"},"content":{"rendered":"\n<p>A popula\u00e7\u00e3o de Guarant\u00e3 do Norte\/MT est\u00e1 aterrorizada com a aud\u00e1cia dos bandidos, nos \u00faltimos dias vem acontecendo v\u00e1rios crimes na cidade, aonde os bandidos est\u00e3o usando de um certo grau de viol\u00eancia com as v\u00edtimas.<\/p>\n\n\n\n<p>Na tarde da segunda-feira (17\/04), dois mercados localizados no Bairro Cidade Nova, foram assaltados quase que ao mesmo tempo, em ambas as a\u00e7\u00f5es os bandidos levaram uma certa quantia em dinheiro e usaram de viol\u00eancia, al\u00e9m humilhar as v\u00edtimas durante o assalto.<\/p>\n\n\n\n<p>A policia ao realizar rondas no Bairro 13 de maio se deparou com tr\u00eas indiv\u00edduos em atitudes suspeitas, ao realizar uma abordagem nos mesmos, foi encontrado um rev\u00f3lver calibre 38, com quatro muni\u00e7\u00f5es intactas e uma quantia de R$442,00. Foi dado voz de pris\u00e3o para os tr\u00eas e conduzidos para a Delegacia Judiciaria de policia civil.<\/p>\n\n\n\n<p>Na noite do \u00faltimo s\u00e1bado (15\/04), um local que comercializa venda de espetinho, no Bairro cidade Nova, tr\u00eas indiv\u00edduos chegaram, um deles estava de posse de uma pistola e os outros dois portavam facas, anunciaram o assalto, aonde o propriet\u00e1rio teve de entregar todo o dinheiro que tinha, uma quantia de um mil reais.<\/p>\n\n\n\n<p>No domingo (16\/04), um homem teria feito o saque no caixa eletr\u00f4nico de uma cooperativa de credito e quando estava caminhando pela Rua Jacarand\u00e1s, no centro da cidade, dois indiv\u00edduos em uma motocicleta se aproximou e anunciou o assalto, a vitima teve de entregar cem reais e o seu celular.<\/p>\n\n\n\n<p>Nas redes sociais v\u00e1rias pessoas questionam, referente a seguran\u00e7a do munic\u00edpio, uma vez que, h\u00e1 policia Militar, Pol\u00edcia Civil, For\u00e7a T\u00e1tica, al\u00e9m da Policia Rodovi\u00e1ria Federal e nem assim intimida os bandidos.<\/p>\n\n\n\n<p>Por C\u00e9lio Ribeiro\/Roteiro Not\u00edcias<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/oterritorio.com.br\/wp-content\/uploads\/2023\/04\/20230417_213400-scaled.jpg\" alt=\"\"\/><\/figure>\n\n\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A popula\u00e7\u00e3o de Guarant\u00e3 do Norte\/MT est\u00e1 aterrorizada com a aud\u00e1cia dos bandidos, nos \u00faltimos<\/p>\n","protected":false},"author":2,"featured_media":120226,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,12],"tags":[],"class_list":["post-120224","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidades","category-justica"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/120224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=120224"}],"version-history":[{"count":1,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/120224\/revisions"}],"predecessor-version":[{"id":120225,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/120224\/revisions\/120225"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/120226"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=120224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=120224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=120224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}