{"id":120162,"date":"2023-04-17T23:08:20","date_gmt":"2023-04-18T02:08:20","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/17\/arcabouco-fiscal-deve-ser-entregue-ao-congresso-na-terca-com-mudancas\/"},"modified":"2023-04-17T23:08:20","modified_gmt":"2023-04-18T02:08:20","slug":"arcabouco-fiscal-deve-ser-entregue-ao-congresso-na-terca-com-mudancas","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/17\/arcabouco-fiscal-deve-ser-entregue-ao-congresso-na-terca-com-mudancas\/","title":{"rendered":"Arcabou\u00e7o fiscal deve ser entregue ao Congresso na ter\u00e7a com mudan\u00e7as"},"content":{"rendered":"<p>BRAS\u00cdLIA, DF (FOLHAPRESS) &#8211; O governo do presidente Luiz In\u00e1cio Lula da Silva (PT) deve entregar ao Congresso Nacional nesta ter\u00e7a-feira (18) a proposta de arcabou\u00e7o fiscal para substituir a regra do teto dos gastos. Ministros da \u00e1rea pol\u00edtica e econ\u00f4mica mostraram alinhamento no discurso a respeito da data.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>Antes do envio, a equipe econ\u00f4mica avaliou uma altera\u00e7\u00e3o no texto final do arcabou\u00e7o. Com o objetivo de mostrar desde o in\u00edcio maior compromisso com os par\u00e2metros da nova regra fiscal, o time envolvido na elabora\u00e7\u00e3o do projeto decidiu colocar tanto os conceitos do marco quanto os valores utilizados para os pr\u00f3ximos quatro anos na vers\u00e3o final da lei complementar.<\/p>\n<p>O texto deixa a possibilidade de mudan\u00e7a dos par\u00e2metros por meio de lei ordin\u00e1ria a partir do pr\u00f3ximo governo. A princ\u00edpio, a ideia era definir os conceitos do arcabou\u00e7o em lei complementar e os par\u00e2metros em lei ordin\u00e1ria.<\/p>\n<p>A regra prev\u00ea que a alta real da despesa, acima da infla\u00e7\u00e3o, ser\u00e1 equivalente a 70% da varia\u00e7\u00e3o das receitas -assegurados um piso de 0,6% e um teto de 2,5% de crescimento real dos gastos ao ano.<\/p>\n<p>A altera\u00e7\u00e3o pode, assim, facilitar mudan\u00e7as nas regras fiscais ap\u00f3s o fim do governo Lula. Isso porque a tramita\u00e7\u00e3o de um projeto de lei complementar exige um qu\u00f3rum especial, com a maioria absoluta dos deputados de cada Casa legislativa. Um projeto de lei ordin\u00e1ria, no entanto, demanda apenas a maioria dos parlamentares presentes na sess\u00e3o.<\/p>\n<p>Ao sair de uma reuni\u00e3o com Lula, no Pal\u00e1cio da Alvorada, na manh\u00e3 desta segunda-feira (17), o ministro Alexandre Padilha (Rela\u00e7\u00f5es Institucionais) afirmou que a proposta da equipe econ\u00f4mica deve ser entregue pelo mandat\u00e1rio diretamente nas m\u00e3os dos presidentes do Senado e da C\u00e2mara dos Deputados, respectivamente Rodrigo Pacheco (PSD-MG) e Arthur Lira (PP-AL).<\/p>\n<p>Lula vai realizar uma grande reuni\u00e3o no Planalto com ministros, governadores e chefes dos Poderes, para tratar de medidas para combater a viol\u00eancia nas escolas.<\/p>\n<p>&#8220;E tamb\u00e9m [temos] a expectativa de amanh\u00e3, no encontro que teremos sobre o tema das escolas, e a preocupa\u00e7\u00e3o do presidente Lula \u00e9 da defesa das escolas, da escola como espa\u00e7o de defesa da vida [&#8230;] convidou o presidente da C\u00e2mara, do Senado, dos poderes, e o presidente quer aproveitar esse momento [para apresentar o arcabou\u00e7o]&#8221;, afirmou Padilha.<\/p>\n<p>O titular das Rela\u00e7\u00f5es Institucionais afirmou esperar que a C\u00e2mara defina ainda nesta semana quem ser\u00e1 o relator da proposta durante a tramita\u00e7\u00e3o naquela Casa legislativa. Segundo Padilha, Lira teria afirmado que o marco fiscal poderia ser votado em 15 dias, mas ressaltou que a previs\u00e3o do governo \u00e9 que a medida possa ser aprovada, tanto na C\u00e2mara como no Senado, at\u00e9 o final do semestre.<\/p>\n<p>&#8220;Vai ter esse momento amanh\u00e3, tamb\u00e9m com o presidente da C\u00e2mara e do Senado, onde ele [Lula] deve junto com o ministro Haddad entregar a proposta, o texto do novo marco fiscal. A expectativa \u00e9 que, em sendo entregue amanh\u00e3, a C\u00e2mara possa definir o nome do relator para o marco fiscal para que a gente possa vot\u00e1-lo na velocidade e na urg\u00eancia que o pa\u00eds pede&#8221;, completou.<\/p>\n<p>Segundo o ministro Fernando Haddad (Fazenda), o encaminhamento &#8220;est\u00e1 dependendo da Casa Civil e de uma combina\u00e7\u00e3o com os presidentes das Casas&#8221;.<\/p>\n<p>&#8220;O presidente Arthur Lira n\u00e3o est\u00e1 em Bras\u00edlia hoje [segunda-feira], acho que [a entrega do arcabou\u00e7o fiscal ao Congresso] ficou para amanh\u00e3 [ter\u00e7a-feira]&#8221;, disse.<\/p>\n<p>Mais cedo, a ministra Simone Tebet (Planejamento) afirmou que assinou na manh\u00e3 desta segunda o texto do projeto de lei complementar do novo marco fiscal e enviou o documento para a Casa Civil.<\/p>\n<p>&#8220;Acabei de assinar [o texto] e, portanto, j\u00e1 encaminhamos para a Casa Civil neste momento por parte do Minist\u00e9rio do Planejamento e Or\u00e7amento dando o ok em rela\u00e7\u00e3o ao arcabou\u00e7o fiscal&#8221;, disse a chefe da pasta durante apresenta\u00e7\u00e3o do PLDO (Projeto de Lei de Diretrizes Or\u00e7ament\u00e1rias).<\/p>\n<p>Ela disse tamb\u00e9m que, de acordo com a Casa Civil, a expectativa \u00e9 que a nova regra fiscal seja encaminhada ao Congresso entre segunda e ter\u00e7a, mas que a decis\u00e3o caberia ao presidente Lula.<\/p>\n<p>&#8220;N\u00f3s acabamos de fechar o texto, eu assinei, acabou de chegar nesse momento na Casa Civil. Agora, vai ser apresentado ao presidente Lula. Ele vai assinar no tempo dele, n\u00e3o sei se hoje [segunda], amanh\u00e3 [ter\u00e7a] ou depois. \u00c9 uma decis\u00e3o pol\u00edtica. H\u00e1 uma expectativa de que ainda nesta semana, o mais r\u00e1pido poss\u00edvel dentro dessas pr\u00f3ximas horas, ele possa chegar ao Congresso Nacional&#8221;, afirmou Tebet.<\/p>\n<p>Mais cedo, o l\u00edder do governo na C\u00e2mara, Jos\u00e9 Guimar\u00e3es (PT-CE), tamb\u00e9m afirmou que o texto do arcabou\u00e7o fiscal dever\u00e1 ser entregue pelo Executivo ao Congresso Nacional nesta ter\u00e7a-feira (18).<\/p>\n<p>Em entrevista \u00e0 GloboNews, o parlamentar afirmou que o texto poder\u00e1 ser entregue ap\u00f3s reuni\u00e3o no Pal\u00e1cio do Planalto que dever\u00e1 contar com a presen\u00e7a de Lula, ministros e os presidentes da C\u00e2mara, Arthur Lira (PP-AL), e do Senado, Rodrigo Pacheco (PSD-MG).<\/p>\n<p>&#8220;Penso que ser\u00e1 o melhor momento para o ministro Haddad entregar formalmente o texto da nova pol\u00edtica fiscal do pa\u00eds&#8221;, disse.<\/p>\n<p>Guimar\u00e3es afirmou ainda que h\u00e1 um compromisso com Lira para votar o texto na Casa &#8220;com rapidez&#8221;. &#8220;Pela minha percep\u00e7\u00e3o, pelo ambiente pol\u00edtico que est\u00e1 posto, n\u00f3s votaremos esta mat\u00e9ria em 15, 20 dias para ela ir ao Senado.&#8221;<\/p>\n<p><a href=\"https:\/\/www.noticiasaominuto.com.br\/economia\/2010604\/arcabouco-fiscal-deve-ser-entregue-ao-congresso-na-terca-com-mudancas?utm_source=rss-economia&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><br \/>\nNot\u00edcias ao Minuto Brasil &#8211; Economia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BRAS\u00cdLIA, DF (FOLHAPRESS) &#8211; O governo do presidente Luiz In\u00e1cio Lula da Silva (PT) deve<\/p>\n","protected":false},"author":0,"featured_media":120163,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-120162","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/120162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=120162"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/120162\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/120163"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=120162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=120162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=120162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}