{"id":120154,"date":"2023-04-17T22:08:49","date_gmt":"2023-04-18T01:08:49","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/17\/ue-rebate-declaracoes-de-lula-e-nega-contribuir-para-prolongamento-da-guerra-na-ucrania\/"},"modified":"2023-04-17T22:08:49","modified_gmt":"2023-04-18T01:08:49","slug":"ue-rebate-declaracoes-de-lula-e-nega-contribuir-para-prolongamento-da-guerra-na-ucrania","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/17\/ue-rebate-declaracoes-de-lula-e-nega-contribuir-para-prolongamento-da-guerra-na-ucrania\/","title":{"rendered":"UE rebate declara\u00e7\u00f5es de Lula e nega contribuir para prolongamento da guerra na Ucr\u00e2nia"},"content":{"rendered":"<p>A Uni\u00e3o Europeia (UE) reagiu, nesta segunda-feira, 17, \u00e0s acusa\u00e7\u00f5es do presidente Luiz In\u00e1cio Lula da Silva (PT) de que Estados Unidos e Europa contribuiriam para o prolongamento da guerra na Ucr\u00e2nia. <\/p>\n<p>Em coletiva de imprensa, o porta-voz da Comiss\u00e3o Europeia, Peter Stano, negou que as a\u00e7\u00f5es do bloco tenham alimentado o conflito e enfatizou que a R\u00fassia \u00e9 a agressora neste caso. &#8220;O que estamos fazendo \u00e9 ajudar a Ucr\u00e2nia a exercer seu direito leg\u00edtimo de autodefesa&#8221;, afirmou. <\/p>\n<\/p>\n<p>Stano lembrou que o Brasil votou a favor da resolu\u00e7\u00e3o que condena a decis\u00e3o de Moscou de invadir o pa\u00eds vizinho e determina que o Kremlin retire todas as tropas do territ\u00f3rio ucraniano. &#8220;N\u00e3o \u00e9 verdade que os EUA e a UE estejam ajudando a prolongar o conflito. A verdade \u00e9 que a Ucr\u00e2nia \u00e9 v\u00edtima de uma agress\u00e3o ilegal que viola a Carta das Na\u00e7\u00f5es Unidas&#8221;, rebateu. <\/p>\n<\/p>\n<p>Em viagem aos Emirados \u00c1rabes Unidos, Lula voltou a criticar o presidente ucraniano, Volodymyr Zelensky, ontem e prop\u00f4s a cria\u00e7\u00e3o de um f\u00f3rum semelhante ao G20 que busque uma solu\u00e7\u00e3o pac\u00edfica no leste europeu. <\/p>\n<\/p>\n<p>Em resposta, o porta-voz da Comiss\u00e3o Europeia argumentou que a UE apoia iniciativas de paz desde antes da invas\u00e3o russa. Stano alega que o bloco ofereceu ao Kremlin diversas oportunidades para apresentar suas preocupa\u00e7\u00f5es &#8220;de maneira civilizada&#8221;. Segundo ele, todas as alternativas foram respondidas com uma escalada das hostilidades pelo presidente russo, Vladimir Putin.<\/p>\n<\/p>\n<p>&#8220;Claro que a UE apoia a paz o mais breve poss\u00edvel, mas n\u00e3o nos esque\u00e7amos de que a Ucr\u00e2nia \u00e9 que a v\u00edtima, ent\u00e3o \u00e9 a Ucr\u00e2nia que definir\u00e1 sob quais condi\u00e7\u00f5es poss\u00edveis conversas de paz come\u00e7ar\u00e3o&#8221;, ressaltou.<\/p>\n<\/p>\n<p>As declara\u00e7\u00f5es acontecem no mesmo dia em que o ministro das rela\u00e7\u00f5es exteriores da R\u00fassia, Sergey Lavrov, chegou ao Brasil para reuni\u00f5es com representantes do governo Lula. Ap\u00f3s encontro com o hom\u00f3logo brasileiro,  Mauro Vier, Lavrov disse que os dois pa\u00edses t\u00eam &#8220;vis\u00e3o similar&#8221; sobre a guerra na Ucr\u00e2nia.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Mundo<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/politica\/2010641\/ue-rebate-declaracoes-de-lula-e-nega-contribuir-para-prolongamento-da-guerra-na-ucrania?utm_source=rss-mundo&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Uni\u00e3o Europeia (UE) reagiu, nesta segunda-feira, 17, \u00e0s acusa\u00e7\u00f5es do presidente Luiz In\u00e1cio Lula<\/p>\n","protected":false},"author":0,"featured_media":120155,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-120154","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/120154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=120154"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/120154\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/120155"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=120154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=120154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=120154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}