{"id":120075,"date":"2023-04-17T14:52:30","date_gmt":"2023-04-17T17:52:30","guid":{"rendered":"http:\/\/roteironoticias.com.br\/?p=120075"},"modified":"2023-04-17T14:52:31","modified_gmt":"2023-04-17T17:52:31","slug":"mato-grosso-beneficiarias-do-bolsa-familia-tem-o-maior-valor-medio-na-regiao-centro-oeste","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/17\/mato-grosso-beneficiarias-do-bolsa-familia-tem-o-maior-valor-medio-na-regiao-centro-oeste\/","title":{"rendered":"Mato Grosso: benefici\u00e1rias do Bolsa Fam\u00edlia t\u00eam o maior valor m\u00e9dio na regi\u00e3o Centro-Oeste"},"content":{"rendered":"\n<p><em>Pagamento foram iniciados nesta sexta-feira (14\/4) e ser\u00e3o mais de 258 mil fam\u00edlias beneficiadas no estado, com valor m\u00e9dio de R$ 696,28. Repasse do Governo Federal \u00e9 de R$ 178,56 milh\u00f5es<\/em><\/p>\n\n\n\n<p>No Mato Grosso, as benefici\u00e1rias do Bolsa Fam\u00edlia em abril v\u00e3o contar com o maior valor m\u00e9dio do Centro-Oeste: R$ 696,28. Com os pagamentos iniciados nesta sexta-feira (14\/4), ser\u00e3o contempladas 258.304 fam\u00edlias nas 141 cidades mato-grossenses. Para tanto, o Governo Federal vai repassar mais de R$ 178,56 milh\u00f5es em recursos.<\/p>\n\n\n\n<p>No Mato Grosso, a capital Cuiab\u00e1 conta com mais fam\u00edlias benefici\u00e1rias. S\u00e3o 44.384 fam\u00edlias apoiadas, que recebem em abril um valor, em m\u00e9dia, de R$ 686,46, a partir do investimento federal de R$ 30,38 milh\u00f5es. Na sequ\u00eancia est\u00e3o V\u00e1rzea Grande (32.403), Rondon\u00f3polis (16.204), C\u00e1ceres (9.753) e Barra do Gar\u00e7as (6.953).<\/p>\n\n\n\n<p>O programa Bolsa Fam\u00edlia assegura um valor m\u00ednimo de R$ 600 por fam\u00edlia e conta com um adicional de R$ 150 do Benef\u00edcio Primeira Inf\u00e2ncia, destinado a cada crian\u00e7a de zero a seis anos na composi\u00e7\u00e3o familiar dos benefici\u00e1rios. Em todo o pa\u00eds, em abril, s\u00e3o 7,2 milh\u00f5es de fam\u00edlias com pelo menos uma crian\u00e7a nessa faixa et\u00e1ria. Em Mato Grosso, s\u00e3o 115.984 fam\u00edlias contempladas pelo Primeira Inf\u00e2ncia, a partir de um aporte de R$ 22,98 milh\u00f5es.<\/p>\n\n\n\n<p>O Centro-Oeste tem o maior t\u00edquete m\u00e9dio recebido por fam\u00edlia. S\u00e3o 1,1 milh\u00e3o de fam\u00edlias atendidas na regi\u00e3o, que recebem em m\u00e9dia R$ 689, a partir de um investimento federal de R$ 775 milh\u00f5es.<\/p>\n\n\n\n<p>Abril tamb\u00e9m \u00e9 marcado pelo pagamento do Aux\u00edlio G\u00e1s. O benef\u00edcio \u00e9 pago a cada dois meses e considera a m\u00e9dia do pre\u00e7o nacional do botij\u00e3o de 13kg do g\u00e1s de cozinha. O valor a ser repassado neste m\u00eas \u00e9 de R$ 110 por fam\u00edlia e, ao todo, 38.517 mil fam\u00edlias do Mato Grosso ser\u00e3o contempladas, a partir do repasse federal de R$ 4,23 milh\u00f5es.<\/p>\n\n\n\n<p><strong>PROGRAMA NACIONAL<\/strong> \u2013 Neste m\u00eas, 21,19 milh\u00f5es de fam\u00edlias ser\u00e3o beneficiadas pelo PBF, em todas as 5.570 cidades brasileiras. O total a ser transferido \u00e9 pr\u00f3ximo de R$ 14 bilh\u00f5es. O valor m\u00e9dio recebido por fam\u00edlia \u00e9 o maior j\u00e1 registrado na hist\u00f3ria do programa de transfer\u00eancia de renda do Governo Federal. O recorde anterior foi registrado no m\u00eas passado (R$ 670,33).<\/p>\n\n\n\n<p>Em rela\u00e7\u00e3o ao Benef\u00edcio Primeira Inf\u00e2ncia, 8,89 milh\u00f5es de crian\u00e7as de zero a seis anos ser\u00e3o assistidas em abril em todo o Brasil. O investimento para o pagamento desse benef\u00edcio \u00e9 de R$ 1,33 bilh\u00e3o. Neste m\u00eas, 7,21 milh\u00f5es de fam\u00edlias contam com pelo menos uma crian\u00e7a na faixa et\u00e1ria prevista para o pagamento.<\/p>\n\n\n\n<p><strong>CALEND\u00c1RIO<\/strong> \u2013 O calend\u00e1rio de repasses do programa \u00e9 feito de forma escalonada, a partir do final do N\u00famero de Identifica\u00e7\u00e3o Social (NIS) dos benefici\u00e1rios <em>(confira abaixo)<\/em>. Os primeiros que recebem s\u00e3o os benefici\u00e1rios com NIS de final 1, no dia 14. O cronograma de pagamentos segue at\u00e9 o dia 28 para benefici\u00e1rios com o NIS de final zero.<\/p>\n\n\n\n<p>Para munic\u00edpios em situa\u00e7\u00e3o de emerg\u00eancia ou calamidade p\u00fablica reconhecida, o Governo Federal unificou o pagamento do Bolsa Fam\u00edlia para o primeiro dia do calend\u00e1rio. Assim, na sexta-feira j\u00e1 foram contempladas as fam\u00edlias benefici\u00e1rias em locais atingidos pelas chuvas e inunda\u00e7\u00f5es no Acre, Amazonas, S\u00e3o Paulo, Esp\u00edrito Santo ou Maranh\u00e3o, por exemplo, bem como as afetadas pela estiagem no Rio Grande do Sul, al\u00e9m do povo Yanomami em Roraima.<\/p>\n\n\n\n<p><strong>REGI\u00d5ES<\/strong> \u2013 No recorte por regi\u00f5es brasileiras, o maior n\u00famero de benefici\u00e1rios se concentra nos nove estados do Nordeste, com 9,73 milh\u00f5es de fam\u00edlias contempladas, a partir de um investimento de R$ 6,34 bilh\u00f5es e benef\u00edcio m\u00e9dio de R$ 662,68.<\/p>\n\n\n\n<p>Na sequ\u00eancia aparece o Sudeste. Os quatro estados da regi\u00e3o somam 6,31 milh\u00f5es de fam\u00edlias benefici\u00e1rias, com um aporte federal de R$ 4,20 bilh\u00f5es e um benef\u00edcio m\u00e9dio de R$ 669,94. O Norte re\u00fane 2,59 milh\u00f5es de fam\u00edlias, com R$ 1,7 bilh\u00e3o em recursos transferidos e um valor m\u00e9dio recebido por fam\u00edlia de R$ 686,50.<\/p>\n\n\n\n<p>J\u00e1 os tr\u00eas estados do Sul contam com 1,42 milh\u00e3o de fam\u00edlias contempladas, a partir de um investimento de R$ 965 milh\u00f5es e benef\u00edcio m\u00e9dio de R$ 683,05. No Centro-Oeste est\u00e1 o maior valor m\u00e9dio recebido por fam\u00edlia. As 1,12 milh\u00e3o de fam\u00edlias atendidas na regi\u00e3o recebem m\u00e9dia de R$ 689,02, a partir de um investimento federal de R$ 775 milh\u00f5es.<\/p>\n\n\n\n<p><strong>ESTADOS<\/strong> \u2013 Na divis\u00e3o por Unidades da Federa\u00e7\u00e3o, S\u00e3o Paulo aparece em segundo lugar no ranking nacional em n\u00famero de fam\u00edlias atendidas, com 2,55 milh\u00f5es, um pouco abaixo dos 2,56 milh\u00f5es de contemplados na Bahia. O estado paulista, entretanto, contar\u00e1 com um investimento maior, de R$ 1,71 bilh\u00e3o, porque no estado h\u00e1 mais crian\u00e7as de zero a seis anos que recebem o Benef\u00edcio Primeira Inf\u00e2ncia.<\/p>\n\n\n\n<p>Outros seis estados re\u00fanem mais de um milh\u00e3o de fam\u00edlias contempladas em abril: Rio de Janeiro (1,83 milh\u00e3o), Pernambuco (1,67 milh\u00e3o), Minas Gerais (1,61 milh\u00e3o), Cear\u00e1 (1,49 milh\u00e3o), Par\u00e1 (1,35 milh\u00e3o) e Maranh\u00e3o (1,23 milh\u00e3o).<\/p>\n\n\n\n<p><strong>AUX\u00cdLIO G\u00c1S<\/strong> \u2013 Neste m\u00eas, 5,69 milh\u00f5es de fam\u00edlias em condi\u00e7\u00e3o de extrema vulnerabilidade receber\u00e3o o Aux\u00edlio G\u00e1s em todo o Brasil, a partir de um investimento do Governo Federal de R$ 626 milh\u00f5es. O calend\u00e1rio de repasses \u00e9 o mesmo do Bolsa Fam\u00edlia.<\/p>\n\n\n\n<p>A maior parte das fam\u00edlias atendidas pelo Aux\u00edlio G\u00e1s est\u00e1 no Nordeste. Para repassar o benef\u00edcio \u00e0s 2,72 milh\u00f5es de fam\u00edlias da regi\u00e3o, o Governo Federal investe quase R$ 300 milh\u00f5es. Em seguida aparece o Sudeste, com 1,85 milh\u00e3o de contemplados, resultado de um repasse de R$ 204 milh\u00f5es.<\/p>\n\n\n\n<p>Na regi\u00e3o Norte, o Aux\u00edlio G\u00e1s chega a 546 mil fam\u00edlias. Juntas, elas recebem R$ 60,11 milh\u00f5es. J\u00e1 no Sul, s\u00e3o 367 mil atendidos, a partir de um investimento de R$ 40,43 milh\u00f5es. Por fim, no Centro-Oeste h\u00e1 194 mil fam\u00edlias benefici\u00e1rias, com R$ 21,37 milh\u00f5es transferidos.<\/p>\n\n\n\n<p><em><span class=\"has-inline-color has-vivid-cyan-blue-color\">Da Assessoria\/Jessica Gomes<\/span><\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"http:\/\/roteironoticias.com.br\/wp-content\/uploads\/2023\/04\/Infografico_PBF-724x1024.jpg\" alt=\"\" class=\"wp-image-120077\" srcset=\"https:\/\/roteironoticias.com.br\/wp-content\/uploads\/2023\/04\/Infografico_PBF-724x1024.jpg 724w, https:\/\/roteironoticias.com.br\/wp-content\/uploads\/2023\/04\/Infografico_PBF-212x300.jpg 212w, https:\/\/roteironoticias.com.br\/wp-content\/uploads\/2023\/04\/Infografico_PBF-768x1086.jpg 768w, https:\/\/roteironoticias.com.br\/wp-content\/uploads\/2023\/04\/Infografico_PBF.jpg 1024w\" sizes=\"auto, (max-width: 724px) 100vw, 724px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Pagamento foram iniciados nesta sexta-feira (14\/4) e ser\u00e3o mais de 258 mil fam\u00edlias beneficiadas no<\/p>\n","protected":false},"author":2,"featured_media":120076,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-120075","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/120075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=120075"}],"version-history":[{"count":1,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/120075\/revisions"}],"predecessor-version":[{"id":120078,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/120075\/revisions\/120078"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/120076"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=120075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=120075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=120075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}