{"id":120053,"date":"2023-04-17T12:09:18","date_gmt":"2023-04-17T15:09:18","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/17\/blumenau-creche-atacada-reabre-apos-mutirao-de-reforma-de-pais-professores-e-voluntarios\/"},"modified":"2023-04-17T12:09:18","modified_gmt":"2023-04-17T15:09:18","slug":"blumenau-creche-atacada-reabre-apos-mutirao-de-reforma-de-pais-professores-e-voluntarios","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/17\/blumenau-creche-atacada-reabre-apos-mutirao-de-reforma-de-pais-professores-e-voluntarios\/","title":{"rendered":"Blumenau: creche atacada reabre ap\u00f3s mutir\u00e3o de reforma de pais, professores e volunt\u00e1rios"},"content":{"rendered":"<p>Desde quarta-feira, 12, quando completou uma semana do ataque \u00e0 creche Cantinho Bom Pastor em Blumenau, que deixou quatro crian\u00e7as mortas, pais e professores da escola est\u00e3o trabalhando para revitalizar o local, com reformas que aumentem a seguran\u00e7a e devolvam o local aconchegante e feliz onde as crian\u00e7as estudam.<\/p>\n<p>Os muros j\u00e1 foram aumentados e uma boa parte do espa\u00e7o da unidade de ensino j\u00e1 est\u00e1 com uma nova pintura. Os trabalhos v\u00e3o prosseguir, mesmo nesta segunda-feira, 17, quando as aulas ser\u00e3o retomadas na creche.<\/p>\n<\/p>\n<p>Conforme a assessora jur\u00eddica da institui\u00e7\u00e3o, Patr\u00edcia Kasburg, muitas pessoas est\u00e3o ajudando voluntariamente nas reformas, inclusive pais de crian\u00e7as que perderam a vida no ataque. &#8220;N\u00f3s fizemos um clamor \u00e0 comunidade para nos ajudar, e nossos primeiros apoiadores, os primeiros ajudantes, foram os pr\u00f3prios pais das crian\u00e7as que est\u00e3o aqui. Inclusive pais das fam\u00edlias enlutadas abriram seus cora\u00e7\u00f5es e vieram nos ajudar, fomentar ainda mais o apoio da comunidade&#8221;, disse.<\/p>\n<\/p>\n<p>Muitas doa\u00e7\u00f5es foram realizadas por empresas e pela comunidade em geral de Blumenau. O parque, onde o crime aconteceu, j\u00e1 foi desmontado, e nos pr\u00f3ximos dias come\u00e7ar\u00e1 a ser revitalizado com a ajuda, tamb\u00e9m, de uma empresa que ofereceu uma estrutura nova.<\/p>\n<\/p>\n<p>&#8220;Desde o primeiro dia que falamos da reforma do Cantinho, j\u00e1 recebemos materiais de constru\u00e7\u00e3o, materiais el\u00e9tricos, pintura, e a pr\u00f3pria m\u00e3o de obra que foi disponibilizada por uma empresa e por profissionais volunt\u00e1rios. J\u00e1 estamos em contato com uma empresa que nos procurou para revitalizar o parque por completo, ent\u00e3o tudo isso \u00e9 pra realmente mudar a cara da escola, para que as crian\u00e7as que voltarem aqui n\u00e3o tenham aquela imagem do momento&#8221;, explicou F\u00e1bio Rocha, pai de uma aluna de 6 anos que estuda na creche, e que coordena os trabalhos das obras no local.<\/p>\n<\/p>\n<p><b>Pais n\u00e3o pretendem tirar os filhos da escola<\/b><\/p>\n<\/p>\n<p>Conforme a diretora da CEI Cantinho Bom Pastor j\u00e1 havia confirmado na \u00faltima semana, as aulas na institui\u00e7\u00e3o retornam nessa segunda-feira, 17. A decis\u00e3o foi tomada porque muitos pais n\u00e3o querem tirar os filhos da creche e n\u00e3o t\u00eam onde deix\u00e1-los nesse per\u00edodo.<\/p>\n<\/p>\n<p>Durante os trabalhos do mutir\u00e3o, muitas crian\u00e7as est\u00e3o indo para a creche no intuito de ajudar a reconstruir o espa\u00e7o. Camila Pereira, m\u00e3e de uma aluna de 4 anos, conta que a filha vai empolgada para a escola nesse per\u00edodo em que as aulas n\u00e3o come\u00e7aram ainda. &#8220;Para estudar estamos vendo que ela est\u00e1 muito nervosa em ficar sem a gente. Mas ela pediu para vir ajudar a pintar, empolgada para reconstruir, pintar um lugar que ela vai sempre lembrar que ela quem fez aquela parte. Ent\u00e3o \u00e9 isso que ela est\u00e1 feliz, est\u00e1 ajudando a reconstruir a escola, fazer uma nova hist\u00f3ria&#8221;, relatou a m\u00e3e. &#8220;At\u00e9 sexta-feira, ela vinha, mas eu tinha de ficar toda hora por perto. Agora ela j\u00e1 est\u00e1 solta, viu o amiguinho, t\u00e1 empolgada que ela pintou. Ontem ela corria atr\u00e1s de mim, e hoje eu \u00e9 que estou correndo atr\u00e1s dela aqui na creche. \u00c9 um passo de cada vez, n\u00e3o queremos tirar ela da creche, mas por enquanto ela vir\u00e1 s\u00f3 meio per\u00edodo, para adaptar tudo de novo.&#8221;<\/p>\n<\/p>\n<p>Enquanto coordena as obras da escola, F\u00e1bio tamb\u00e9m pensa no espa\u00e7o que a filha de 6 anos encontra a partir desta segunda. &#8220;Nada melhor do que a minha filha voltar aqui com aquela vontade de estar aqui mesmo, com aquele brilho nos olhos de vir, correr, abra\u00e7ar as professoras. De na hora de eu vir buscar, ela falar \u0091Papai, mas voc\u00ea j\u00e1 veio me buscar? Eu queria ficar mais um pouco\u0092. E \u00e9 isso que a gente gosta daqui: \u00e9 uma fam\u00edlia mesmo.&#8221;<\/p>\n<\/p>\n<p><b>Creche pede por ajuda para finalizar os trabalhos<\/b><\/p>\n<\/p>\n<p>Embora muitas pessoas j\u00e1 estejam ajudando a CEI Cantinho Bom Pastor, a institui\u00e7\u00e3o ainda precisa de mais apoio para finalizar os trabalhos enquanto as crian\u00e7as retornam \u00e0s aulas. &#8220;Desde apoio financeiro para fazermos todas as mudan\u00e7as, at\u00e9 o apoio da comunidade e de empres\u00e1rios, que possam nos fornecer alguns materiais que ainda faltam. Precisamos urgente de um port\u00e3o, de um contrapiso, que estamos buscando conseguir&#8221;, explicou Patr\u00edcia, assessora jur\u00eddica da creche.<\/p>\n<\/p>\n<p>As doa\u00e7\u00f5es podem ser feitas diretamente na creche ou pelo PIX feito exclusivamente para essas reformas, apoiocantinho@gmail.com. O contato para mais informa\u00e7\u00f5es pode ser feito com Patr\u00edcia Kasburg, pelo (47) 99183-2491.<\/p>\n<\/p>\n<p>&#8220;Os pais est\u00e3o aqui com a m\u00e3o na massa. Mesmo tendo de trabalhar durante a semana, eles est\u00e3o aqui dando apoio. E \u00e9 isso que motiva mais ainda a fazer a diferen\u00e7a. \u00c9 uma corrente do bem&#8221;, disse Patr\u00edcia. A creche tem 14 anos de atividades, e est\u00e1 com cerca de 220 crian\u00e7as matriculadas, que t\u00eam direito a 5 refei\u00e7\u00f5es por dia dentro da escola e participam de diversas atividades em per\u00edodo integral.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Brasil<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/ultima-hora\/2010469\/blumenau-creche-atacada-reabre-apos-mutirao-de-reforma-de-pais-professores-e-voluntarios?utm_source=rss-brasil&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde quarta-feira, 12, quando completou uma semana do ataque \u00e0 creche Cantinho Bom Pastor em<\/p>\n","protected":false},"author":0,"featured_media":120054,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-120053","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/120053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=120053"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/120053\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/120054"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=120053"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=120053"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=120053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}