{"id":120051,"date":"2023-04-17T12:09:18","date_gmt":"2023-04-17T15:09:18","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/17\/colisao-entre-moto-e-onibus-deixa-tres-mortos-na-zona-sul-de-sp\/"},"modified":"2023-04-17T12:09:18","modified_gmt":"2023-04-17T15:09:18","slug":"colisao-entre-moto-e-onibus-deixa-tres-mortos-na-zona-sul-de-sp","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/17\/colisao-entre-moto-e-onibus-deixa-tres-mortos-na-zona-sul-de-sp\/","title":{"rendered":"Colis\u00e3o entre moto e \u00f4nibus deixa tr\u00eas mortos na zona sul de SP"},"content":{"rendered":"<p>(FOLHAPRESS) &#8211; Um acidente envolvendo uma motocicleta e um \u00f4nibus deixou tr\u00eas pessoas mortas na manh\u00e3 desta segunda-feira (17) em S\u00e3o Paulo.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>Segundo o Corpo de Bombeiros, que atendeu a ocorr\u00eancia, as tr\u00eas v\u00edtimas estavam na mesma motocicleta.<\/p>\n<p>O acidente ocorreu \u00e0s 5h10, na estrada do Campo Limpo, em frente ao Terminal Campo Limpo, na zona sul.<\/p>\n<p>As causas do acidente ainda s\u00e3o investigadas. A motocicleta era ocupada por um homem e duas mulheres, todos adultos.<\/p>\n<p>De acordo com o bombeiros, o homem morreu ainda no local, enquanto as mulheres foram socorridas, mas n\u00e3o resistiram aos ferimentos.<\/p>\n<p>A SPTrans afirmou que determinou \u00e0 concession\u00e1ria Transwolff que preste o apoio necess\u00e1rio \u00e0s fam\u00edlias das v\u00edtimas. O Programa de Redu\u00e7\u00e3o de Acidentes em Transportes, disse, est\u00e1 apurando a ocorr\u00eancia envolvendo o \u00f4nibus de prefixo 78616, da linha 7054\/10 Jd. Maced\u00f4nia &#8211; Term. Campo Limpo.<\/p>\n<p>Conforme a Folha publicou no \u00faltimo dia 21, a cidade de S\u00e3o Paulo registrou 66 mortes no tr\u00e2nsito em fevereiro deste ano, o maior n\u00famero de v\u00edtimas para o m\u00eas desde 2018. Em rela\u00e7\u00e3o ao mesmo m\u00eas em 2022, o aumento \u00e9 de 53%.<\/p>\n<p>Embora tenha ficado est\u00e1vel o n\u00famero de mortes de motociclistas, que historicamente s\u00e3o as mais numerosas, houve um aumento de v\u00edtimas entre pedestres e entre os motoristas e passageiros de carros.<\/p>\n<p>As motocicletas continuam sendo o meio de transporte mais perigoso na cidade. Em janeiro e fevereiro, 46 motociclistas e passageiros morreram no tr\u00e2nsito da capital -mesma quantidade de mortes no mesmo per\u00edodo do ano passado.<\/p>\n<p>A redu\u00e7\u00e3o do n\u00famero de mortes envolvendo motos \u00e9 uma das prioridades de Ricardo Nunes (MDB). A gest\u00e3o municipal implementou, de forma experimental, as faixas azuis para motociclistas. Ap\u00f3s completar um ano sem mortes, Nunes planeja implantar mais 220 quil\u00f4metros dessas faixas na cidade e a gest\u00e3o estuda criar pistas segregadas para motociclistas nas marginais Tiet\u00ea e Pinheiros.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Brasil<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/brasil\/2010481\/colisao-entre-moto-e-onibus-deixa-tres-mortos-na-zona-sul-de-sp?utm_source=rss-brasil&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(FOLHAPRESS) &#8211; Um acidente envolvendo uma motocicleta e um \u00f4nibus deixou tr\u00eas pessoas mortas na<\/p>\n","protected":false},"author":0,"featured_media":120052,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-120051","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/120051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=120051"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/120051\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/120052"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=120051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=120051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=120051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}