{"id":120045,"date":"2023-04-17T12:09:12","date_gmt":"2023-04-17T15:09:12","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/17\/um-milagre-foi-dado-como-morto-mas-duas-horas-depois-estava-vivo\/"},"modified":"2023-04-17T12:09:12","modified_gmt":"2023-04-17T15:09:12","slug":"um-milagre-foi-dado-como-morto-mas-duas-horas-depois-estava-vivo","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/17\/um-milagre-foi-dado-como-morto-mas-duas-horas-depois-estava-vivo\/","title":{"rendered":"&quot;Um milagre&quot;. Foi dado como morto&#8230; mas duas horas depois estava vivo"},"content":{"rendered":"<p>Sammy Berko, um adolescente da cidade de Missouri, no Texas, Estados Unidos, foi a uma academia de escalada e, enquanto praticava o esporte, sofreu uma parada cardiorrespirat\u00f3ria e morreu. Duas horas depois, ele estava vivo.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>De acordo com sua m\u00e3e, Jennifer Berko, em entrevista \u00e0 Fox 26 no domingo, Sammy &#8220;subiu at\u00e9 o topo da parede, tocou a campainha, como nos disseram, e ent\u00e3o seu corpo ficou mole, e parecia que estava brincando ou tinha desmaiado. Quando perceberam que ele n\u00e3o estava respondendo, o baixaram lentamente&#8221;.<\/p>\n<p>Quando os servi\u00e7os de emerg\u00eancia chegaram, foi realizada uma ressuscita\u00e7\u00e3o cardiopulmonar (RCP) por duas horas antes de informarem Jennifer que ele tinha falecido. Ela e seu marido, Craig, sentaram-se com o filho por alguns minutos para se despedirem.<\/p>\n<p>&#8220;Comecei a falar com ele, apenas dizendo o quanto o amo e lamentando que n\u00e3o soub\u00e9ssemos como salv\u00e1-lo&#8221;, disse a m\u00e3e, acrescentando que, de repente, quando come\u00e7ou a rezar, o marido disse: &#8216;Oh meu Deus, ele est\u00e1 se mexendo'&#8221;. O casal gritou para a equipe m\u00e9dica, que voltou correndo e reiniciou o processo.<\/p>\n<p>Devido ao tempo que Sammy ficou sem oxig\u00eanio, os m\u00e9dicos temiam que ele tivesse sofrido uma les\u00e3o cerebral grave. No entanto, al\u00e9m de algumas les\u00f5es f\u00edsicas, Sammy s\u00f3 teve perda moment\u00e2nea de mem\u00f3ria.<\/p>\n<p>&#8220;N\u00e3o me lembro de nada sobre o dia em que isso aconteceu. A \u00faltima coisa de que me lembro \u00e9 da noite antes de assinarmos os termos de responsabilidade (para a academia de escalada), e ent\u00e3o acordei&#8221;, disse Sammy \u00e0 Fox 26.<\/p>\n<p>Apesar da sorte que Sammy teve, n\u00e3o significa que o caminho para a recupera\u00e7\u00e3o tenha sido f\u00e1cil. Sammy tem trabalhado para recuperar a for\u00e7a nas pernas ap\u00f3s um m\u00eas no hospital e est\u00e1 fazendo fisioterapia para a les\u00e3o isqu\u00eamica na coluna vertebral.<\/p>\n<p>&#8220;Eu sabia que seria uma experi\u00eancia estranha e louca aprender a andar novamente e trabalhar na for\u00e7a sem usar minhas pernas para me equilibrar. Na verdade, tem sido uma experi\u00eancia incr\u00edvel aqui, como se eu tivesse percebido que estou melhorando a cada dia! Estou fazendo algo novo todos os dias&#8221;, disse o jovem.<\/p>\n<p>&#8220;Fiquei muito impressionado com a hist\u00f3ria dele. \u00c9 muito emocionante e muito incomum. \u00c9 aquele \u00fanico jovem que voc\u00ea conhece que teve essa taquicardia ventricular polim\u00f3rfica catecolamin\u00e9rgica (CPVT), que \u00e9 um dist\u00farbio gen\u00e9tico extremamente raro que afeta o cora\u00e7\u00e3o&#8221;, afirmou o Dr. Stacey Hall.<\/p>\n<p>O diretor m\u00e9dico do Programa de Reabilita\u00e7\u00e3o Pedi\u00e1trica que acompanha Sammy disse \u00e0 mesma emissora de televis\u00e3o que v\u00ea &#8220;crian\u00e7as todos os dias que passaram por RCP, mas com RCP prolongada normalmente vemos les\u00f5es cerebrais graves, ent\u00e3o, para mim, ele \u00e9 um milagre&#8221;.<br \/>\u00a0<a href=\"https:\/\/www.noticiasaominuto.com\/pais\/2298773\/suspeito-da-morte-de-jovem-em-almada-ainda-nao-foi-identificado\" target=\"_blank\" rel=\"noopener noreferrer\"><\/a><\/p>\n<p>Leia Tamb\u00e9m: <a href=\"https:\/\/www.noticiasaominuto.com.br\/celebridades\/2010290\/preta-gil-teve-choque-septico-durante-tratamento-de-cancer-grande-susto\" target=\"_blank\" rel=\"noopener noreferrer\">Preta Gil teve choque s\u00e9ptico durante tratamento de c\u00e2ncer: &#8216;Grande susto&#8217;<\/a><\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Mundo<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/mundo\/2010394\/um-milagre-foi-dado-como-morto-mas-duas-horas-depois-estava-vivo?utm_source=rss-mundo&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sammy Berko, um adolescente da cidade de Missouri, no Texas, Estados Unidos, foi a uma<\/p>\n","protected":false},"author":0,"featured_media":120046,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-120045","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/120045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=120045"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/120045\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/120046"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=120045"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=120045"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=120045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}