{"id":119988,"date":"2023-04-17T09:08:57","date_gmt":"2023-04-17T12:08:57","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/17\/roy-keane-critica-maguire-e-lindelof-nao-deviam-estar-aqui\/"},"modified":"2023-04-17T09:08:57","modified_gmt":"2023-04-17T12:08:57","slug":"roy-keane-critica-maguire-e-lindelof-nao-deviam-estar-aqui","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/17\/roy-keane-critica-maguire-e-lindelof-nao-deviam-estar-aqui\/","title":{"rendered":"Roy Keane critica Maguire e Lindelof: &quot;N\u00e3o deviam estar aqui&#8230;&quot;"},"content":{"rendered":"<p>Roy Keane acredita que Victor Lindelof e Harry Maguire n\u00e3o deveriam estar no Manchester United, uma vez que n\u00e3o justificam as oportunidades que t\u00eam com Erik ten Hag. Em entrevista \u00e0 Sky Sports, o ex-jogador do Manchester United criticou a dupla que jogou contra o Nottingham Forest (2-0) no domingo.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>&#8220;Esses dois n\u00e3o s\u00e3o titulares, mas est\u00e3o no Manchester United porque, quando h\u00e1 uma oportunidade, \u00e9 preciso aproveit\u00e1-la. S\u00e3o jogadores internacionais e experientes, ent\u00e3o quando enfrentam uma equipe como o Forest, que est\u00e1 em dificuldades, espera-se que deem conta do recado&#8221;, come\u00e7ou Keane, continuando.<\/p>\n<p>&#8220;Claro, ambos precisam dos jogadores \u00e0 frente deles para dar alguma prote\u00e7\u00e3o, mas Maguire e Lindelof est\u00e3o jogando pelo Manchester United por alguma raz\u00e3o. Esperamos que possam lidar com o ataque do Forest. Caso contr\u00e1rio, n\u00e3o deveriam estar aqui, neste clube&#8221;, concluiu o ex-meio-campista gal\u00eas do Manchester United.<\/p>\n<p>Leia Tamb\u00e9m: <a href=\"https:\/\/www.noticiasaominuto.com.br\/esporte\/2010346\/ex-piloto-de-formula-1-e-assaltado-e-espancado\" target=\"_blank\" rel=\"noopener noreferrer\">Ex-piloto de F\u00f3rmula 1 \u00e9 assaltado e espancado<\/a><\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Esporte<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/esporte\/2010365\/roy-keane-critica-maguire-e-lindelof-nao-deviam-estar-aqui?utm_source=rss-esporte&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Roy Keane acredita que Victor Lindelof e Harry Maguire n\u00e3o deveriam estar no Manchester United,<\/p>\n","protected":false},"author":0,"featured_media":119989,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-119988","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/119988","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=119988"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/119988\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/119989"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=119988"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=119988"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=119988"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}