{"id":119959,"date":"2023-04-17T07:08:31","date_gmt":"2023-04-17T10:08:31","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/17\/inter-ja-decidiu-lukaku-e-para-despachar-no-final-da-temporada\/"},"modified":"2023-04-17T07:08:31","modified_gmt":"2023-04-17T10:08:31","slug":"inter-ja-decidiu-lukaku-e-para-despachar-no-final-da-temporada","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/17\/inter-ja-decidiu-lukaku-e-para-despachar-no-final-da-temporada\/","title":{"rendered":"Inter j\u00e1 decidiu: Lukaku \u00e9 para &#8216;despachar&#8217; no final da temporada"},"content":{"rendered":"<p>Romelu Lukaku pode estar de sa\u00edda do Inter ao final da temporada, de acordo com informa\u00e7\u00f5es da Gazzetta dello Sport.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>O clube italiano teria decidido n\u00e3o investir na compra definitiva do passe do jogador belga, que at\u00e9 o momento marcou apenas sete gols em 24 jogos disputados. Lukaku foi contratado pelo Inter por 20 milh\u00f5es de euros no \u00faltimo ver\u00e3o, mas seu desempenho n\u00e3o tem sido considerado um sucesso.<\/p>\n<p>Um dos gols de Lukaku foi marcado na recente visita do Inter ao Benfica, em jogo da primeira m\u00e3o dos quartos de final da Liga dos Campe\u00f5es.<\/p>\n<p>Leia Tamb\u00e9m: <a href=\"https:\/\/www.noticiasaominuto.com.br\/esporte\/2010194\/santos-fecha-patrocinio-master-com-plataforma-de-apostas-que-tem-neymar-como-embaixador\" target=\"_blank\" rel=\"noopener noreferrer\">Santos fecha patroc\u00ednio master com plataforma de apostas que tem Neymar como embaixador<\/a><\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Esporte<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/esporte\/2010333\/inter-ja-decidiu-lukaku-e-para-despachar-no-final-da-temporada?utm_source=rss-esporte&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Romelu Lukaku pode estar de sa\u00edda do Inter ao final da temporada, de acordo com<\/p>\n","protected":false},"author":0,"featured_media":119960,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-119959","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/119959","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=119959"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/119959\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/119960"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=119959"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=119959"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=119959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}