{"id":119917,"date":"2023-04-16T20:08:25","date_gmt":"2023-04-16T23:08:25","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/16\/policia-prende-homem-em-santa-catarina-apos-encontrar-supermaconha-em-estufas\/"},"modified":"2023-04-16T20:08:25","modified_gmt":"2023-04-16T23:08:25","slug":"policia-prende-homem-em-santa-catarina-apos-encontrar-supermaconha-em-estufas","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/16\/policia-prende-homem-em-santa-catarina-apos-encontrar-supermaconha-em-estufas\/","title":{"rendered":"Pol\u00edcia prende homem em Santa Catarina ap\u00f3s encontrar supermaconha em estufas"},"content":{"rendered":"<p>LEONARDO VIECELI<br \/>RIO DE JANEIRO, RJ (FOLHAPRESS) &#8211; Uma opera\u00e7\u00e3o da Pol\u00edcia Civil de Santa Catarina apreendeu na sexta-feira (14) 60 p\u00e9s da droga conhecida como supermaconha. As plantas estavam em estufas no munic\u00edpio de Itaja\u00ed (a 102 km de Florian\u00f3polis).<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>Um homem foi preso sob suspeita de cultivar e vender a supermaconha, termo usado popularmente para descrever a variedade skunk (ou skank). Por ser mais forte do que a maconha comum, ela costuma ter um valor mais elevado no mercado de entorpecentes.<\/p>\n<p>De acordo com a Pol\u00edcia Civil, a investiga\u00e7\u00e3o que resultou na pris\u00e3o em Itaja\u00ed teve in\u00edcio em fevereiro, ap\u00f3s an\u00e1lise do &#8220;fluxo financeiro&#8221; do suspeito.<\/p>\n<p>&#8220;Os investigadores do SIC [Setor de Investiga\u00e7\u00e3o Criminal] de Itaja\u00ed passaram a monitorar o alvo e em a\u00e7\u00e3o conjunta identificaram dois im\u00f3veis que estariam sendo utilizados para o cultivo e a venda de skank&#8221;, diz a pol\u00edcia.<\/p>\n<p>As buscas nesta sexta ocorreram nos bairros S\u00e3o Judas e S\u00e3o Vicente. Al\u00e9m da supermaconha, a opera\u00e7\u00e3o tamb\u00e9m apreendeu aparelhos celulares, um ve\u00edculo de luxo e uma motocicleta de alta cilindrada.<\/p>\n<p>O investigado foi levado, inicialmente, para a DIC [Divis\u00e3o de Investiga\u00e7\u00e3o Criminal] de Itaja\u00ed. Depois, o homem foi encaminhado para o Complexo Penitenci\u00e1rio do Vale do Itaja\u00ed. Ele n\u00e3o teve o nome divulgado.<\/p>\n<p>A pol\u00edcia afirma que, segundo estudos, a variedade skunk tem um \u00edndice de THC (tetrahidrocanabinol) sete vezes maior do que a maconha comum. &#8220;A porcentagem chega at\u00e9 17,5%, sendo que na maconha \u00e9 de 2,5%&#8221;, diz a pol\u00edcia.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Brasil<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/brasil\/2010101\/policia-prende-homem-em-santa-catarina-apos-encontrar-supermaconha-em-estufas?utm_source=rss-brasil&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>LEONARDO VIECELIRIO DE JANEIRO, RJ (FOLHAPRESS) &#8211; Uma opera\u00e7\u00e3o da Pol\u00edcia Civil de Santa Catarina<\/p>\n","protected":false},"author":0,"featured_media":119918,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-119917","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/119917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=119917"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/119917\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/119918"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=119917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=119917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=119917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}