{"id":119915,"date":"2023-04-16T20:08:24","date_gmt":"2023-04-16T23:08:24","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/16\/vaquinha-para-entregador-agredido-no-rio-comprar-casa-ultrapassa-r-100-mil\/"},"modified":"2023-04-16T20:08:24","modified_gmt":"2023-04-16T23:08:24","slug":"vaquinha-para-entregador-agredido-no-rio-comprar-casa-ultrapassa-r-100-mil","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/16\/vaquinha-para-entregador-agredido-no-rio-comprar-casa-ultrapassa-r-100-mil\/","title":{"rendered":"Vaquinha para entregador agredido no Rio comprar casa ultrapassa R$ 100 mil"},"content":{"rendered":"<p>S\u00c3O PAULO, SP (UOL\/FOLHAPRESS) &#8211; Uma vaquinha criada para Max \u00c2ngelo dos Santos, entregador agredido na Zona Sul do Rio na semana passada pela ex-atleta de v\u00f4lei e nutricionista Sandra Mathias Correia de S\u00e1, j\u00e1 ultrapassou R$ 100 mil.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>A arrecada\u00e7\u00e3o de dinheiro \u00e9 para Max conseguir uma casa pr\u00f3pria e tirar habilita\u00e7\u00e3o de moto. Ele \u00e9 pai de tr\u00eas crian\u00e7as e chega a pedalar at\u00e9 18h por dia, segundo contou ao UOL, desde que perdeu o trabalho com carteira assinada.<\/p>\n<p>A meta da vaquinha \u00e9 de R$ 190 mil. At\u00e9 a \u00faltima atualiza\u00e7\u00e3o desta reportagem, cerca de R$ 134 mil j\u00e1 havia sido arrecadado. A vaquinha tem dura\u00e7\u00e3o de mais 30 dias.<\/p>\n<p>As formas de ajudar s\u00e3o por divulga\u00e7\u00e3o (h\u00e1 um link de compartilhamento na p\u00e1gina da vaquinha de Max) e doa\u00e7\u00e3o -no Pix, \u00e9 poss\u00edvel contribuir com qualquer valor.<\/p>\n<p>Max foi agredido no \u00faltimo domingo (9) pela ex-atleta de v\u00f4lei e nutricionista Sandra Mathias Correia de S\u00e1. Imagens mostram a nutricionista batendo e xingando entregadores, que estavam na cal\u00e7ada da loja em que trabalham.<\/p>\n<p>Ap\u00f3s puxar a camisa e dar socos em Max, Sandra pegou a guia da coleira do cachorro e deu uma chicotada nas costas dele.<br \/>O caso est\u00e1 sendo investigado pela 15\u00aa DP (G\u00e1vea). Sandra Mathias foi intimada a depor na pol\u00edcia ontem. No entanto, ela n\u00e3o compareceu. O advogado de defesa justificou que a ex-atleta tem um atestado m\u00e9dico v\u00e1lido at\u00e9 amanh\u00e3 (16).<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Brasil<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/brasil\/2010110\/vaquinha-para-entregador-agredido-no-rio-comprar-casa-ultrapassa-r-100-mil?utm_source=rss-brasil&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00c3O PAULO, SP (UOL\/FOLHAPRESS) &#8211; Uma vaquinha criada para Max \u00c2ngelo dos Santos, entregador agredido<\/p>\n","protected":false},"author":0,"featured_media":119916,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-119915","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/119915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=119915"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/119915\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/119916"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=119915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=119915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=119915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}