{"id":119839,"date":"2023-04-16T10:08:23","date_gmt":"2023-04-16T13:08:23","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/16\/camila-cabello-confirma-volta-do-relacionamento-com-shawn-mendes\/"},"modified":"2023-04-16T10:08:23","modified_gmt":"2023-04-16T13:08:23","slug":"camila-cabello-confirma-volta-do-relacionamento-com-shawn-mendes","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/16\/camila-cabello-confirma-volta-do-relacionamento-com-shawn-mendes\/","title":{"rendered":"Camila Cabello confirma volta do relacionamento com Shawn Mendes"},"content":{"rendered":"<p>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; Os ex-namorados Shawn Mendes e Camila Cabello parecem n\u00e3o ser mais t\u00e3o &#8220;ex&#8221; assim. Durante a primeira noite do Coachella, nesta sexta (14), a cantora de &#8220;Havana&#8221; e o cantor canadense foram flagrados trocando car\u00edcias e beijos enquanto assistiam a uma apresenta\u00e7\u00e3o juntos. Se s\u00f3 isso n\u00e3o era suficiente, h\u00e1 registros de Cabello confirmando o retorno do casal.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>No v\u00eddeo filmado durante os shows, os dois sorriem um para o outro antes de darem um beijo caloroso, pr\u00f3ximos a outras pessoas na multid\u00e3o. Em outros momentos da noite, o at\u00e9 ent\u00e3o ex-casal \u2013que se separou em novembro de 2021\u2013 conversou e bebeu com amigos.<\/p>\n<p>Em um v\u00eddeo que parece ter sido gravado no final do festival, quando Cabello e Mendes estavam entrando em um carro para ir embora, a cantora est\u00e1 acompanhada de amigas quando um rep\u00f3rter questiona: &#8220;Voc\u00eas est\u00e3o juntos de novo?&#8221;. Ela responde que sim.<\/p>\n<p>O reencontro deles ocorreu mais de um ano depois que eles divulgaram um comunicado conjunto anunciando o t\u00e9rmino do relacionamento ap\u00f3s mais de dois anos juntos. A separa\u00e7\u00e3o foi uma surpresa para os f\u00e3s.<\/p>\n<p>Embora n\u00e3o tenham divulgado muitos detalhes sobre seu romance, no ano passado, Cabello foi sincera sobre como suas prioridades &#8220;mudaram&#8221; durante o relacionamento. &#8220;Come\u00e7amos t\u00e3o jovens tamb\u00e9m&#8221;, disse a ex-cantora do Fifth Harmony em uma entrevista. &#8220;\u00c9 como se estiv\u00e9ssemos aprendendo a ser adultos saud\u00e1veis de verdade. Minhas prioridades mudaram e meu foco mudou ao longo da minha vida.&#8221;<\/p>\n<p>Ap\u00f3s a separa\u00e7\u00e3o, Mendes foi ligado a v\u00e1rias mulheres, incluindo sua quiroprata de 51 anos, Dra. Jocelyne Miranda. Tamb\u00e9m houve especula\u00e7\u00f5es de que o pop star canadense estava tendo um romance com Sabrina Carpenter, mas ele negou os rumores.<\/p>\n<p>Cabello, por sua vez, namorou o CEO do aplicativo de relacionamento Lox Club, Austin Kevitch, ap\u00f3s o t\u00e9rmino com Mendes. Eles foram vistos juntos pela primeira vez em junho de 2022, mas o romance acabou oito meses depois.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Fama<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/celebridades\/2010126\/camila-cabello-confirma-volta-do-relacionamento-com-shawn-mendes?utm_source=rss-fama&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; Os ex-namorados Shawn Mendes e Camila Cabello parecem n\u00e3o ser<\/p>\n","protected":false},"author":0,"featured_media":119840,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-119839","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fama-e-tv"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/119839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=119839"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/119839\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/119840"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=119839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=119839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=119839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}