{"id":119821,"date":"2023-04-16T08:08:37","date_gmt":"2023-04-16T11:08:37","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/16\/familia-de-marilia-mendonca-vai-entrar-com-acao-contra-facebook-e-google\/"},"modified":"2023-04-16T08:08:37","modified_gmt":"2023-04-16T11:08:37","slug":"familia-de-marilia-mendonca-vai-entrar-com-acao-contra-facebook-e-google","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/16\/familia-de-marilia-mendonca-vai-entrar-com-acao-contra-facebook-e-google\/","title":{"rendered":"Fam\u00edlia de Mar\u00edlia Mendon\u00e7a vai entrar com a\u00e7\u00e3o contra Facebook e Google"},"content":{"rendered":"<p>GABRIELA BONIN<br \/>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; Ap\u00f3s imagens da aut\u00f3psia do corpo de Mar\u00edlia Mendon\u00e7a circularem na internet, a fam\u00edlia da cantora vai entrar na Justi\u00e7a para punir eventuais respons\u00e1veis pela divulga\u00e7\u00e3o das fotos. O advogado da fam\u00edlia, Robson Cunha, disse que Facebook e Google ser\u00e3o alvos de a\u00e7\u00f5es &#8220;para tentar coibir qualquer tipo de divulga\u00e7\u00e3o e responsabiliz\u00e1-los&#8221; pelo compartilhamento das imagens.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>Ao programa Fofocalizando, do SBT, Cunha afirmou que o primeiro passo \u00e9 coibir a repercuss\u00e3o das imagens. &#8220;O crime inicial foi cometido, que foi a divulga\u00e7\u00e3o desse conte\u00fado, mas a propaga\u00e7\u00e3o desse material tamb\u00e9m \u00e9 crime. As pessoas t\u00eam que entender a gravidade disso&#8221;, falou.<\/p>\n<p>O F5 apurou que o Google vai agir para retirar do ar conte\u00fados que violem pol\u00edticas da plataforma. Procurada, a assessoria do Google informou que &#8220;a empresa n\u00e3o tem nada a comentar&#8221;. A Meta, dona do Facebook, n\u00e3o respondeu at\u00e9 a \u00faltima atualiza\u00e7\u00e3o deste texto.<\/p>\n<p>Questionado sobre eventuais a\u00e7\u00f5es contra o Governo de Minas Gerais, o advogado disse que a fam\u00edlia est\u00e1 esperando um esclarecimento sobre o caso. &#8220;At\u00e9 agora, a gente n\u00e3o recebeu absolutamente nada oficial do governo de estado. A gente precisa, inicialmente, de uma manifesta\u00e7\u00e3o p\u00fablica do que de fato aconteceu. O primeiro passo \u00e9 esse. O segundo passo \u00e9 responsabilizar n\u00e3o apenas o agente que cometeu esse crime, como tamb\u00e9m o pr\u00f3prio estado&#8221;, explicou.<\/p>\n<p>A Pol\u00edcia Civil de Minas Gerais instaurou um procedimento administrativo para a apura\u00e7\u00e3o dos fatos. &#8220;A Pol\u00edcia Civil informa que o sistema onde ficam armazenados os documentos investigativos s\u00e3o audit\u00e1veis e que a Superintend\u00eancia de Informa\u00e7\u00f5es e Intelig\u00eancia Policial (SIIP) j\u00e1 est\u00e1 realizando os levantamentos com vistas a identificar todos os acessos ao referido laudo&#8221;, diz trecho da nota enviada ao F5.<\/p>\n<p>O advogado da fam\u00edlia reiterou o fato de que o inqu\u00e9rito do qual as fotos foram colhidas era restrito a poucas pessoas, o que tornaria mais simples a identifica\u00e7\u00e3o do culpado. &#8220;\u00c9 um inqu\u00e9rito policial sigiloso e, ainda mais, pouqu\u00edssimas pessoas t\u00eam acesso. Esse conte\u00fado n\u00e3o est\u00e1 liberado, inclusive, para terceiros da pr\u00f3pria pol\u00edcia que queiram acess\u00e1-lo&#8221;, explicou. &#8220;Quem o fez, o fez atrav\u00e9s de um acesso restrito. Ent\u00e3o, \u00e9 de f\u00e1cil identifica\u00e7\u00e3o.&#8221;<\/p>\n<p>Cunha relatou que foi Murilo Huff, ex-namorado e pai do filho da cantora, que o avisou sobre as fotos vazadas. &#8220;Ele, muito chocado, muito abalado no telefone, me deu a not\u00edcia de que estava recebendo algumas imagens&#8221;, disse.<\/p>\n<p>O advogado falou ainda sobre os esfor\u00e7os feitos por ele e pela fam\u00edlia de Mar\u00edlia Mendon\u00e7a para evitar o vazamento de imagens logo ap\u00f3s o acidente, em novembro de 2021. &#8220;Eu entrei em contato com respons\u00e1veis do IML e pedi para que o corpo n\u00e3o sa\u00edsse do IML enquanto eu n\u00e3o chegasse. Eles entenderam, compreenderam a situa\u00e7\u00e3o e aguardaram. A raz\u00e3o pela qual eu havia feito esse pedido era justamente para que, saindo do IML, n\u00e3o se perdesse o controle de tudo que estava sendo feito.&#8221;<\/p>\n<p>Cunha explicou os procedimentos adotados na \u00e9poca para evitar que fotos do corpo da cantora fossem divulgados. &#8220;Colocamos uma escolta acompanhando o carro da funer\u00e1ria. Na funer\u00e1ria, recolhemos todos os equipamentos celulares, inclusive o do propriet\u00e1rio do local. Desligamos todas as c\u00e2meras e monitoramento do local. Enfim, tivemos o cuidado e a aten\u00e7\u00e3o de fazer um trabalho que evitasse qualquer exposi\u00e7\u00e3o de qualquer imagem associada ao p\u00f3s-acidente.&#8221;<\/p>\n<p>&#8220;At\u00e9 ontem, a gente imaginava ter feito um trabalho de respeito \u00e0 imagem da Mar\u00edlia&#8221;, complementou.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Fama<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/celebridades\/2010099\/3-familia-de-marilia-mendonca-vai-entrar-com-acao-contra-facebook-e-google?utm_source=rss-fama&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>GABRIELA BONINS\u00c3O PAULO, SP (FOLHAPRESS) &#8211; Ap\u00f3s imagens da aut\u00f3psia do corpo de Mar\u00edlia Mendon\u00e7a<\/p>\n","protected":false},"author":0,"featured_media":119822,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-119821","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fama-e-tv"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/119821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=119821"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/119821\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/119822"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=119821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=119821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=119821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}