{"id":119813,"date":"2023-04-16T07:08:21","date_gmt":"2023-04-16T10:08:21","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/16\/lula-incomoda-washington-ao-receber-visita-de-chanceler-russo\/"},"modified":"2023-04-16T07:08:21","modified_gmt":"2023-04-16T10:08:21","slug":"lula-incomoda-washington-ao-receber-visita-de-chanceler-russo","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/16\/lula-incomoda-washington-ao-receber-visita-de-chanceler-russo\/","title":{"rendered":"Lula incomoda Washington ao receber visita de chanceler russo"},"content":{"rendered":"<p>IGOR GIELOW<br \/>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; O chanceler da R\u00fassia, Serguei Lavrov, desembarca nesta segunda-feira (17) em Bras\u00edlia para uma viagem de dois dias ao pa\u00eds, na primeira etapa de um giro em que seguir\u00e1 para tr\u00eas advers\u00e1rios dos Estados Unidos na Am\u00e9rica Latina pr\u00f3ximos do PT.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>Mais do que a visita de Estado \u00e0 China, em que j\u00e1 foi dif\u00edcil para Luiz In\u00e1cio Lula da Silva (PT) sustentar a imagem de neutralidade no contexto da Guerra Fria 2.0 entre Pequim e Washington, a vinda de Lavrov posiciona o Brasil de um lado do conflito na Ucr\u00e2nia aos olhos da diplomacia americana e ocidental.<\/p>\n<p>Para o Itamaraty e para o Kremlin, isso \u00e9 irrelevante, e a visita \u00e9 uma prova de uma saud\u00e1vel independ\u00eancia brasileira em um mundo que n\u00e3o comporta domin\u00e2ncias e blocos estanques. Para cr\u00edticos, \u00e9 um alinhamento excessivo entre o Brasil e a R\u00fassia \u2013condenada pela maioria dos pa\u00edses da ONU por sua guerra.<\/p>\n<p>Nem tudo ser\u00e1 consenso, apesar do avan\u00e7o recente das compras brasileiras de \u00f3leo diesel da R\u00fassia, que deve estar na agenda. Haver\u00e1 nas conversas em Bras\u00edlia o espinhoso tema dos alegados espi\u00f5es russos que se passavam por brasileiros, um assunto em apura\u00e7\u00e3o pela Pol\u00edcia Federal.<\/p>\n<p>Para complicar, advogados do not\u00f3rio opositor de Vladimir Putin Alexei Navalni dizem que ele est\u00e1 em estado cr\u00edtico na cadeia, supostamente envenenado pela segunda vez. Se morrer com Lavrov junto \u00e0 Lula, o constrangimento internacional \u00e9 certo.<\/p>\n<p>Descontando esse cen\u00e1rio extremo, tudo tende a ser ofuscado pelo contexto geral. A ambiguidade brasileira em rela\u00e7\u00e3o \u00e0 invas\u00e3o russa de 2022 precede o conflito, quando o ent\u00e3o presidente Jair Bolsonaro (PL) visitou Moscou e prestou solidariedade ao colega Putin uma semana antes das tropas do Kremlin atravessarem a fronteira.<\/p>\n<p>O motivo \u00e9 a depend\u00eancia brasileira de fertilizantes russos, que somam mais de 20% do mercado nacional. Havia outros itens na pauta, como a necessidade brasileira de acesso a combust\u00edvel nuclear certificado para o reator at\u00f4mico de seu futuro submarino.<\/p>\n<p>Mas os fertilizantes dominam a conversa. Eles puxaram o aumento do fluxo comercial Brasil-R\u00fassia em pleno regime de san\u00e7\u00f5es ocidentais a Moscou: em 2022, os brasileiros compraram 37% a mais produtos russos do que em 2021, somando US$ 7,8 bilh\u00f5es, um balan\u00e7a superavit\u00e1ria para Moscou em US$ 5,9 bilh\u00f5es.<\/p>\n<p>Ao mesmo tempo, o Brasil votou duas vezes na ONU condena\u00e7\u00f5es \u00e0 agress\u00e3o contra Kiev, ainda que tenha rejeitado aplicar san\u00e7\u00f5es \u00e0 R\u00fassia. O pragmatismo, consonante com a posi\u00e7\u00e3o hist\u00f3rica do pa\u00eds, acabou ampliado com a volta de Lula ao poder.<\/p>\n<p>Afinal, foi sob suas duas passagens pela Presid\u00eancia anteriores que o Brasil estimulou, anabolizado pelo boom de commodities da China nos anos 2000, uma diplomacia mais agressiva ao buscar parcerias no chamado Sul Global. O Brics, o bloco que une at\u00e9 advers\u00e1rios como \u00cdndia e China, foi resultado disso.<\/p>\n<p>No come\u00e7o do ano, o petista rejeitou um pedido da Alemanha para vender muni\u00e7\u00e3o de velhos tanques Leopard-1 que opera, que seriam repassados junto com os carros de combate do modelo que a Europa enviar\u00e1 ao esfor\u00e7o de guerra ucraniano. Disse que isso fere a ideia de neutralidade.<\/p>\n<p>Kiev protestou, e o pr\u00f3prio presidente Volodimir Zelenski convidou o brasileiro a visit\u00e1-lo, sem sucesso. Lula j\u00e1 havia irritado os ucranianos ao dizer que o l\u00edder era t\u00e3o respons\u00e1vel quanto Putin pela guerra e, recentemente, foi criticado por sugerir que a paz poderia ser alcan\u00e7ada se a Ucr\u00e2nia cedesse territ\u00f3rio.<\/p>\n<p>H\u00e1 duas semanas, Lula enviou o influente assessor e ex-chanceler Celso Amorim para encontrar-se com Putin no Kremlin. Agora, Lavrov devolve a cortesia. &#8220;Qual a vantagem disso?&#8221;, questiona Rubens Barbosa, ex-embaixador do Brasil em Washington.<\/p>\n<p>A terceira encarna\u00e7\u00e3o de Lula presidente, aproveitando a terra arrasada deixada por Bolsonaro no campo internacional, buscou vender a ideia de que o pa\u00eds est\u00e1 de volta ao jogo. S\u00f3 que, em vez de focar em temas sobre os quais h\u00e1 consenso do peso brasileiro, como crise do clima e seguran\u00e7a alimentar, Lula mira alto.<\/p>\n<p>Quer assento em um tema vital de seguran\u00e7a mundial, a Guerra da Ucr\u00e2nia. Sugeriu a cria\u00e7\u00e3o de um &#8220;clube da paz&#8221;, ideia bombardeada pelos EUA por incluir a China, aliada russa, e elogiada em Moscou e Pequim.<\/p>\n<p>Para cr\u00edticos, isso oscila entre deslumbramento e o risco de ser usado por Putin e Xi Jinping. No caso russo, a vinda de Lavrov serve \u00e0 necessidade do Kremlin de mostrar que n\u00e3o est\u00e1 isolado. Em artigo \u00e0 Folha, o chanceler falou sobre a import\u00e2ncia de um mundo sem a unipolaridade americana do p\u00f3s-Guerra Fria.<\/p>\n<p>Esse tempo de todo modo acabou, como os m\u00faltiplos desafios enfrentados pelos EUA demonstram: crises econ\u00f4micas, fracassos militares e a ascens\u00e3o chinesa \u2013exacerbada pelo papel de Xi Jinping, o mais poderoso l\u00edder do pa\u00eds em mais de tr\u00eas d\u00e9cadas.<\/p>\n<p>Decano da grande diplomacia mundial, Lavrov est\u00e1 no cargo desde 2004. Com experi\u00eancia pr\u00e9via de dez anos na ONU, sempre foi respeitado como um ponderado negociador multilateral.<\/p>\n<p>A crescente agressividade do Kremlin \u2013vista na tentativa de impedir a expans\u00e3o da Otan, a alian\u00e7a militar ocidental\u2013 colocou Lavrov sob fogo dos antigos admiradores.<\/p>\n<p>Diplomatas e analistas russos contemporizam, dizendo que Lavrov, 73, n\u00e3o tem influ\u00eancia decisiva sobre as medidas do chefe. Seja como for, ele tem passado dificuldades p\u00fablicas, como quando um coment\u00e1rio seu afirmando que a guerra foi imposta \u00e0 R\u00fassia pelo Ocidente foi alvo de risadas de uma plateia. Ao mesmo tempo, segue em alta costura, tendo organizado a pomposa visita de Xi a Putin.<\/p>\n<p>Para completar o quadro, Lavrov deixar\u00e1 Bras\u00edlia rumo a tr\u00eas ditaduras pr\u00f3ximas de Moscou, e tamb\u00e9m do PT e da esquerda, na regi\u00e3o: Venezuela, Nicar\u00e1gua e Cuba.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Mundo<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/mundo\/2010138\/lula-incomoda-washington-ao-receber-visita-de-chanceler-russo?utm_source=rss-mundo&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>IGOR GIELOWS\u00c3O PAULO, SP (FOLHAPRESS) &#8211; O chanceler da R\u00fassia, Serguei Lavrov, desembarca nesta segunda-feira<\/p>\n","protected":false},"author":0,"featured_media":119814,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-119813","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/119813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=119813"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/119813\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/119814"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=119813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=119813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=119813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}