{"id":119767,"date":"2023-04-15T17:08:35","date_gmt":"2023-04-15T20:08:35","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/15\/embalado-pelo-titulo-carioca-fluminense-pega-america-mg-pelo-brasileirao\/"},"modified":"2023-04-15T17:08:35","modified_gmt":"2023-04-15T20:08:35","slug":"embalado-pelo-titulo-carioca-fluminense-pega-america-mg-pelo-brasileirao","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/15\/embalado-pelo-titulo-carioca-fluminense-pega-america-mg-pelo-brasileirao\/","title":{"rendered":"Embalado pelo t\u00edtulo carioca, Fluminense pega Am\u00e9rica-MG pelo Brasileir\u00e3o"},"content":{"rendered":"<p>Depois de conquistar o bicampeonato carioca de forma impressionante, uma goleada em cima do Flamengo por 4 a 1, o Fluminense d\u00e1 a largada no Campeonato Brasileiro apontado como um dos favoritos ao t\u00edtulo da temporada. A sua estreia, por\u00e9m, ser\u00e1 distante da torcida e do Maracan\u00e3, o palco de sua \u00faltima exibi\u00e7\u00e3o de gala. O primeiro advers\u00e1rio ser\u00e1 o Am\u00e9rica-MG, vice-campe\u00e3o mineiro, neste s\u00e1bado, \u00e0s 16h, no Est\u00e1dio Independ\u00eancia, em Belo Horizonte (MG).<\/p>\n<p>Na temporada passada, por sua vez, os dois times brigaram na parte de cima da tabela e neste ano querem fazer bonito novamente para garantir vaga nas competi\u00e7\u00f5es internacionais e at\u00e9 brigar pelo t\u00edtulo. O time tricolor foi o terceiro colocado em 2022, enquanto o Am\u00e9rica ficou em d\u00e9cimo. Nas m\u00e3os do t\u00e9cnico Fernando Diniz, os cariocas v\u00eam fazendo um trabalho muito elogiado e com um futebol envolvente.<\/p>\n<\/p>\n<p>Para o duelo, o t\u00e9cnico Vagner Mancini tem um retorno importante para escalar o time titular do Am\u00e9rica-MG nesta estreia. O meia Ben\u00edtez est\u00e1 recuperado de dores no joelho esquerdo, que o tiraram do jogo de volta da decis\u00e3o do Campeonato Mineiro e do jogo de ida da terceira fase da Copa do Brasil no qual, o time mineiro venceu o Nova Igua\u00e7u-RJ, por 2 a 1, e volta a ficar \u00e0 disposi\u00e7\u00e3o.<\/p>\n<\/p>\n<p>Por outro lado, o atacante Alo\u00edsio, que tamb\u00e9m esteve de fora destas \u00faltimas partidas, n\u00e3o se recuperou a tempo de dores musculares assim como seu companheiro, e por isso segue como desfalque. Mancini, inclusive falou sobre isso, em entrevista nesta semana. <\/p>\n<\/p>\n<p>Do outro lado, depois de passar pelo Paysandu neste meio de semana, vencendo o jogo de ida da terceira fase da Copa do Brasil por 3 a 0 no Maracan\u00e3, e embalado pelo t\u00edtulo carioca, o Fluminense deve estrear no Brasileir\u00e3o com for\u00e7a m\u00e1xima.<\/p>\n<\/p>\n<p>Mesmo assim, Fernando Diniz fez um alerta sobre disputar o primeiro jogo como visitante. &#8220;A localiza\u00e7\u00e3o (de pontos de refer\u00eancia do campo como mandante) pode ter alguma influ\u00eancia, mas n\u00e3o \u00e9 determinante. Tem (como influ\u00eancia) o h\u00e1bito de jogar no mesmo campo, a grama, a for\u00e7a da torcida quando est\u00e1 apoiando, n\u00e3o ter que deslocar o grupo e descansar mais para o jogo. Uma s\u00e9rie de fatores fazem os mandantes terem um aproveitamento melhor, mas acho que \u00e9 a soma de muitos fatores.&#8221;<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Esporte<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/esporte\/2009946\/embalado-pelo-titulo-carioca-fluminense-pega-america-mg-pelo-brasileirao?utm_source=rss-esporte&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depois de conquistar o bicampeonato carioca de forma impressionante, uma goleada em cima do Flamengo<\/p>\n","protected":false},"author":0,"featured_media":119768,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-119767","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/119767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=119767"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/119767\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/119768"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=119767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=119767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=119767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}