{"id":119765,"date":"2023-04-15T17:08:34","date_gmt":"2023-04-15T20:08:34","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/15\/bayern-tropeca-e-borussia-dortmund-perde-chance-de-alcancar-rival-ao-levar-empate-surpreendente\/"},"modified":"2023-04-15T17:08:34","modified_gmt":"2023-04-15T20:08:34","slug":"bayern-tropeca-e-borussia-dortmund-perde-chance-de-alcancar-rival-ao-levar-empate-surpreendente","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/15\/bayern-tropeca-e-borussia-dortmund-perde-chance-de-alcancar-rival-ao-levar-empate-surpreendente\/","title":{"rendered":"Bayern trope\u00e7a e Borussia Dortmund perde chance de alcan\u00e7ar rival ao levar empate surpreendente"},"content":{"rendered":"<p>O Borussia Dortmund perdeu uma chance inacredit\u00e1vel de alcan\u00e7ar o Bayern de Munique no topo da tabela do Campeonato Alem\u00e3o no in\u00edcio da tarde deste s\u00e1bado. Ap\u00f3s ser goleado pelo Manchester City no meio da semana, o Bayern ficou apenas no empate por 1 a 1 com o Hoffenheim. Em um jogo maluco no mesmo hor\u00e1rio, com um jogador a mais durante todo o segundo tempo, o Borussia vencia por 2 a 0 e sofreu o empate contra o Stuttgart. J\u00e1 nos acr\u00e9scimos, o Borussia chegou a fazer 3 a 2, mas levou novo empate no \u00faltimo lance do jogo, j\u00e1 aos 51 minutos, ficando no 3 a 3. <\/p>\n<p>Ap\u00f3s perder o confronto direto contra o rival, o Borussia desperdi\u00e7a tamb\u00e9m a chance de alcan\u00e7ar o Bayern de Munique na lideran\u00e7a ap\u00f3s 28 partidas. Como os dois times empataram, o Bayern segue com vantagem de dois pontos sobre o Borussia, com 59 contra 57. O Stuttgart est\u00e1 em 16\u00ba, com 24 pontos e o Hoffenheim em 13\u00ba, com 29. <\/p>\n<\/p>\n<p>Em casa, na Allianz Arena, o Bayern abriu o placar aos 17 minutos com Benjamin Pavard. Ap\u00f3s escanteio e confus\u00e3o na \u00e1rea, a bola sobrou para o franc\u00eas na \u00e1rea, que finalizou do jeito que dava e marcou. O Hoffenheim dificultou a vida do Bayern e buscou o empate com um gola\u00e7o j\u00e1 no segundo tempo, aos 25 minutos, em uma bela cobran\u00e7a de falta de Kramaric. Pavard chegou a marcar mais um, mas o lance foi anulado pelo VAR. O jogo terminou 1 a 1.<\/p>\n<\/p>\n<p>Em Stuttgart, o Borussia Dortmund teve um primeiro tempo bastante favor\u00e1vel. Malen fez boa jogada pela direita e cruzou para S\u00e9bastien Haller fazer 1 a 0 aos 26 minutos, com um chute de primeira. Aos 33, Donyell Malen apareceu novamente para decidir. O holand\u00eas ficou com a bola na \u00e1rea, protegeu bem da defesa e finalizou rasteiro para fazer 2 a 0. <\/p>\n<\/p>\n<p>No fim do primeiro tempo, Mavropanos foi expulso, deixando o Stuttgart com um a menos em todo o segundo tempo. Mesmo assim, o time da casa conseguiu buscar o empate com gols de Coulibaly e Vagnoman aos 33 e 39 minutos da etapa final. Os minutos finais do jogo foram de tirar o f\u00f4lego. J\u00e1 nos acr\u00e9scimos, Giovanni Reyna conseguiu recolocar o Borussia em vantagem ao marcar o gol do 3 a 2. Mas, no \u00faltimo lance na partida, a zaga falhou e Mvumpa impediu a derrota do Stuttgart, empatando novamente por 3 a 3. <\/p>\n<\/p>\n<p>OUTROS JOGOS<\/p>\n<p>Terceiro colocado, com 51 pontos, o RB Leipzig venceu o Augsburg por 3 a 2 em outro jogo movimentado. O Augsburg \u00e9 o 14\u00ba colocado, com 29 pontos, e vive p\u00e9ssima fase. Em s\u00e9timo (42 pontos), o Mainz ficou no empate por 1 a 1 contra o Col\u00f4nia (11\u00ba, 32 pontos) fora de casa.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Esporte<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/esporte\/2010019\/bayern-tropeca-e-borussia-dortmund-perde-chance-de-alcancar-rival-ao-levar-empate-surpreendente?utm_source=rss-esporte&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Borussia Dortmund perdeu uma chance inacredit\u00e1vel de alcan\u00e7ar o Bayern de Munique no topo<\/p>\n","protected":false},"author":0,"featured_media":119766,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-119765","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/119765","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=119765"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/119765\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/119766"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=119765"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=119765"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=119765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}