{"id":119751,"date":"2023-04-15T17:08:26","date_gmt":"2023-04-15T20:08:26","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/15\/astros-e-estrelas-que-foram-parar-na-lista-de-comunistas-de-hollywood\/"},"modified":"2023-04-15T17:08:26","modified_gmt":"2023-04-15T20:08:26","slug":"astros-e-estrelas-que-foram-parar-na-lista-de-comunistas-de-hollywood","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/15\/astros-e-estrelas-que-foram-parar-na-lista-de-comunistas-de-hollywood\/","title":{"rendered":"Astros e estrelas que foram parar na lista de comunistas de Hollywood"},"content":{"rendered":"<p>Quando governos querem apagar uma ideologia de sua popula\u00e7\u00e3o, a arte \u00e9 quase sempre o primeiro bra\u00e7o da cultura a ser atacado. Figuras proeminentes no cinema e na m\u00fasica, que det\u00e9m o apre\u00e7o e confian\u00e7a do p\u00fablico por suas opini\u00f5es, podem se tornar inimigos perigosos do Estado se seus pontos de vista n\u00e3o estiverem alinhados com os do governo sob o qual operam. A persegui\u00e7\u00e3o a pessoas ligadas \u00e0 cultura tem sido bastante comum ao longo da hist\u00f3ria. Nos Estados Unidos, por\u00e9m, isso nunca foi t\u00e3o difundido ou t\u00e3o hist\u00e9rico quanto sob o macarthismo. Comumente comparado a uma ca\u00e7a \u00e0s bruxas, as primeiras d\u00e9cadas da Guerra Fria foram repletas de comit\u00eas e tribunais governamentais dedicados a erradicar todos os \u00faltimos ind\u00edcios de sentimento comunista, socialista ou anarquista na ind\u00fastria do entretenimento americana. E muitas figuras proeminentes, v\u00e1rias das quais s\u00e3o celebradas hoje, pagaram, com suas pr\u00f3prias carreiras, por sua suposta insurg\u00eancia.<\/p>\n<p>Nesta galeria, descubra quais astros e estrelas foram colocadas na lista de comunistas de Hollywood.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Fama<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/fama\/2009942\/astros-e-estrelas-que-foram-parar-na-lista-de-comunistas-de-hollywood-e-perderam-trabalho-por-isso?utm_source=rss-fama&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quando governos querem apagar uma ideologia de sua popula\u00e7\u00e3o, a arte \u00e9 quase sempre o<\/p>\n","protected":false},"author":0,"featured_media":119752,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-119751","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fama-e-tv"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/119751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=119751"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/119751\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/119752"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=119751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=119751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=119751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}