{"id":119633,"date":"2023-04-14T22:08:36","date_gmt":"2023-04-15T01:08:36","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/14\/gloria-groove-e-masego-sao-anunciados-para-o-the-town-e-tocarao-no-palco-the-one\/"},"modified":"2023-04-14T22:08:36","modified_gmt":"2023-04-15T01:08:36","slug":"gloria-groove-e-masego-sao-anunciados-para-o-the-town-e-tocarao-no-palco-the-one","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/14\/gloria-groove-e-masego-sao-anunciados-para-o-the-town-e-tocarao-no-palco-the-one\/","title":{"rendered":"Gloria Groove e Masego s\u00e3o anunciados para o The Town e tocar\u00e3o no palco The One"},"content":{"rendered":"<p>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; Gloria Groove e Masego foram anunciados nessa sexta-feira (13) como novas atra\u00e7\u00f5es do The Town, que ocorre nos dias 2, 3, 7, 9 e 10 de setembro, no Aut\u00f3dromo de Interlagos em S\u00e3o Paulo. Eles se apresentar\u00e3o no palco The One.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>O m\u00fasico jamaicano-americano, nome de destaque do jazz e R&amp;B, sobe ao palco no dia 7, mesma ocasi\u00e3o em que NE-YO ser\u00e1 a atra\u00e7\u00e3o principal do espa\u00e7o. J\u00e1 Gloria Groove, c\u00e9lebre cantora de pop nacional, far\u00e1 seu show no dia 10.<\/p>\n<p>O an\u00fancio \u00e9 feito quatro dias antes do The Town abrir a venda oficial dos ingressos para todo o p\u00fablico. Ela come\u00e7a na ter\u00e7a-feira (18), \u00e0s 19h, somente no site da Ticketmaster.<\/p>\n<p>O The Town ter\u00e1 seis palcos, por onde passar\u00e3o artistas como Bruno Mars, Foo Fighters, Queens of The Stone Age, H.E.R, Ludmilla, Seu Jorge e X\u00eania Fran\u00e7a. A expectativa de p\u00fablico na Cidade da M\u00fasica \u00e9 de 500 mil pessoas.<\/p>\n<p>O Aut\u00f3dromo de Interlagos passar\u00e1 por uma reforma e ter\u00e1 uma rede de esgoto que promete substituir os banheiros qu\u00edmicos. As mudan\u00e7as tamb\u00e9m incluem a instala\u00e7\u00e3o de grama sint\u00e9tica sobre o espa\u00e7o, para que n\u00e3o haja lama caso chova.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Cultura<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/celebridades\/2009729\/gloria-groove-e-masego-sao-anunciados-para-o-the-town-e-tocarao-no-palco-the-one?utm_source=rss-cultura&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; Gloria Groove e Masego foram anunciados nessa sexta-feira (13) como<\/p>\n","protected":false},"author":0,"featured_media":119634,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-119633","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/119633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=119633"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/119633\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/119634"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=119633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=119633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=119633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}