{"id":119621,"date":"2023-04-14T20:08:45","date_gmt":"2023-04-14T23:08:45","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/14\/confederacao-adia-jogo-da-superliga-na-busca-por-solucao-no-caso-wallace\/"},"modified":"2023-04-14T20:08:45","modified_gmt":"2023-04-14T23:08:45","slug":"confederacao-adia-jogo-da-superliga-na-busca-por-solucao-no-caso-wallace","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/14\/confederacao-adia-jogo-da-superliga-na-busca-por-solucao-no-caso-wallace\/","title":{"rendered":"Confedera\u00e7\u00e3o adia jogo da Superliga na busca por solu\u00e7\u00e3o no caso Wallace"},"content":{"rendered":"<p>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; A CBV (Confedera\u00e7\u00e3o Brasileira de V\u00f4lei) decidiu alterar a data da partida entre Sada Cruzeiro e S\u00e3o Jos\u00e9, pela fase final da Superliga masculina. O confronto, que seria neste s\u00e1bado (15), foi adiado para quarta-feira (19), \u00e0s 21h.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>A mudan\u00e7a foi a solu\u00e7\u00e3o encontrada pela Confedera\u00e7\u00e3o para tentar definir o imbr\u00f3glio envolvendo o oposto Wallace. Suspenso por 90 dias pelo Conselho de \u00c9tica do COB (Comit\u00ea Ol\u00edmpico do Brasil), ele conseguiu efeito suspensivo no STJD (Superior Tribunal de Justi\u00e7a Desportiva) da modalidade at\u00e9 o julgamento do m\u00e9rito do recurso. Isso o liberaria para jogar.<\/p>\n<p>Como n\u00e3o h\u00e1 um \u00f3rg\u00e3o superior para apelar e resolver a quest\u00e3o, criou-se um impasse e a CBV teme, caso Wallace jogue, ser punida pelo COB. A entidade buscou ajuda no CBMA (Centro Brasileiro de Media\u00e7\u00e3o e Arbitragem) para tentar uma solu\u00e7\u00e3o definitiva.<\/p>\n<p>No final de janeiro, o atleta postou foto em sua conta de Instagram. Estava em clube de tiro, com uma arma na m\u00e3o e abriu a caixa de perguntas do aplicativo para responder a d\u00favidas dos seus seguidores. Um deles questionou se usaria aquele rev\u00f3lver para dar um tiro no presidente da Rep\u00fablica, Luiz In\u00e1cio Lula da Silva (PT). Wallace respondeu com a abertura de enquete questionando quem faria aquilo.<\/p>\n<p>&#8220;A CBV se viu diante de duas decis\u00f5es conflitantes, tomadas por dois \u00f3rg\u00e3os independentes (Conselho de \u00c9tica do Comit\u00ea Ol\u00edmpico do Brasil e STJD), sobre o caso envolvendo o atleta Wallace, do Sada Cruzeiro. Assim, decidiu submeter a quest\u00e3o ao Centro Brasileiro de Media\u00e7\u00e3o e Arbitragem (CBMA), inst\u00e2ncia arbitral com compet\u00eancia para tal, conforme previsto nos estatutos do COB e da CBV&#8221;, diz nota da Confedera\u00e7\u00e3o.<\/p>\n<p>Desde quarta-feira (12), quando foi concedido o efeito suspensivo, busca-se uma sa\u00edda pol\u00edtica para o conflito. O Conselho de \u00c9tica, \u00f3rg\u00e3o independente do COB, n\u00e3o abre m\u00e3o da decis\u00e3o de punir Wallace. O Sada Cruzeiro n\u00e3o aceita n\u00e3o ter o jogador em quadra e ainda protesta pela mudan\u00e7a de data.<\/p>\n<p>&#8220;A op\u00e7\u00e3o pelo adiamento parece uma clara tentativa de arrumar brechas para descumprir uma decis\u00e3o do \u00f3rg\u00e3o competente para julgar os atos de atletas, clubes e federa\u00e7\u00f5es, que \u00e9 o Superior Tribunal de Justi\u00e7a Desportiva. As decis\u00f5es da justi\u00e7a desportiva, especialmente do STJD da modalidade, devem ser cumpridas. O Sada Cruzeiro espera e confia numa resposta do STJD, que se encontra desacatado neste momento&#8221;, manifestou-se o clube.<\/p>\n<p>Com o adiamento, CBV ganha tempo tamb\u00e9m para que aconte\u00e7a o julgamento do m\u00e9rito do recurso apresentado pelo Cruzeiro e pelo jogador. Se suspens\u00e3o for mantida tamb\u00e9m pelo tribunal desportivo (que havia arquivado inicialmente a den\u00fancia por n\u00e3o ver rela\u00e7\u00e3o entre a postagem e o esporte), Wallace estaria fora das finais da Superliga e o problema acabaria.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Esporte<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/esporte\/2009656\/confederacao-adia-jogo-da-superliga-na-busca-por-solucao-no-caso-wallace?utm_source=rss-esporte&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; A CBV (Confedera\u00e7\u00e3o Brasileira de V\u00f4lei) decidiu alterar a data<\/p>\n","protected":false},"author":0,"featured_media":119622,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-119621","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/119621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=119621"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/119621\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/119622"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=119621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=119621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=119621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}