{"id":119584,"date":"2023-04-14T17:08:30","date_gmt":"2023-04-14T20:08:30","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/14\/gilberto-assume-vaga-de-deputado-na-assembleia-juliano-melo-comandara-secretaria-de-saude\/"},"modified":"2023-04-14T17:08:30","modified_gmt":"2023-04-14T20:08:30","slug":"gilberto-assume-vaga-de-deputado-na-assembleia-juliano-melo-comandara-secretaria-de-saude","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/14\/gilberto-assume-vaga-de-deputado-na-assembleia-juliano-melo-comandara-secretaria-de-saude\/","title":{"rendered":"Gilberto assume vaga de deputado na Assembleia; Juliano Melo comandar\u00e1 secretaria de Sa\u00fade"},"content":{"rendered":"<p>O servidor de carreira Juliano Melo \u00e9 o novo secret\u00e1rio estadual de Sa\u00fade, substituindo  Gilberto Figueiredo, que assume na pr\u00f3xima segunda-feira mandato de deputado estadual, por quatro meses, na vaga deixada por Eduardo Botelho, que entrou em licen\u00e7a.\u00a0<\/p>\n<p>A nomea\u00e7\u00e3o de Juliano e exonera\u00e7\u00e3o de Gilberto foram publicadas em edi\u00e7\u00e3o extra do Di\u00e1rio Oficial, que circula hoje. Juliano \u00e9 secret\u00e1rio adjunto de Aten\u00e7\u00e3o e Vigil\u00e2ncia em Sa\u00fade, desde 2019.\u00a0Nutricionista, formado pela Universidade Federal de Mato Grosso, ele est\u00e1 na secretaria h\u00e1 19 anos.<\/p>\n<p>Juliano tem especializa\u00e7\u00e3o em Gest\u00e3o de Sa\u00fade e experi\u00eancia em gest\u00e3o de informa\u00e7\u00f5es, com \u00eanfase nos sistemas DataSUS e BI, e j\u00e1 foi respons\u00e1vel pela Coordenadoria de Vigil\u00e2ncia Epidemiol\u00f3gica da SES, pela Superintend\u00eancia de Vigil\u00e2ncia em Sa\u00fade da SES e diretor da Vigil\u00e2ncia do munic\u00edpio de V\u00e1rzea Grande.<\/p>\n<p>Al\u00e9m disso, coordenou as a\u00e7\u00f5es de Vigil\u00e2ncia da Copa do Mundo de 2014 em Mato Grosso, tamb\u00e9m esteve \u00e0 frente das a\u00e7\u00f5es de combate \u00e0 pandemia pela Covid-19 no Estado e auxiliou a estrutura\u00e7\u00e3o de programas como o Imuniza Mais MT e o Mais MT Cirurgias.<\/p>\n<p>Gilberto Figueiredo comandou a secretaria por mais de 3 anos no primeiro mandato de Mauro Mendes. Saiu para ser candidato a deputado estadual e ficou na primeira supl\u00eancia. Em janeiro, voltou a assumir o comando da pasta.<\/p>\n<p><a href=\"https:\/\/chat.whatsapp.com\/GlnxgGg8UmIKFKzEKwsWMy\">Receba em seu WhatsApp informa\u00e7\u00f5es publicadas em S\u00f3 Not\u00edcias. Clique aqui.<\/a><\/p>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"606\" src=\"https:\/\/www.sonoticias.com.br\/wp-content\/uploads\/2023\/04\/Juliano-Melo-abril-2023-ass--1024x606.jpg\" alt=\"\" class=\"wp-image-1016777\"><\/figure>\n<p>Fonte: S\u00f3 Not\u00edcias<br \/>\nArtigo Original em &gt; www.sonoticias.com.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O servidor de carreira Juliano Melo \u00e9 o novo secret\u00e1rio estadual de Sa\u00fade, substituindo Gilberto<\/p>\n","protected":false},"author":0,"featured_media":119585,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-119584","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/119584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=119584"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/119584\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/119585"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=119584"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=119584"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=119584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}