{"id":119535,"date":"2023-04-14T11:08:15","date_gmt":"2023-04-14T14:08:15","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/14\/prefeito-reitera-pedido-para-fab-instalar-base-no-aeroporto-de-sorriso\/"},"modified":"2023-04-14T11:08:15","modified_gmt":"2023-04-14T14:08:15","slug":"prefeito-reitera-pedido-para-fab-instalar-base-no-aeroporto-de-sorriso","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/14\/prefeito-reitera-pedido-para-fab-instalar-base-no-aeroporto-de-sorriso\/","title":{"rendered":"Prefeito reitera pedido para FAB instalar base no aeroporto de Sorriso"},"content":{"rendered":"<p>O prefeito Ari Lafin acompanhou, ontem, a celebra\u00e7\u00e3o dos 40 anos da Campo de Provas Brigadeiro Velloso, a Base A\u00e9rea do Cachimbo, da Aeron\u00e1utica, pr\u00f3ximo a divisa de Mato Grosso e Par\u00e1. Ari voltou a defender a instala\u00e7\u00e3o de base da FAB no aeroporto regional de Sorriso. Ele manifestou, ao tenente-coronel aviador Rodrigo Gon\u00e7alves Stief, que o munic\u00edpio conta com aeroporto regional localizado a 10 km do centro da cidade, gerenciado pela Infraero e j\u00e1 conta com uma unidade do Centro Integrado de Opera\u00e7\u00f5es A\u00e9reas (Ciopaer), al\u00e9m da Base A\u00e9rea de Combate a Inc\u00eandios Florestais e do Servi\u00e7o de Preven\u00e7\u00e3o, Salvamento e Combate a Inc\u00eandios em Aer\u00f3dromos.<\/p>\n<p> \u201cSomos admiradores do trabalho da Aeron\u00e1utica para nosso pa\u00eds, e novamente, estamos reiterando a proposta de parceria, para que este trabalho de excel\u00eancia realizado aqui na divisa entre o Mato Grosso e Par\u00e1 possa tamb\u00e9m ser feito bem no centro de Mato Grosso, ponto estrat\u00e9gico para todo o pa\u00eds\u201d, manifestou o prefeito sorrisense. <\/p>\n<p>A articula\u00e7\u00e3o de Lafin iniciou, em abril do ano passado, ao requerer a base para o comandante do 6\u00ba Comando A\u00e9reo Regional, major brigadeiro do ar M\u00e1rio S\u00e9rgio Rodrigues Costa. Em junho de 2022, no minist\u00e9rio da Defesa, <a href=\"https:\/\/www.sonoticias.com.br\/politica\/prefeito-reitera-no-ministerio-da-defesa-articulacao-para-sorriso-ter-base-da-fab\/\">em Bras\u00edlia, o prefeito se reuniu com o coronel <\/a>Souza e defendeu a viabilidade da base a\u00e9rea em Sorriso. <\/p>\n<p>A FAB ainda n\u00e3o se manifestou, oficialmente, sobre a solicita\u00e7\u00e3o.<\/p>\n<\/p>\n<p>Fonte: S\u00f3 Not\u00edcias<br \/>\nArtigo Original em &gt; www.sonoticias.com.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O prefeito Ari Lafin acompanhou, ontem, a celebra\u00e7\u00e3o dos 40 anos da Campo de Provas<\/p>\n","protected":false},"author":0,"featured_media":119536,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-119535","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/119535","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=119535"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/119535\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/119536"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=119535"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=119535"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=119535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}