{"id":119469,"date":"2023-04-13T21:08:33","date_gmt":"2023-04-14T00:08:33","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/13\/dolar-volta-a-cair-e-chega-a-ficar-abaixo-de-r-490-durante-o-dia\/"},"modified":"2023-04-13T21:08:33","modified_gmt":"2023-04-14T00:08:33","slug":"dolar-volta-a-cair-e-chega-a-ficar-abaixo-de-r-490-durante-o-dia","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/13\/dolar-volta-a-cair-e-chega-a-ficar-abaixo-de-r-490-durante-o-dia\/","title":{"rendered":"D\u00f3lar volta a cair, e chega a ficar abaixo de R$ 4,90 durante o dia"},"content":{"rendered":"<p>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; O d\u00f3lar teve seu terceiro dia seguido de queda nesta quinta-feira (13), chegando a ficar abaixo de R$ 4,90 na m\u00ednima do dia. Segundo analistas, a situa\u00e7\u00e3o da economia americana faz a moeda perder for\u00e7a globalmente, e a melhora na perspectiva para os juros no Brasil levam a uma valoriza\u00e7\u00e3o mais intensa do real em rela\u00e7\u00e3o a outras divisas.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>A Bolsa tamb\u00e9m caiu nesta quinta-feira, com os investidores aproveitando a agenda local mais esvaziada para realizar lucros. O Ibovespa subiu 6% nos tr\u00eas preg\u00f5es anteriores.<\/p>\n<p>O d\u00f3lar comercial \u00e0 vista fechou em baixa de 0,28%, a R$ 4,927. Na m\u00ednima do dia, a moeda atingiu R$ 4,896. O Ibovespa encerrou o dia em queda de 0,40%, a 106.457 pontos.<\/p>\n<p>Nos mercados futuros, os juros fecharam em baixa nos vencimentos mais longos. Nos contratos para janeiro de 2024, a taxa passou de 13,13% para 13,16%. No vencimento em janeiro de 2025, os juros ca\u00edram de 11,79% para 11,77%. Para janeiro de 2027, a taxa passava de 11,74% para 11,63%.<\/p>\n<p>Os indicadores econ\u00f4micos americanos est\u00e3o no centro das aten\u00e7\u00f5es do mercado nesta quinta-feira, com reflexos principalmente no d\u00f3lar.<\/p>\n<p>No mercado de trabalho, foram 239 mil novos pedidos de seguro-desemprego nos Estados Unidos, na semana que terminou no dia 8 de abril. A expectativa dos economistas ouvidos pela Bloomberg era de 235 mil novos pedidos.<\/p>\n<p>Os pre\u00e7os ao produtor americano, que medem a infla\u00e7\u00e3o de atacado no pa\u00eds, desacelerou em 12 meses de 4,9% em fevereiro para 2,7% em mar\u00e7o. Economistas ouvidos pela Reuters esperavam varia\u00e7\u00e3o anual de 3%. Na varia\u00e7\u00e3o mensal, houve defla\u00e7\u00e3o de 0,5%, ante queda de 0,1% em fevereiro.<\/p>\n<p>Andr\u00e9 Fernandes, diretor de renda vari\u00e1vel e s\u00f3cio da A7 Capital, afirma que os investidores come\u00e7aram a refletir no d\u00f3lar a possibilidade cada vez mais alta de recess\u00e3o nos Estados Unidos.<\/p>\n<p>&#8220;O real acabou se saindo melhor que outras moedas, pois os estrangeiros voltaram a entrar na nossa bolsa, o que acelerou a queda do d\u00f3lar&#8221;, diz Fernandes.<\/p>\n<p>Os dados fizeram os \u00edndices de a\u00e7\u00f5es em Nova York fecharem em alta, refletindo a possibilidade de que o ciclo de alta dos juros se encerre na pr\u00f3xima reuni\u00e3o do Fed (Federal Reserve, o banco central americano), em maio. O Dow Jones encerrou o dia com avan\u00e7o de 1,14%. O S&amp;P 500 subiu 1,33%. O Nasdaq, mais sens\u00edvel \u00e0s perspectivas para os juros, fechou em alta de 1,99%.<\/p>\n<p>Para a equipe da Levante Investimentos, a queda do d\u00f3lar em escala global acontece por falta de interesse dos investidores em comprar a moeda neste momento.<\/p>\n<p>Segundo a Levante, a infla\u00e7\u00e3o ao consumidor abaixo do esperado em mar\u00e7o, e a ata da \u00faltima reuni\u00e3o do Fed citando &#8220;recess\u00e3o&#8221; levam o mercado a precificar mais uma alta de juros, de 0,25 ponto percentual, e posterior pausa no ciclo.<\/p>\n<p>Al\u00e9m da poss\u00edvel recess\u00e3o americana, a recupera\u00e7\u00e3o da China tamb\u00e9m favorece o real. Na madrugada desta quinta-feira, o pa\u00eds asi\u00e1tico divulgou um aumento anual de quase 15% nas exporta\u00e7\u00f5es em mar\u00e7o.<\/p>\n<p>&#8220;As exporta\u00e7\u00f5es chinesas vieram muito acima do esperado, contrariando as previs\u00f5es de queda. Quando a China exporta mais, ela precisa importar mais commodities, e isso beneficia o Brasil&#8221;, diz a Levante.<\/p>\n<p>Os analistas afirmam que n\u00e3o \u00e9 poss\u00edvel dizer quanto vai durar este ciclo de valoriza\u00e7\u00e3o do real ante o d\u00f3lar. &#8220;No entanto, com todas as ressalvas e cuidados, \u00e9 poss\u00edvel dizer que h\u00e1 perspectivas de um al\u00edvio no c\u00e2mbio, o que \u00e9 positivo para a infla\u00e7\u00e3o e para os juros no Brasil&#8221;, diz a Levante.<\/p>\n<p>Gabriel Meira, especialista da Valor Investimentos, diz que a expectativa de pausa no ciclo de alta dos juros nos Estados Unidos, e at\u00e9 mesmo de in\u00edcio de cortes da taxa ainda neste ano, tem reflexos principalmente nas taxas futuras no mercado brasileiro, nesta quinta-feira.<\/p>\n<p>&#8220;J\u00e1 vemos o mercado trabalhando com a possibilidade da Selic chegar na casa dos 12% at\u00e9 o final do ano, por conta do cen\u00e1rio americano e tamb\u00e9m do esperado aumento na exporta\u00e7\u00e3o de commodities, o que favorece o c\u00e2mbio e a desacelera\u00e7\u00e3o da infla\u00e7\u00e3o&#8221;, diz Meira.<\/p>\n<p>Ainda em rela\u00e7\u00e3o ao d\u00f3lar, o presidente Luiz In\u00e1cio Lula da Silva (PT), que est\u00e1 em viagem oficial \u00e0 China, defendeu, na cerim\u00f4nia de posse de Dilma Rousseff no Banco do Brics (Novo Banco de Desenvolvimento, NDB na sigla em ingl\u00eas), a amplia\u00e7\u00e3o do com\u00e9rcio nas pr\u00f3prias moedas pelos integrantes da institui\u00e7\u00e3o -e at\u00e9 mesmo uma moeda do grupo Brics.<\/p>\n<p>&#8220;Por que n\u00e3o podemos fazer o nosso com\u00e9rcio lastreado na nossa moeda?&#8221;, perguntou ele, sob aplausos, ao deixar o discurso escrito e improvisar. &#8220;Quem \u00e9 que decidiu que era o d\u00f3lar? N\u00f3s precisamos ter uma moeda que transforme os pa\u00edses numa situa\u00e7\u00e3o um pouco mais tranquila, porque hoje um pa\u00eds precisa correr atr\u00e1s de d\u00f3lar para exportar.&#8221;<\/p>\n<p>Sobre os juros no Brasil, o ministro da Fazenda, Fernando Haddad, disse nesta quinta-feira que o Banco Central tem uma &#8220;janela de oportunidade&#8221; para reduzir a taxa b\u00e1sica de juros e que essa medida ser\u00e1 necess\u00e1ria para, de acordo com o ministro, destravar o mercado de capitais.<\/p>\n<p>&#8220;Agora quero crer que o Banco Central tem uma janela de oportunidade que eu espero que seja aproveitada para que o Brasil possa pensar em crescimento econ\u00f4mico sustent\u00e1vel&#8221;, disse Haddad a jornalistas em Xangai, onde acompanha o presidente Lula na China.<\/p>\n<p>O presidente da C\u00e2mara dos Deputados, Arthur Lira (PP-AL), afirmou nesta quinta-feira que o governo Luiz In\u00e1cio Lula da Silva (PT) precisa &#8220;melhorar a sua engrenagem pol\u00edtica&#8221; para conseguir a vota\u00e7\u00e3o de temas econ\u00f4micos, caso do novo arcabou\u00e7o fiscal.<\/p>\n<p><a href=\"https:\/\/www.noticiasaominuto.com.br\/economia\/2009487\/dolar-volta-a-cair-e-chega-a-ficar-abaixo-de-r-4-90-durante-o-dia-bolsa-recua-com-realizacao-de-lucros?utm_source=rss-economia&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><br \/>\nNot\u00edcias ao Minuto Brasil &#8211; Economia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; O d\u00f3lar teve seu terceiro dia seguido de queda nesta<\/p>\n","protected":false},"author":0,"featured_media":119470,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-119469","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/119469","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=119469"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/119469\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/119470"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=119469"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=119469"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=119469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}