{"id":119427,"date":"2023-04-13T18:08:51","date_gmt":"2023-04-13T21:08:51","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/13\/xuxa-sobre-nao-ter-engravidado-aos-30-disseram-que-eu-nao-podia\/"},"modified":"2023-04-13T18:08:51","modified_gmt":"2023-04-13T21:08:51","slug":"xuxa-sobre-nao-ter-engravidado-aos-30-disseram-que-eu-nao-podia","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/13\/xuxa-sobre-nao-ter-engravidado-aos-30-disseram-que-eu-nao-podia\/","title":{"rendered":"Xuxa sobre n\u00e3o ter engravidado aos 30: &quot;disseram que eu n\u00e3o podia\u201d"},"content":{"rendered":"<p>Xuxa mais afiada do que nunca. A rainha dos baixinhos chega ao 60 sem filtro e em entrevista ao &#8216;Fofocalizando&#8217;, no SBT, desta quinta-feira (13), fez revela\u00e7\u00f5es com situa\u00e7\u00f5es que ningu\u00e9m imaginava. O rep\u00f3rter Rodrigo Assis conversou com a apresentadora durante a festa de lan\u00e7amento do novo reality show comandado por ela.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>Sobre essa nova fase de sua vida, comentou: <span class=\"news_italic news_bold\">\u201cuma mulher de 60 anos sem filtro como eu&#8230; Posso falar o que eu quero. Antes eu j\u00e1 falava, imagina agora depois dos 60.Fui muito presa, calada por um tempo na minha vida e isso me traumatizou. Voc\u00ea n\u00e3o quer que eu \u2018isso\u2019?! Agora vou usar dois disso. Estou assim, sabe? Essa sou eu. E sempre falo para as pessoas que me acompanham: para voc\u00ea dizer que voc\u00ea gosta de algu\u00e9m, tem que aceitar a pessoa do jeito que \u00e9. Se me aceita do jeito que sou, voc\u00ea me ama\u201d<\/span>.<\/p>\n<p>Recordando o passado, revela o motivo de n\u00e3o ter tido filhos aos 30 anos: <span class=\"news_bold news_italic\">\u201cfizeram uma reuni\u00e3o para dizer que eu n\u00e3o podia engravidar, porque eu ia \u2018embarangar\u2019\u201d.<\/span><\/p>\n<p>A respeito de um procedimento no nariz, explica como conseguiu guardar segredo: <span class=\"news_bold news_italic\">\u201cas pessoas me perguntavam e eu falava eu fiz um ponto no meu nariz. O engra\u00e7ado \u00e9 que eu n\u00e3o tinha falado como foi que eu fiz. Depois de tr\u00eas dias estava trabalhando. Nem minha m\u00e3e sabia, por que os outros tinham que saber?! N\u00e3o quis contar porque minha m\u00e3e ia ficar assustada. Mandei fotos\u201d.<\/span><\/p>\n<p>Ela ent\u00e3o complementa: <span class=\"news_bold news_italic\">\u201cfiz com muito de medo e eu acho que com esse medo que eu passei agora eu tenho o maior trauma. Quando falam \u2018vamos fazer uma cirurgia? \u2019, eu falo \u2018n\u00e3o, deixa cair mais, arrebentar mais, para eu poder levantar\u201d<\/span>. Ainda sobre cirurgia pl\u00e1stica, ressalta: \u201c<span class=\"news_bold news_italic\">vou fazer quando eu quiser, n\u00e3o quando os outros quiserem\u201d.<\/span><\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Fama<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/fama\/2009424\/xuxa-sobre-nao-ter-engravidado-aos-30-disseram-que-eu-nao-podia?utm_source=rss-fama&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Xuxa mais afiada do que nunca. A rainha dos baixinhos chega ao 60 sem filtro<\/p>\n","protected":false},"author":0,"featured_media":119428,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-119427","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fama-e-tv"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/119427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=119427"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/119427\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/119428"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=119427"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=119427"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=119427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}