{"id":119270,"date":"2023-04-12T21:08:35","date_gmt":"2023-04-13T00:08:35","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/12\/leila-diz-que-palmeiras-nao-fara-contratacoes-mesmo-com-onda-de-lesoes\/"},"modified":"2023-04-12T21:08:35","modified_gmt":"2023-04-13T00:08:35","slug":"leila-diz-que-palmeiras-nao-fara-contratacoes-mesmo-com-onda-de-lesoes","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/12\/leila-diz-que-palmeiras-nao-fara-contratacoes-mesmo-com-onda-de-lesoes\/","title":{"rendered":"Leila diz que Palmeiras n\u00e3o far\u00e1 contrata\u00e7\u00f5es mesmo com onda de les\u00f5es"},"content":{"rendered":"<p>S\u00c3O PAULO, SP (UOL\/FOLHAPRESS) &#8211; O Palmeiras tem seis jogadores no departamento m\u00e9dico, mas a presidente Leila Pereira avisou que n\u00e3o h\u00e1 contrata\u00e7\u00f5es na mira.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>Cinco jogadores se machucaram durante o mata-mata do Campeonato Paulista. As \u00faltimas baixas foram o meia Raphael Veiga e o atacante Rony.<\/p>\n<p>Abel tem cobertor curto em algumas posi\u00e7\u00f5es. A lateral-esquerda e a posi\u00e7\u00e3o 10 -do meia-atacante- s\u00e3o as principais dores de cabe\u00e7a do portugu\u00eas.<\/p>\n<p>Leila diz que o clube n\u00e3o far\u00e1 contrata\u00e7\u00f5es neste momento. A presidente afirmou que est\u00e1 atenta ao mercado, mas que n\u00e3o est\u00e1 prevista a chegada de mais refor\u00e7os. At\u00e9 o momento, o clube anunciou Richard R\u00edos, ex-Guarani, e Artur, ex-Red Bull Bragantino.<\/p>\n<p>Desfalcado, o Palmeiras se prepara para enfrentar o Tombense. A partida ser\u00e1 no Allianz Parque, \u00e0s 20h (de Bras\u00edlia), pela ida da terceira fase da Copa do Brasil.<\/p>\n<p><span class=\"news_bold\">PRESIDENTE EXALTA ELENCO E FOCA EM RENOVA\u00c7\u00d5ES<\/span><\/p>\n<p>Leila destacou a preocupa\u00e7\u00e3o com a sa\u00fade financeira do clube. Ela foi questionada sobre poss\u00edveis contrata\u00e7\u00f5es durante a festa de premia\u00e7\u00e3o do Campeonato Paulista.<\/p>\n<p>A dirigente n\u00e3o planeja contrata\u00e7\u00f5es, mas se diz atenta ao mercado e aos pedidos de Abel. Leila Pereira explicou que o Palmeiras trabalha com &#8220;contrata\u00e7\u00f5es pontuais&#8221; e em &#8220;setores espec\u00edficos&#8221;.<\/p>\n<p><span class=\"news_bold\">PROBLEMAS PARA ABEL<\/span><\/p>\n<p>Sem Veiga e Tabata, o treinador pode ser obrigado a improvisar no meio-campo. Com os meia-armadores lesionados, Abel pode adiantar Z\u00e9 Rafael e Gabriel Menino &#8211; colocando Fabinho como volante &#8211; ou improvisar Artur ou Navarro na posi\u00e7\u00e3o.<\/p>\n<p>Artur jogou pelo meio na Libertadores e Tabata j\u00e1 treinou como 10. O ex-Red Bull Bragantino, por\u00e9m, n\u00e3o pode defender o Palmeiras pela Copa do Brasil.<\/p>\n<p>Vanderlan ter\u00e1 maratona na lateral-esquerda. Com a les\u00e3o de Piquerez, a Cria da Academia assumiu o posto, e tem como substituto o jovem Ian.<\/p>\n<p>Perdeu o artilheiro do time. Rony \u00e9 o goleador do Palmeiras na temporada, e os centroavantes Rafael Navarro e Flaco L\u00f3pez ainda n\u00e3o se firmaram.<\/p>\n<p><span class=\"news_bold\">O DM DO PALMEIRAS<\/span><\/p>\n<p>&#8211; Rony (cirurgia ap\u00f3s fratura no antebra\u00e7o)<br \/>&#8211; Raphael Veiga (les\u00e3o na coxa direita)<br \/>&#8211; Piquerez (entorse do joelho direito)<br \/>&#8211; Mayke (entorse tornozelo direito)<br \/>&#8211; Bruno Tabata (les\u00e3o na coxa esquerda, mas iniciou transi\u00e7\u00e3o f\u00edsica)<br \/>&#8211; Atuesta (cirurgia ap\u00f3s rompimento do ligamento cruzado do joelho direito)<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Esporte<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/esporte\/2008848\/leila-diz-que-palmeiras-nao-fara-contratacoes-mesmo-com-onda-de-lesoes?utm_source=rss-esporte&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00c3O PAULO, SP (UOL\/FOLHAPRESS) &#8211; O Palmeiras tem seis jogadores no departamento m\u00e9dico, mas a<\/p>\n","protected":false},"author":0,"featured_media":119271,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-119270","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/119270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=119270"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/119270\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/119271"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=119270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=119270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=119270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}