{"id":119256,"date":"2023-04-12T20:08:12","date_gmt":"2023-04-12T23:08:12","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2023\/04\/12\/entenda-a-mudanca-na-isencao-de-produtos-importados-de-ate-us-50\/"},"modified":"2023-04-12T20:08:12","modified_gmt":"2023-04-12T23:08:12","slug":"entenda-a-mudanca-na-isencao-de-produtos-importados-de-ate-us-50","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2023\/04\/12\/entenda-a-mudanca-na-isencao-de-produtos-importados-de-ate-us-50\/","title":{"rendered":"Entenda a mudan\u00e7a na isen\u00e7\u00e3o de produtos importados de at\u00e9 US$ 50"},"content":{"rendered":"<p>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; O governo Luiz In\u00e1cio Lula da Silva (PT) colocar\u00e1 fim \u00e0 isen\u00e7\u00e3o de imposto de importa\u00e7\u00e3o para encomendas de at\u00e9 US$ 50 (R$ 250) destinadas a pessoas f\u00edsicas. N\u00e3o haver\u00e1 mais distin\u00e7\u00e3o de tratamento nas remessas por pessoas jur\u00eddicas e f\u00edsicas -o que serviria hoje apenas para fraudes generalizadas, segundo o governo. Veja o que deve mudar.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p><span class=\"news_bold\">QUANDO O IMPOSTO COME\u00c7A A SER COBRADO?<\/span><\/p>\n<p>Ainda n\u00e3o h\u00e1 uma data para o in\u00edcio da cobran\u00e7a.<\/p>\n<p><span class=\"news_bold\">QUEM VAI PAGAR?<\/span><\/p>\n<p>A ideia \u00e9 que o tributo seja recolhido antecipadamente pelo vendedor, que poder\u00e1 repassar o custo para o consumidor. Se o imposto n\u00e3o for recolhido antes, caber\u00e1 ao destinat\u00e1rio pag\u00e1-lo em uma ag\u00eancia dos Correios.<\/p>\n<p><span class=\"news_bold\">QUAL A JUSTIFICATIVA PARA A MEDIDA?<\/span><\/p>\n<p>A isen\u00e7\u00e3o vem sendo utilizada para fraudes por empresas de com\u00e9rcio eletr\u00f4nico que colocam indevidamente o nome de pessoas f\u00edsicas como remetentes. O chamado &#8220;contrabando digital&#8221; est\u00e1 na mira da pasta econ\u00f4mica desde o in\u00edcio do ano. Com isso, elas t\u00eam mais uma vantagem na concorr\u00eancia com empresas brasileiras.<\/p>\n<p><span class=\"news_bold\">QUAIS AS EMPRESAS AFETADAS?<\/span><\/p>\n<p>Plataformas de varejo internacionais. Entre elas, varejistas asi\u00e1ticas, como AliExpress, Shein e Shopee, que abocanharam uma parte significativa do mercado brasileiro com produtos mais baratos e s\u00e3o acusadas de concorr\u00eancia desleal por parte das empresas brasileiras.<\/p>\n<p>Considerando apenas as compras em sites que operam a partir do Brasil, o com\u00e9rcio eletr\u00f4nico somou R$ 182,7 bilh\u00f5es no ano passado.<\/p>\n<p><span class=\"news_bold\">O QUE MUDA PARA O CONSUMIDOR E ESSAS PLATAFORMAS?<\/span><\/p>\n<p>A Receita deve prever a obrigatoriedade de declara\u00e7\u00f5es completas e antecipadas da importa\u00e7\u00e3o por parte das plataformas, identificando exportador e importador, com possibilidade de multa em caso de subfaturamento ou dados incompletos ou incorretos.<\/p>\n<p>Com a declara\u00e7\u00e3o antecipada, a mercadoria chegaria ao Brasil j\u00e1 liberada, podendo seguir diretamente para o consumidor.<\/p>\n<p>A fiscaliza\u00e7\u00e3o da Receita ficaria, assim, centralizada nas remessas de maior risco a partir de inconsist\u00eancias identificadas pelos sistemas de gest\u00e3o de riscos, alimentados pelos dados concedidos previamente.<\/p>\n<p><span class=\"news_bold\">QUAL O VALOR DO IMPOSTO DE IMPORTA\u00c7\u00c3O?<\/span><\/p>\n<p>O Brasil adota para as remessas internacionais o Regime de Tributa\u00e7\u00e3o Simplificada, no qual \u00e9 aplicada uma al\u00edquota \u00fanica de 60% sobre o valor aduaneiro da remessa (somat\u00f3rio dos valores do produto, do frete e do seguro).<br \/>Atualmente, h\u00e1 isen\u00e7\u00e3o na encomenda de at\u00e9 US$ 50 (incluindo o valor do produto, frete, embalagem e eventual seguro) para pessoas f\u00edsicas. A ideia \u00e9 que a al\u00edquota do Imposto de Importa\u00e7\u00e3o se aplique a todos os produtos, independentemente do valor.<\/p>\n<p><span class=\"news_h3\">Exemplo ap\u00f3s a mudan\u00e7a:<\/span><\/p>\n<p>O destinat\u00e1rio realiza uma compra em um site de com\u00e9rcio eletr\u00f4nico internacional no valor total de US$ 50,00, sendo o valor do bem de US$ 40,00 e valor do frete de US$ 8,00 e seguro de US$ 2,00.<\/p>\n<p>&#8211; Taxa de c\u00e2mbio do dia do registro: R$ 5,00<br \/>&#8211; Valor aduaneiro: US$ 50,00 (R$ 250,00)<br \/>&#8211; Al\u00edquota do Imposto de Importa\u00e7\u00e3o: 60%<br \/>&#8211; Valor do Imposto de Importa\u00e7\u00e3o devido: R$ 150,00<br \/>&#8211; Custo total: R$ 400,00<\/p>\n<p><span class=\"news_bold\">O QUE DIZ A LEGISLA\u00c7\u00c3O ATUALMENTE?<\/span><\/p>\n<p>Atualmente, a isen\u00e7\u00e3o se aplica para os bens que integrem remessa postal internacional, importados via Correios, desde que o remetente e o destinat\u00e1rio sejam pessoas f\u00edsicas e a remessa n\u00e3o seja fruto de uma transa\u00e7\u00e3o comercial. Essa brecha foi criada nos anos 1980 pensando em encomendas de pessoa f\u00edsica para pessoa f\u00edsica.<\/p>\n<p>Quando ocorre uma opera\u00e7\u00e3o comercial, ainda que o remetente seja uma pessoa f\u00edsica, na verdade estar\u00e1 atuando como se pessoa jur\u00eddica fosse, afastando a aplicabilidade da isen\u00e7\u00e3o, segundo a Receita.<\/p>\n<p>A legisla\u00e7\u00e3o vigente n\u00e3o prev\u00ea imunidade, isen\u00e7\u00e3o ou qualquer outro benef\u00edcio fiscal para bens usados.<\/p>\n<p>Essa isen\u00e7\u00e3o tamb\u00e9m n\u00e3o se aplica a encomendas expressas internacionais transportadas sob responsabilidade de empresas de transporte expresso internacional porta a porta, tamb\u00e9m conhecidas como empresas de courier, segundo a Receita.<\/p>\n<p><span class=\"news_bold\">QUAL A PENALIDADE?<\/span><\/p>\n<p>Segundo a Receita, atos praticados com a finalidade de dissimular as opera\u00e7\u00f5es com encomendas internacionais sujeitam o contribuinte \u00e0s penalidades tribut\u00e1rias e aduaneiras<\/p>\n<p><span class=\"news_bold\">QUANTO O GOVERNO ESPERA ARRECADAR COM A MUDAN\u00c7A?<\/span><\/p>\n<p>O governo estima arrecadar at\u00e9 R$ 8 bilh\u00f5es com a tributa\u00e7\u00e3o.<\/p>\n<p><span class=\"news_bold\">POR QUE O GOVERNO DECIDIU ADOTAR A MEDIDA AGORA?<\/span><\/p>\n<p>Em 2022, a Receita Federal anunciou que estava estudando uma medida provis\u00f3ria para impedir que empresas de com\u00e9rcio eletr\u00f4nico estrangeiras vendam mercadorias para brasileiros sem pagar os devidos impostos. Mas a proposta foi descartada pelo ex-presidente Jair Bolsonaro (PL).<\/p>\n<p>Em mar\u00e7o deste ano, deputados e senadores da FPE (Frente Parlamentar Mista do Empreendedorismo) pediram que o Minist\u00e9rio da Fazenda atue pelo fim do &#8220;contrabando digital&#8221; feito, segundo eles, por empresas chinesas. Os parlamentares afirmam que as companhias asi\u00e1ticas vendem produtos sem taxa\u00e7\u00e3o ou subfaturados no pa\u00eds.<\/p>\n<p>O Brasil recebe hoje 500 mil pacotes di\u00e1rios vindos da China, em que os valores s\u00e3o subfaturados e os pacotes s\u00e3o multiplicados, segundo o deputado Marco Bertaiolli (PSD-SP), presidente da FPE.<\/p>\n<p>Quando um consumidor compra cinco camisetas, por exemplo, a plataforma envia cinco pacotes, um com cada camiseta, para estar abaixo do valor de US$ 50, segundo a FPE. A frente afirma ainda que, quando o pre\u00e7o do produto individual passa de US$ 50, o valor da nota fiscal vem subfaturado.<\/p>\n<p>A taxa\u00e7\u00e3o de plataformas que descumpram as regras da Receita Federal tamb\u00e9m faz parte do pacote de at\u00e9 R$ 150 bilh\u00f5es em medidas propostas pela Fazenda para arrecadar mais e conseguir atingir as metas previstas no arcabou\u00e7o fiscal, entregando a melhora nas contas p\u00fablicas prometida para os pr\u00f3ximos anos.<\/p>\n<p>A primeira dama Janja Lula Silva publicou em redes sociais a mensagem de que conversou com o ministro Fernando Haddad (Fazenda) sobre o tema e que &#8220;se trata de combater sonega\u00e7\u00e3o das empresas e n\u00e3o taxar as pessoas que compram&#8221;.<\/p>\n<p>O vice-presidente da Unafisco (associa\u00e7\u00e3o dos auditores da Receita), Kleber Cabral, estima que o volume de remessa caia significativamente com o Regime de Tributa\u00e7\u00e3o Simplificada em 60%.<\/p>\n<p>Ele afirma que diversos sites, principalmente chineses, mas n\u00e3o apenas esses, praticam fraudes, por exemplo, colocando pessoas f\u00edsicas como remetentes de produtos. &#8220;A Receita Federal n\u00e3o consegue separar um caso do outro adequadamente, aplica uma amostragem, com perda de arrecada\u00e7\u00e3o e preju\u00edzo ao com\u00e9rcio varejista nacional, que sofre concorr\u00eancia desleal dessas e-commerce.&#8221;<\/p>\n<p><span class=\"news_bold\">EXISTEM BENS QUE N\u00c3O S\u00c3O TRIBUTADOS NA IMPORTA\u00c7\u00c3O DE REMESSAS INTERNACIONAIS E TALVEZ CONTINUEM ASSIM?<\/span><\/p>\n<p>\u00c9 uma possibilidade.<\/p>\n<p>Medicamentos importados por pessoa f\u00edsica para uso humano, at\u00e9 o limite de US$ 10.000,00, por exemplo, n\u00e3o s\u00e3o tributados. O benef\u00edcio n\u00e3o inclui medicamentos de uso veterin\u00e1rio, suplementos e cosm\u00e9ticos. A Receita pode exigir receita m\u00e9dica para comprova\u00e7\u00e3o de uso pr\u00f3prio ou individual do medicamento.<\/p>\n<p>A Receita tamb\u00e9m permite que pessoas jur\u00eddicas possam usufruir da isen\u00e7\u00e3o quando realizarem a importa\u00e7\u00e3o de amostras sem valor comercial por meio de encomenda internacional.<\/p>\n<p>\u00c9 concedida tamb\u00e9m imunidade do imposto \u00e0s importa\u00e7\u00f5es de livros, jornais e peri\u00f3dicos.<\/p>\n<p><a href=\"https:\/\/www.noticiasaominuto.com.br\/economia\/2008937\/entenda-a-mudanca-na-isencao-de-produtos-importados-de-ate-us-50?utm_source=rss-economia&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><br \/>\nNot\u00edcias ao Minuto Brasil &#8211; Economia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; O governo Luiz In\u00e1cio Lula da Silva (PT) colocar\u00e1 fim<\/p>\n","protected":false},"author":0,"featured_media":119257,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-119256","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/119256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=119256"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/119256\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/119257"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=119256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=119256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=119256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}